{"id":104677,"date":"2021-02-08T08:30:16","date_gmt":"2021-02-08T07:30:16","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=104677"},"modified":"2021-02-08T08:26:23","modified_gmt":"2021-02-08T07:26:23","slug":"8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/","title":{"rendered":"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/hockey-sur-glace\/\">HOCKEY SUR GLACE<\/a> &#8211; En 1998, pour la premi\u00e8re fois, la LNH autorise les stars de la ligue \u00e0 participer aux Jeux, un break olympique nouveau pour les hockeyeurs masculins. Tant mieux pour eux, ce n\u2019est pas ce dont nous allons parler. Car si les hommes sont pr\u00e9sents aux JO d\u2019hiver depuis 1920, les femmes arrivent tout juste en 1998.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">\u00c7a s&rsquo;est pass\u00e9 le 8 f\u00e9vrier 1998<\/h2>\n<p style=\"text-align: justify;\">Vaut mieux tard que jamais \u2026 Enfin ! Pr\u00e8s de 80 ans apr\u00e8s leurs homologues masculins, les joueuses de hockey int\u00e8grent les Jeux Olympiques. Pour cette premi\u00e8re \u00e9dition chez les dames, six \u00e9quipes sont au programme : les USA, le Canada, la Chine, la Su\u00e8de, la Finlande et le Japon. Chacune d\u2019entre elles rencontre l\u2019ensemble des autres \u00e9quipes une fois pour \u00e9tablir un classement. Les deux premi\u00e8res nations \u00e0 la fin de ce tour se retrouvent en finale tandis que les troisi\u00e8me et quatri\u00e8me se disputent la m\u00e9daille de bronze. Apr\u00e8s un carton plein de cinq victoires sur cinq, les Etats-Unis retrouvent les Canadiennes en finale. Ces derni\u00e8res, grandes gagnantes de tous les mondiaux de hockey f\u00e9minins partent donc favorites. Mais dans le sport, tout est possible.<\/p>\n<p style=\"text-align: justify;\">Surtout qu\u2019\u00e0 Nagano, lors de la phase pr\u00e9liminaire, les Am\u00e9ricaines se sont d\u00e9j\u00e0 impos\u00e9es contre le Canada. Men\u00e9es pourtant 4-1, elles avaient renvers\u00e9 la rencontre pour la gagner 7-4. Quelques jours plus tard, Karyn Bye et ses co\u00e9quipi\u00e8res remettent \u00e7a et d\u00e9crochent l\u2019or olympique sur le score de 3-1. Les Finlandaises vont, elles, chercher le bronze en s\u2019imposant face \u00e0 la Chine.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Info\u00a0: les Canadiennes ont pris leur revanche sur les Am\u00e9ricaines en finale lors des Jeux Olympiques suivants avant de remporter \u00e9galement les \u00e9ditions 2006, 2010 et 2014. A Pyeongchang, les Etats-Unis ont fini par r\u00e9cup\u00e9rer le titre \u2026 contre le Canada.<\/p>\n<p><em><strong>Sophie Clapier<\/strong><br \/>\n<\/em><a href=\"https:\/\/twitter.com\/soocube\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.facebook.com\/soocube\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retour sur la date du 8 f\u00e9vrier 1998, quand le hockey f\u00e9minin connaissait son tout premier match dans des Jeux Olympiques.<\/p>\n","protected":false},"author":18,"featured_media":104764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8,10575],"tags":[838,1398],"class_list":["post-104677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-hockey-sur-glace","tag-hockey-sur-glace","tag-sport-feminin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques<\/title>\n<meta name=\"description\" content=\"Retour sur la date du 8 f\u00e9vrier 1998, quand le hockey f\u00e9minin connaissait son tout premier match dans des Jeux Olympiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques\" \/>\n<meta property=\"og:description\" content=\"Retour sur la date du 8 f\u00e9vrier 1998, quand le hockey f\u00e9minin connaissait son tout premier match dans des Jeux Olympiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-08T07:30:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques\",\"datePublished\":\"2021-02-08T07:30:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png\",\"keywords\":[\"hockey sur glace\",\"sport f\u00e9minin\"],\"articleSection\":[\"Histoire\",\"Hockey sur glace\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/\",\"name\":\"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png\",\"datePublished\":\"2021-02-08T07:30:16+00:00\",\"description\":\"Retour sur la date du 8 f\u00e9vrier 1998, quand le hockey f\u00e9minin connaissait son tout premier match dans des Jeux Olympiques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png\",\"width\":800,\"height\":445,\"caption\":\"8 f\u00e9vrier 1998 - Premier match de hockey f\u00e9minin aux Jeux Olympiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques","description":"Retour sur la date du 8 f\u00e9vrier 1998, quand le hockey f\u00e9minin connaissait son tout premier match dans des Jeux Olympiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/","og_locale":"fr_FR","og_type":"article","og_title":"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques","og_description":"Retour sur la date du 8 f\u00e9vrier 1998, quand le hockey f\u00e9minin connaissait son tout premier match dans des Jeux Olympiques.","og_url":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-02-08T07:30:16+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques","datePublished":"2021-02-08T07:30:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png","keywords":["hockey sur glace","sport f\u00e9minin"],"articleSection":["Histoire","Hockey sur glace"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/","url":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/","name":"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png","datePublished":"2021-02-08T07:30:16+00:00","description":"Retour sur la date du 8 f\u00e9vrier 1998, quand le hockey f\u00e9minin connaissait son tout premier match dans des Jeux Olympiques.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/8-fevrier-1998-Premier-match-de-hockey-feminin-aux-Jeux-Olympiques.png","width":800,"height":445,"caption":"8 f\u00e9vrier 1998 - Premier match de hockey f\u00e9minin aux Jeux Olympiques"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/8-fevrier-1998-premier-match-de-hockey-feminin-aux-jeux-olympiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"8 f\u00e9vrier 1998 : premier match de hockey f\u00e9minin aux Jeux Olympiques"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/104677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=104677"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/104677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/104764"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=104677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=104677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=104677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}