{"id":105678,"date":"2021-02-12T10:38:53","date_gmt":"2021-02-12T09:38:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=105678&#038;preview=true&#038;preview_id=105678"},"modified":"2021-02-17T08:21:34","modified_gmt":"2021-02-17T07:21:34","slug":"open-daustralie-2021-les-tableaux-tennis-fauteuil","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/","title":{"rendered":"Open d&rsquo;Australie 2021 : les tableaux tennis fauteuil"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/tennis\/open-australie-2021\/\" target=\"_blank\" rel=\"noopener noreferrer\">OPEN D\u2019AUSTRALIE 2021<\/a> \u2013 Le tirage au sort des tableaux de tennis fauteuil a eu lieu.\u00a0<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Simple dames<\/h2>\n<p style=\"text-align: justify;\"><strong>Yui Kamiji<\/strong>, vainqueur en 2017 et 2020 n&rsquo;a pas r\u00e9ussi la passe de 3. La num\u00e9ro 1 mondiale <strong>Diede de Groot<\/strong> s&rsquo;est impos\u00e9e 6-3 6-7[4] 7-6[4] en finale.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 20px;\"><a href=\"https:\/\/ausopen.com\/draws#!womens-wheelchair-singles\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Le tableau complet<\/strong><\/a><\/span><\/p>\n<h2>Double dames<\/h2>\n<p style=\"text-align: justify;\">Les num\u00e9ros 1 mondiales <strong>Diede de Groot et Aniek van Koot<\/strong> se sont impos\u00e9es en finale face aux num\u00e9ros 2 Montjane\/Shuker (6-4 6-1).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/ausopen.com\/draws#!womens-wheelchair-doubles\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 20px;\"><strong>Le tableau complet<\/strong><\/span><\/a><\/p>\n<h2>Simple messieurs<\/h2>\n<p style=\"text-align: justify;\"><b>Alfie Hewett\u00a0<\/b>a r\u00e9alis\u00e9 l&rsquo;exploit en \u00e9liminant le num\u00e9ro 1 mondial Shingo Kunieda. Mais c&rsquo;est <strong>Joachim G\u00e9rard<\/strong> qui a remport\u00e9 son premier titre du Grand Chelem en simple. Il s&rsquo;est impos\u00e9 en finale face au Britannique 6-0 4-6 6-4<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/ausopen.com\/draws#!mens-wheelchair-singles\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"font-size: 20px;\">Le tableau complet<\/span><\/strong><\/a><\/p>\n<h2>Double messieurs<\/h2>\n<p style=\"text-align: justify;\"><strong>Alfie Hewett et Gordon Reid<\/strong> se sont impos\u00e9s en finale face aux Fran\u00e7ais St\u00e9phane Houdet et Nicolas Peifer (7-5 7-6[3]).<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 20px;\"><strong><a href=\"https:\/\/ausopen.com\/draws#!mens-wheelchair-doubles\" target=\"_blank\" rel=\"noopener\">Le tableau complet<\/a><\/strong><\/span><\/p>\n<h2><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/ausopen.com\/draws#!quad-wheelchair-singles\" target=\"_blank\" rel=\"noopener\">Quad simple<\/a><\/span><\/h2>\n<h2><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/ausopen.com\/draws#!quad-wheelchair-doubles\" target=\"_blank\" rel=\"noopener\">Quad double<\/a><\/span><\/h2>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OPEN D\u2019AUSTRALIE 2021 \u2013 Le tirage au sort du double femmes a eu lieu. Qui succ\u00e9dera \u00e0 Barbora Krejcikova et Nikola Mektic ?<\/p>\n","protected":false},"author":12,"featured_media":105703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47089],"tags":[3226,1600],"class_list":["post-105678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-open-d-australie","tag-open-daustralie","tag-tennis-fauteuil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Open d&#039;Australie 2021 : les tableaux tennis fauteuil<\/title>\n<meta name=\"description\" content=\"OPEN D\u2019AUSTRALIE 2021 \u2013 Le tirage au sort du double femmes a eu lieu. Qui succ\u00e9dera \u00e0 Barbora Krejcikova et Nikola Mektic ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open d&#039;Australie 2021 : les tableaux tennis fauteuil\" \/>\n<meta property=\"og:description\" content=\"OPEN D\u2019AUSTRALIE 2021 \u2013 Le tirage au sort du double femmes a eu lieu. Qui succ\u00e9dera \u00e0 Barbora Krejcikova et Nikola Mektic ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-12T09:38:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-17T07:21:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Open d&#039;Australie 2021 : les tableaux tennis fauteuil\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Open d&rsquo;Australie 2021 : les tableaux tennis fauteuil\",\"datePublished\":\"2021-02-12T09:38:53+00:00\",\"dateModified\":\"2021-02-17T07:21:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/\"},\"wordCount\":168,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg\",\"keywords\":[\"Open d'Australie\",\"tennis fauteuil\"],\"articleSection\":[\"Open d'Australie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/\",\"name\":\"Open d'Australie 2021 : les tableaux tennis fauteuil\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg\",\"datePublished\":\"2021-02-12T09:38:53+00:00\",\"dateModified\":\"2021-02-17T07:21:34+00:00\",\"description\":\"OPEN D\u2019AUSTRALIE 2021 \u2013 Le tirage au sort du double femmes a eu lieu. Qui succ\u00e9dera \u00e0 Barbora Krejcikova et Nikola Mektic ?\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Open d&rsquo;Australie 2021 : les tableaux tennis fauteuil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Open d'Australie 2021 : les tableaux tennis fauteuil","description":"OPEN D\u2019AUSTRALIE 2021 \u2013 Le tirage au sort du double femmes a eu lieu. Qui succ\u00e9dera \u00e0 Barbora Krejcikova et Nikola Mektic ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/","og_locale":"fr_FR","og_type":"article","og_title":"Open d'Australie 2021 : les tableaux tennis fauteuil","og_description":"OPEN D\u2019AUSTRALIE 2021 \u2013 Le tirage au sort du double femmes a eu lieu. Qui succ\u00e9dera \u00e0 Barbora Krejcikova et Nikola Mektic ?","og_url":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-02-12T09:38:53+00:00","article_modified_time":"2021-02-17T07:21:34+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg","type":"image\/jpeg"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Open d'Australie 2021 : les tableaux tennis fauteuil","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Open d&rsquo;Australie 2021 : les tableaux tennis fauteuil","datePublished":"2021-02-12T09:38:53+00:00","dateModified":"2021-02-17T07:21:34+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/"},"wordCount":168,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg","keywords":["Open d'Australie","tennis fauteuil"],"articleSection":["Open d'Australie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/","url":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/","name":"Open d'Australie 2021 : les tableaux tennis fauteuil","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg","datePublished":"2021-02-12T09:38:53+00:00","dateModified":"2021-02-17T07:21:34+00:00","description":"OPEN D\u2019AUSTRALIE 2021 \u2013 Le tirage au sort du double femmes a eu lieu. Qui succ\u00e9dera \u00e0 Barbora Krejcikova et Nikola Mektic ?","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Open-dAustralie-2021-tableaux-tennis-fauteuil.jpeg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/open-daustralie-2021-les-tableaux-tennis-fauteuil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Open d&rsquo;Australie 2021 : les tableaux tennis fauteuil"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/105678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=105678"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/105678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/105703"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=105678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=105678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=105678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}