{"id":115972,"date":"2021-03-24T08:00:45","date_gmt":"2021-03-24T07:00:45","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=115972"},"modified":"2021-03-24T07:33:18","modified_gmt":"2021-03-24T06:33:18","slug":"24-mars-2020-les-jeux-de-tokyo-sont-reportes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/","title":{"rendered":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>C\u2019\u00e9tait THE EVENT de l\u2019ann\u00e9e 2020, le rassemblement sportif que tous les amateurs de sport attendaient, les Jeux Olympiques d\u2019\u00e9t\u00e9. Malheureusement l\u2019annonce est tomb\u00e9e\u2026<\/strong> <\/em><\/p>\n<p style=\"text-align: justify;\">Avant que la pand\u00e9mie de Covid-19 apparaisse, les JO \u00e9taient pr\u00e9vus du 24 juillet au 9 ao\u00fbt, suivis de pr\u00e8s par les Jeux Paralympiques du 25 ao\u00fbt au 6 septembre. Mais l\u2019\u00e9volution et la propagation du virus ont tout chang\u00e9. Certaines comp\u00e9titions sont d\u00e9j\u00e0 en arr\u00eat, report\u00e9es ou encore annul\u00e9es. En ce 24 mars 2020, le Premier Ministre japonais demande au CIO le report de la comp\u00e9tition \u00e0 2021. Le comit\u00e9 d\u2019organisation accepte et rend l\u2019annonce officielle. Cela le m\u00eame jour que le d\u00e9c\u00e8s d\u2019Albert Uderzo. Comment \u00e7a vous ne voyez pas le rapport ?<\/p>\n<div id=\"attachment_115975\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-115975\" class=\"wp-image-115975 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Report-JO.jpg\" alt=\"\" width=\"500\" height=\"642\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Report-JO.jpg 500w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Report-JO-234x300.jpg 234w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><p id=\"caption-attachment-115975\" class=\"wp-caption-text\">\u00a9Bedetheque<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Info\u00a0:<\/strong> Rendez-vous donc -on croise les doigts- entre le 23 juillet et 8 ao\u00fbt 2021 pour les Jeux Olympiques, et ensuite du 24 ao\u00fbt au 5 septembre pour les athl\u00e8tes handisports.<\/p>\n<p><em><strong>Sophie Clapier<\/strong><br \/>\n<\/em><a href=\"https:\/\/twitter.com\/soocube\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.facebook.com\/soocube\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 24 mars 2020 l&rsquo;annonce tombe, les Jeux Olympiques et Paralympiques d&rsquo;\u00e9t\u00e9 de Tokyo sont report\u00e9s d&rsquo;un an. Retour sur cette journ\u00e9e.<\/p>\n","protected":false},"author":18,"featured_media":96722,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8,14180,8433],"tags":[161,1964],"class_list":["post-115972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-jeux-paralympiques-tokyo-2020","category-jo-tokyo-2020","tag-jeux-olympiques","tag-jeux-paralympiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s<\/title>\n<meta name=\"description\" content=\"Le 24 mars 2020 l&#039;annonce tombe, les Jeux Olympiques et Paralympiques d&#039;\u00e9t\u00e9 de Tokyo sont report\u00e9s d&#039;un an. Retour sur cette journ\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Le 24 mars 2020 l&#039;annonce tombe, les Jeux Olympiques et Paralympiques d&#039;\u00e9t\u00e9 de Tokyo sont report\u00e9s d&#039;un an. Retour sur cette journ\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-24T07:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s\",\"datePublished\":\"2021-03-24T07:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/\"},\"wordCount\":180,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png\",\"keywords\":[\"Jeux Olympiques\",\"jeux paralympiques\"],\"articleSection\":[\"Histoire\",\"Jeux Paralympiques de Tokyo 2020\",\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/\",\"name\":\"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png\",\"datePublished\":\"2021-03-24T07:00:45+00:00\",\"description\":\"Le 24 mars 2020 l'annonce tombe, les Jeux Olympiques et Paralympiques d'\u00e9t\u00e9 de Tokyo sont report\u00e9s d'un an. Retour sur cette journ\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png\",\"width\":800,\"height\":445,\"caption\":\"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s","description":"Le 24 mars 2020 l'annonce tombe, les Jeux Olympiques et Paralympiques d'\u00e9t\u00e9 de Tokyo sont report\u00e9s d'un an. Retour sur cette journ\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/","og_locale":"fr_FR","og_type":"article","og_title":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s","og_description":"Le 24 mars 2020 l'annonce tombe, les Jeux Olympiques et Paralympiques d'\u00e9t\u00e9 de Tokyo sont report\u00e9s d'un an. Retour sur cette journ\u00e9e.","og_url":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-03-24T07:00:45+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s","datePublished":"2021-03-24T07:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/"},"wordCount":180,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png","keywords":["Jeux Olympiques","jeux paralympiques"],"articleSection":["Histoire","Jeux Paralympiques de Tokyo 2020","JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/","url":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/","name":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png","datePublished":"2021-03-24T07:00:45+00:00","description":"Le 24 mars 2020 l'annonce tombe, les Jeux Olympiques et Paralympiques d'\u00e9t\u00e9 de Tokyo sont report\u00e9s d'un an. Retour sur cette journ\u00e9e.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Les-Jeux-Olympiques-et-Paralympiques-de-Tokyo-toujours-aussi-incertains.png","width":800,"height":445,"caption":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/24-mars-2020-les-jeux-de-tokyo-sont-reportes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"24 mars 2020 : Les Jeux de Tokyo sont report\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/115972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=115972"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/115972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/96722"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=115972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=115972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=115972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}