{"id":116167,"date":"2021-03-24T16:58:35","date_gmt":"2021-03-24T15:58:35","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=116167&#038;preview=true&#038;preview_id=116167"},"modified":"2021-03-24T17:32:26","modified_gmt":"2021-03-24T16:32:26","slug":"tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/","title":{"rendered":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/\" target=\"_blank\" rel=\"noopener\">CYCLISME<\/a> &#8211; Vainqueur de la 3\u00e8me \u00e9tape du Tour de Catalogne \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s&#8217;emparant \u00e9galement du maillot de leader. Il devance Esteban Chaves (Bike-Exchange) et Alejandro Valverde (Movistar).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Adam Yates<\/strong> comme chez lui \u00e0 Vallter 2000. D\u00e9j\u00e0 victorieux dans la station g\u00e9ronaise il y a deux ans, le Britannique s&rsquo;y est de nouveau impos\u00e9 ce mercredi, \u00e0 l&rsquo;occasion de la 3\u00e8me du Tour de Catalogne 2021. Deuxi\u00e8me du classement g\u00e9n\u00e9ral de l&rsquo;UAE Tour en f\u00e9vrier, le coureur de la formation INEOS Grenadiers a fait la diff\u00e9rence \u00e0 un peu plus d&rsquo;un km du sommet, en d\u00e9posant <strong>Sepp Kuss<\/strong> (Jumbo-Visma). Un temps accompagn\u00e9 d&rsquo;<strong>Alejandro Valverde<\/strong> (Movistar), le duo n\u00e9erlando-britannique a fait la diff\u00e9rence \u00e0 5 km de l&rsquo;arriv\u00e9e, en revenant notamment sur le v\u00e9t\u00e9ran espagnol.<\/p>\n<p style=\"text-align: justify;\">Sur la ligne d&rsquo;arriv\u00e9e, Yates devance finalement un <strong>Esteban Chaves<\/strong> (Bike-Exchange) revenu comme une balle dans le dernier kilom\u00e8tre. Valverde termine 3\u00e8me. Au g\u00e9n\u00e9ral, Adam Yates devance d\u00e9sormais son co\u00e9quipier <strong>Richie Porte<\/strong> de 45 secondes.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Adam Yates fait coup double : le Britannique remporte la 3e \u00e9tape et prend la t\u00eate du classement g\u00e9n\u00e9ral du Tour de Catalogne !<\/p>\n<p>Suivez la <a href=\"https:\/\/twitter.com\/hashtag\/VoltaCatalunya100?src=hash&amp;ref_src=twsrc%5Etfw\">#VoltaCatalunya100<\/a> toute la semaine sur Eurosport et <a href=\"https:\/\/t.co\/7qbNJch1A0\">https:\/\/t.co\/7qbNJch1A0<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LesRP?src=hash&amp;ref_src=twsrc%5Etfw\">#LesRP<\/a> <a href=\"https:\/\/t.co\/ipBAYkYnYJ\">pic.twitter.com\/ipBAYkYnYJ<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/1374753641240887302?ref_src=twsrc%5Etfw\">March 24, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2021-classement-3eme-etape\/\" target=\"_blank\" rel=\"noopener\"><strong>Le classement de la 3\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-2021-classement-general\/\" target=\"_blank\" rel=\"noopener\"><strong>Le classement g\u00e9n\u00e9ral<\/strong><\/a><\/li>\n<\/ul>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; Vainqueur de la 3\u00e8me \u00e9tape \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s&#8217;emparant \u00e9galement du maillot de leader. Il devance Esteban Chaves (Bike-Exchange) et Alejandro Valverde (Movistar).<\/p>\n","protected":false},"author":4,"featured_media":116190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2307],"tags":[7488],"class_list":["post-116167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","tag-tour-de-catalogne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"CYCLISME - Vainqueur de la 3\u00e8me \u00e9tape du Tour de Catalogne \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s&#039;emparant \u00e9galement du maillot de leader.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - Vainqueur de la 3\u00e8me \u00e9tape du Tour de Catalogne \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s&#039;emparant \u00e9galement du maillot de leader.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-24T15:58:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-24T16:32:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape\",\"datePublished\":\"2021-03-24T15:58:35+00:00\",\"dateModified\":\"2021-03-24T16:32:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/\"},\"wordCount\":263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png\",\"keywords\":[\"Tour de Catalogne\"],\"articleSection\":[\"Cyclisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/\",\"name\":\"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png\",\"datePublished\":\"2021-03-24T15:58:35+00:00\",\"dateModified\":\"2021-03-24T16:32:26+00:00\",\"description\":\"CYCLISME - Vainqueur de la 3\u00e8me \u00e9tape du Tour de Catalogne \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s'emparant \u00e9galement du maillot de leader.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png\",\"width\":800,\"height\":445,\"caption\":\"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape","description":"CYCLISME - Vainqueur de la 3\u00e8me \u00e9tape du Tour de Catalogne \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s'emparant \u00e9galement du maillot de leader.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape","og_description":"CYCLISME - Vainqueur de la 3\u00e8me \u00e9tape du Tour de Catalogne \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s'emparant \u00e9galement du maillot de leader.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-03-24T15:58:35+00:00","article_modified_time":"2021-03-24T16:32:26+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape","datePublished":"2021-03-24T15:58:35+00:00","dateModified":"2021-03-24T16:32:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/"},"wordCount":263,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png","keywords":["Tour de Catalogne"],"articleSection":["Cyclisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/","name":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png","datePublished":"2021-03-24T15:58:35+00:00","dateModified":"2021-03-24T16:32:26+00:00","description":"CYCLISME - Vainqueur de la 3\u00e8me \u00e9tape du Tour de Catalogne \u00e0 Vallter 2000, Adam Yates (INEOS Grenadiers) a fait coup double ce mercredi, en s'emparant \u00e9galement du maillot de leader.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Tour-de-Catalogne-Adam-Yates-fait-coup-double-sur-la-3eme-etape.png","width":800,"height":445,"caption":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-catalogne-adam-yates-fait-coup-double-sur-la-3eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de Catalogne : Adam Yates fait coup double sur la 3\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/116167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=116167"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/116167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/116190"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=116167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=116167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=116167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}