{"id":117047,"date":"2021-03-27T20:20:55","date_gmt":"2021-03-27T19:20:55","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=117047&#038;preview=true&#038;preview_id=117047"},"modified":"2021-03-27T21:19:04","modified_gmt":"2021-03-27T20:19:04","slug":"super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/","title":{"rendered":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/definition-sport\/rugby-a-xiii\/\" target=\"_blank\" rel=\"noopener\">RUGBY \u00c0 XIII<\/a> &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/motogp-grand-prix-du-qatar-2021-horaires-et-programme-tv-complet\/\" target=\"_blank\" rel=\"noopener\">SUPER LEAGUE<\/a> &#8211; Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28), sur un drop victorieux de James Maloney.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Auteurs d&rsquo;un d\u00e9but de match tonitruant, les <strong>Dragons Catalans<\/strong> inscrivaient deux essais lors du premier quart d&rsquo;heure. <strong>Fouad Yaha<\/strong> ouvrait le compteur des Dracs (5&prime;) avant que <strong>Matt Whitley<\/strong> n&rsquo;alourdisse la marque (15&prime;), sur un caviar de <strong>Mathieu Laguerre<\/strong> (12-0). Les Anglais r\u00e9agissaient 10 minutes plus tard par l&rsquo;interm\u00e9diaire de <strong>Ryan Hall<\/strong>, qui allait \u00e0 dame apr\u00e8s une erreur de <strong>Dean Whare<\/strong> (12-4). Juste avant la pause, <strong>Mathieu Laguerre<\/strong> claquait son premier essai en Super League. \u00c0 la pause, les Dragons menaient logiquement (18-4).<\/p>\n<p style=\"text-align: justify;\">Au retour des vestiaires, les Catalans repartaient sur les m\u00eames bases que lors du premier acte. Sur une offrande au pied de Josh Drinkwater, le capitaine Benjamin Garcia aplatissait le 4\u00e8me essai des siens (44&prime;, 24-4), avant que Fouad Yaha n&rsquo;y aille de son doubl\u00e9 (50&prime;, 28-4). On se dit alors que les Dragons sont \u00e0 l&rsquo;abri.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">A try for the new captain &#x1f409;<a href=\"https:\/\/twitter.com\/DragonsOfficiel?ref_src=twsrc%5Etfw\">@DragonsOfficiel<\/a> in control live on <a href=\"https:\/\/twitter.com\/SkySportsRL?ref_src=twsrc%5Etfw\">@SkySportsRL<\/a> &#x1f604;<a href=\"https:\/\/twitter.com\/hashtag\/SuperLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#SuperLeague<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/SLCatHKR?src=hash&amp;ref_src=twsrc%5Etfw\">#SLCatHKR<\/a> <a href=\"https:\/\/t.co\/Hpunz1RlMF\">pic.twitter.com\/Hpunz1RlMF<\/a><\/p>\n<p>\u2014 Betfred Super League (@SuperLeague) <a href=\"https:\/\/twitter.com\/SuperLeague\/status\/1375877178806702085?ref_src=twsrc%5Etfw\">March 27, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le r\u00e9veil de Hull KR<\/h2>\n<p style=\"text-align: justify;\">Oui mais voil\u00e0, c&rsquo;est \u00e0 ce moment pr\u00e9cis que les Rovers se r\u00e9veillaient. Domin\u00e9s et impuissants, le Dracs encaissaient deux essais en deux minutes avant l&rsquo;heure de jeu, par <strong>Mikey Lewis<\/strong> (54&prime;) et <strong>Ryan Hall<\/strong> pour le doubl\u00e9 (56&prime;, 28-16). R\u00e9duite \u00e0 12 suite au carton jaune inflig\u00e9 \u00e0 <strong>Julian Bousquet<\/strong>, la franchise fran\u00e7aise voyait Hull KR inscrire un quatri\u00e8me essai, avec un tripl\u00e9 de l&rsquo;in\u00e9vitable <strong>Ryan Hall<\/strong> (71&prime;, 28-22). Pire, <strong>George King<\/strong> marquait le 5\u00e8me essai des Rovers, transform\u00e9 par <strong>Jordan Abdull<\/strong> et synonyme d&rsquo;\u00e9galisation (77&prime;, 28-28). Les deux \u00e9quipes allaient au Golden Point. Et c&rsquo;est sur un drop de James Maloney, apr\u00e8s un exploit d&rsquo;Arthur Mourgue, que les Catalans l&#8217;emportaient (29-28). OUF !<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Mourgue makes the play, Maloney with the winner &#x1f92f;<\/p>\n<p>This is why we love <a href=\"https:\/\/twitter.com\/hashtag\/SuperLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#SuperLeague<\/a> &#x1f60d;<a href=\"https:\/\/twitter.com\/hashtag\/SLCatHKR?src=hash&amp;ref_src=twsrc%5Etfw\">#SLCatHKR<\/a> <a href=\"https:\/\/t.co\/0uuSXaVySw\">pic.twitter.com\/0uuSXaVySw<\/a><\/p>\n<p>\u2014 Betfred Super League (@SuperLeague) <a href=\"https:\/\/twitter.com\/SuperLeague\/status\/1375889930757537796?ref_src=twsrc%5Etfw\">March 27, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY \u00c0 XIII &#8211; SUPER LEAGUE &#8211; Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28), sur un drop victorieux de James Maloney.<\/p>\n","protected":false},"author":4,"featured_media":117052,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9128],"tags":[2049,3795],"class_list":["post-117047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xiii","tag-dragons-catalans","tag-super-league"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR<\/title>\n<meta name=\"description\" content=\"RUGBY \u00c0 XIII - SUPER LEAGUE - Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR\" \/>\n<meta property=\"og:description\" content=\"RUGBY \u00c0 XIII - SUPER LEAGUE - Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-27T19:20:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-27T20:19:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR\",\"datePublished\":\"2021-03-27T19:20:55+00:00\",\"dateModified\":\"2021-03-27T20:19:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/\"},\"wordCount\":371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png\",\"keywords\":[\"Dragons Catalans\",\"Super League\"],\"articleSection\":[\"Rugby \u00e0 XIII\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/\",\"name\":\"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png\",\"datePublished\":\"2021-03-27T19:20:55+00:00\",\"dateModified\":\"2021-03-27T20:19:04+00:00\",\"description\":\"RUGBY \u00c0 XIII - SUPER LEAGUE - Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png\",\"width\":800,\"height\":445,\"caption\":\"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR","description":"RUGBY \u00c0 XIII - SUPER LEAGUE - Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/","og_locale":"fr_FR","og_type":"article","og_title":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR","og_description":"RUGBY \u00c0 XIII - SUPER LEAGUE - Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28).","og_url":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-03-27T19:20:55+00:00","article_modified_time":"2021-03-27T20:19:04+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR","datePublished":"2021-03-27T19:20:55+00:00","dateModified":"2021-03-27T20:19:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/"},"wordCount":371,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png","keywords":["Dragons Catalans","Super League"],"articleSection":["Rugby \u00e0 XIII"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/","url":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/","name":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png","datePublished":"2021-03-27T19:20:55+00:00","dateModified":"2021-03-27T20:19:04+00:00","description":"RUGBY \u00c0 XIII - SUPER LEAGUE - Oppos\u00e9s \u00e0 Hull KR, les Dragons Catalans ont arrach\u00e9 la victoire au Golden Point (29-28).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Super-League-Les-Dragons-Catalans-debutent-par-une-victoire-face-a-Hull-KR.png","width":800,"height":445,"caption":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-debutent-par-une-victoire-face-a-hull-kr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Super League : les Dragons Catalans d\u00e9butent par une victoire face \u00e0 Hull KR"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/117047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=117047"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/117047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/117052"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=117047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=117047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=117047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}