{"id":119700,"date":"2021-04-09T17:19:30","date_gmt":"2021-04-09T15:19:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=119700&#038;preview=true&#038;preview_id=119700"},"modified":"2021-04-09T17:30:52","modified_gmt":"2021-04-09T15:30:52","slug":"tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/","title":{"rendered":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/\" target=\"_blank\" rel=\"noopener\">CYCLISME<\/a> &#8211; Au terme d&rsquo;une grande \u00e9chapp\u00e9e, la Deceuninck &#8211; Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque : Mikkel Honor\u00e9 a devanc\u00e9 Josef Cerny, main dans la main ! Brandon McNulty (UAE Team Emirates) conserve la t\u00eate du classement g\u00e9n\u00e9ral.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">La <strong>Deceuninck &#8211; Quick-Step<\/strong> en d\u00e9monstration. Ce vendredi, entre <span class=\"red\">Hondarribia et <\/span><span class=\"red\">Ondarroa, th\u00e9\u00e2tre de la 5\u00e8me \u00e9tape du Tour du Pays Basque 2021, l&rsquo;\u00e9chapp\u00e9e aura \u00e9t\u00e9 au bout, avec deux membres du Wolfpack pour conclure. Vainqueur de la 5\u00e8me \u00e9tape de la Semaine Coppi et Bartali, le Danois <strong>Mikkel Honor\u00e9<\/strong> s&rsquo;est impos\u00e9, en devan\u00e7ant donc son co\u00e9quipier tch\u00e8que, <strong>Josef Cerny<\/strong>. Les deux comp\u00e8res de la formation manag\u00e9e par <strong>Patrick Lefevere<\/strong> ont r\u00e9sist\u00e9 \u00e0 l&rsquo;avant de la course, en l\u00e2chant notamment leur dernier compagnon de route, le Fran\u00e7ais <strong>Julien Bernard<\/strong> (Trek-Segafredo), \u00e0 5 km de l&rsquo;arriv\u00e9e, dans le dernier coup de cul du jour.<\/span><\/p>\n<p style=\"text-align: justify;\">Derri\u00e8re, c&rsquo;est statuquo chez les leaders du g\u00e9n\u00e9ral. <strong>Brandon McNulty<\/strong> (UAE Team Emirates) reste en t\u00eate du g\u00e9n\u00e9ral, devant <strong>Primoz Roglic<\/strong>, \u00e0 la veille de l&rsquo;\u00e9tape finale (et reine) vers Arrate.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">\u00a1Qu\u00e9 exhibici\u00f3n de <a href=\"https:\/\/twitter.com\/deceuninck_qst?ref_src=twsrc%5Etfw\">@deceuninck_qst<\/a>! &#x1f44f;&#x1f44f;<\/p>\n<p>Joseph Cerny y Mikkel Honor\u00e9 entran juntos a meta completamente solos, escapados durante toda la carrera &#x1f633;<a href=\"https:\/\/twitter.com\/hashtag\/Itzulia2021?src=hash&amp;ref_src=twsrc%5Etfw\">#Itzulia2021<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LaCasaDelCiclismo?src=hash&amp;ref_src=twsrc%5Etfw\">#LaCasaDelCiclismo<\/a> &#x1f6b4;&#x200d;&#x2642;&#xfe0f;<\/p>\n<p>\u2014 Eurosport.es (@Eurosport_ES) <a href=\"https:\/\/twitter.com\/Eurosport_ES\/status\/1380540303535435783?ref_src=twsrc%5Etfw\">April 9, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-2021-classement-5eme-etape\/\" target=\"_blank\" rel=\"noopener\"><strong>Le classement de la 5\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-2021-classement-general\/\" target=\"_blank\" rel=\"noopener\"><strong>Le classement g\u00e9n\u00e9ral<\/strong><\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; Au terme d&rsquo;une grande \u00e9chapp\u00e9e, la Deceuninck &#8211; Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque : Mikkel Honor\u00e9 a devanc\u00e9 Josef Cerny, main dans la main ! Brandon McNulty (UAE Team Emirates) conserve la t\u00eate du classement g\u00e9n\u00e9ral.<\/p>\n","protected":false},"author":4,"featured_media":119708,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2307],"tags":[7583],"class_list":["post-119700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","tag-tour-du-pays-basque"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny<\/title>\n<meta name=\"description\" content=\"CYCLISME - Au terme d&#039;une grande \u00e9chapp\u00e9e, la Deceuninck - Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque, Honor\u00e9 devant Cerny.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - Au terme d&#039;une grande \u00e9chapp\u00e9e, la Deceuninck - Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque, Honor\u00e9 devant Cerny.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-09T15:19:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-09T15:30:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny\",\"datePublished\":\"2021-04-09T15:19:30+00:00\",\"dateModified\":\"2021-04-09T15:30:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/\"},\"wordCount\":276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png\",\"keywords\":[\"Tour du Pays Basque\"],\"articleSection\":[\"Cyclisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/\",\"name\":\"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png\",\"datePublished\":\"2021-04-09T15:19:30+00:00\",\"dateModified\":\"2021-04-09T15:30:52+00:00\",\"description\":\"CYCLISME - Au terme d'une grande \u00e9chapp\u00e9e, la Deceuninck - Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque, Honor\u00e9 devant Cerny.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png\",\"width\":800,\"height\":445,\"caption\":\"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny","description":"CYCLISME - Au terme d'une grande \u00e9chapp\u00e9e, la Deceuninck - Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque, Honor\u00e9 devant Cerny.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny","og_description":"CYCLISME - Au terme d'une grande \u00e9chapp\u00e9e, la Deceuninck - Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque, Honor\u00e9 devant Cerny.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-04-09T15:19:30+00:00","article_modified_time":"2021-04-09T15:30:52+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny","datePublished":"2021-04-09T15:19:30+00:00","dateModified":"2021-04-09T15:30:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/"},"wordCount":276,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png","keywords":["Tour du Pays Basque"],"articleSection":["Cyclisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/","url":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/","name":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png","datePublished":"2021-04-09T15:19:30+00:00","dateModified":"2021-04-09T15:30:52+00:00","description":"CYCLISME - Au terme d'une grande \u00e9chapp\u00e9e, la Deceuninck - Quick-Step a r\u00e9alis\u00e9 un doubl\u00e9 sur la 5\u00e8me \u00e9tape du Tour du Pays Basque, Honor\u00e9 devant Cerny.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Tour-du-Pays-Basque-Double-Deceuninck-sur-la-5eme-etape-Honore-devant-Cerny.png","width":800,"height":445,"caption":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-du-pays-basque-double-deceuninck-sur-5eme-etape-honore-devant-cerny\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour du Pays Basque : Doubl\u00e9 Deceuninck sur la 5\u00e8me \u00e9tape, Honor\u00e9 devant Cerny"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/119700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=119700"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/119700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/119708"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=119700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=119700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=119700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}