{"id":120158,"date":"2021-04-11T14:25:54","date_gmt":"2021-04-11T12:25:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=120158"},"modified":"2025-07-24T21:57:05","modified_gmt":"2025-07-24T19:57:05","slug":"formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/","title":{"rendered":"Formule E &#8211; ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/sports-mecaniques\/formule-e\/\">Formule E<\/a> &#8211; Apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-un-jean-eric-vergne-revanchard-remporte-sa-premiere-victoire-de-la-saison\/\" target=\"_blank\" rel=\"noopener\">la victoire de Jean-Eric Vergne la veille<\/a>, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. En effet, apr\u00e8s la pole du rookie Nick Cassidy devant le Fran\u00e7ais Norman Nato, c&rsquo;est finalement Stoffel Vandoorne qui a remport\u00e9 la course sur une piste humide comme tout au long du week-end.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Comme lors de la course 1, le d\u00e9part de la course a eu lieu sous r\u00e9gime de Safety-Car. Entre t\u00eates \u00e0 queue, grosses batailles et accrochages, la deuxi\u00e8me course de cet <strong>ePrix de Rome<\/strong> a \u00e9t\u00e9 tr\u00e8s anim\u00e9e de bout en bout. Poleman samedi, puis victime d&rsquo;un accrochage lors de la course 1, <strong>Stoffel Vandoorne<\/strong> a finalement \u00e9t\u00e9 chercher sa premi\u00e8re victoire de la saison, la deuxi\u00e8me pour l&rsquo;\u00e9curie Mercedes qui r\u00e9cup\u00e8re la deuxi\u00e8me place du championnat constructeurs. <strong>Alexander Sims<\/strong> (2\u00e8me) et <strong>Pascal Wehrlein<\/strong> (3\u00e8me) compl\u00e8tent le podium apr\u00e8s la disqualification de <strong>Norman Nato<\/strong> pour avoir utilis\u00e9 un surplus de puissance pour terminer la course. <strong>Sam Bird<\/strong> et <strong>Nick de Vries<\/strong>, qui n&rsquo;ont pas fini la course \u00e0 cause d&rsquo;un accrochage, perdent de gros points au championnat du monde.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Hear from your Round 4&#xfe0f;&#x20e3; race winner, <a href=\"https:\/\/twitter.com\/svandoorne?ref_src=twsrc%5Etfw\">@svandoorne<\/a>! &#x1f3c6;<a href=\"https:\/\/twitter.com\/hashtag\/RomeEPrix?src=hash&amp;ref_src=twsrc%5Etfw\">#RomeEPrix<\/a> <a href=\"https:\/\/twitter.com\/MercedesEQFE?ref_src=twsrc%5Etfw\">@MercedesEQFE<\/a> <a href=\"https:\/\/t.co\/hM5IITSjKV\">pic.twitter.com\/hM5IITSjKV<\/a><\/p>\n<p>\u2014 ABB FIA Formula E World Championship (@FIAFormulaE) <a href=\"https:\/\/twitter.com\/FIAFormulaE\/status\/1381216587726925827?ref_src=twsrc%5Etfw\">April 11, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Norman Nato d\u00e9class\u00e9, Vergne 11\u00e8me<\/h2>\n<p style=\"text-align: justify;\">Vingti\u00e8me sur la grille de cette Course 2, <strong>Jean-Eric Vergne<\/strong> a connu un dimanche difficile apr\u00e8s avoir gagn\u00e9 la veille. Au terme d&rsquo;une course pass\u00e9e en fin de peloton, le double champion de Formule E a termin\u00e9 \u00e0 une d\u00e9cevante 11\u00e8me place apr\u00e8s les diverses disqualifications et accidents des autres concurrents. Le Fran\u00e7ais sort, par la m\u00eame occasion, du top 5 du classement pilotes, une mauvaise op\u00e9ration sur le plan comptable.<\/p>\n<p style=\"text-align: justify;\"><strong>Norman Nato<\/strong> a, quant \u00e0 lui, connu un excellent d\u00e9but de journ\u00e9e avec son deuxi\u00e8me temps en qualifications pr\u00e9sageant le meilleur pour la course. D\u00e8s les premiers tours, le Cannois a pris la t\u00eate de la course apr\u00e8s le t\u00eate \u00e0 queue du poleman <strong>Nick Cassidy<\/strong>. Cependant, cela n&rsquo;a pas dur\u00e9 longtemps pour le pilote de l&rsquo;\u00e9curie mon\u00e9gasque ROKIT Venturi Racing. D\u00e9pass\u00e9 peu de temps apr\u00e8s par<strong> Wehrlein<\/strong> puis <strong>Vandoorne<\/strong>, le Fran\u00e7ais a finalement termin\u00e9 3\u00e8me au terme d&rsquo;une course joliment ma\u00eetris\u00e9e jusqu&rsquo;au bout en terminant avec seulement 0.1% d&rsquo;\u00e9nergie dans la batterie de sa monoplace. Cependant, il a finalement \u00e9t\u00e9 d\u00e9class\u00e9 au profit de <strong>Pascal Wehrlein<\/strong> pour avoir utilis\u00e9 plus de puissance que ce qui n&rsquo;est autoris\u00e9. Une fin cruelle pour le Fran\u00e7ais qui s&rsquo;est vaillamment battu tout au long de la course.<\/p>\n<p><strong><b><i><em>Tanguy Le Jeune<br \/>\n<a href=\"https:\/\/twitter.com\/LeJeuneT_\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"https:\/\/i1.wp.com\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter.png?resize=38%2C38\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/tanguyljn_\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3709\" src=\"https:\/\/i0.wp.com\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/signature-instagram.png?resize=38%2C38&amp;ssl=1\" sizes=\"auto, (max-width: 38px) 100vw, 38px\" srcset=\"https:\/\/i0.wp.com\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/signature-instagram.png?resize=38%2C38&amp;ssl=1 283w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/signature-instagram-150x150.png 150w\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/em>\u00a0<\/i><\/b><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Formule E &#8211; Apr\u00e8s la victoire de Jean-Eric Vergne la veille, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. En effet, apr\u00e8s la pole du rookie Nick Cassidy devant le Fran\u00e7ais Norman Nato, c&rsquo;est finalement Stoffel Vandoorne qui a remport\u00e9 la course sur une piste humide comme tout au long du week-end.\u00a0<\/p>\n","protected":false},"author":46,"featured_media":120192,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2312],"tags":[5480],"class_list":["post-120158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports-mecaniques","tag-formule-e"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2<\/title>\n<meta name=\"description\" content=\"Formule E - Apr\u00e8s la victoire de Jean-Eric Vergne la veille, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. Stoffel Vandoorne s&#039;est impos\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2\" \/>\n<meta property=\"og:description\" content=\"Formule E - Apr\u00e8s la victoire de Jean-Eric Vergne la veille, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. Stoffel Vandoorne s&#039;est impos\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-11T12:25:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T19:57:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tanguy Le Jeune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LeJeuneT_\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/\"},\"author\":{\"name\":\"Tanguy Le Jeune\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2\"},\"headline\":\"Formule E &#8211; ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2\",\"datePublished\":\"2021-04-11T12:25:54+00:00\",\"dateModified\":\"2025-07-24T19:57:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png\",\"keywords\":[\"Formule E\"],\"articleSection\":[\"Sports m\u00e9caniques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/\",\"name\":\"Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png\",\"datePublished\":\"2021-04-11T12:25:54+00:00\",\"dateModified\":\"2025-07-24T19:57:05+00:00\",\"description\":\"Formule E - Apr\u00e8s la victoire de Jean-Eric Vergne la veille, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. Stoffel Vandoorne s'est impos\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png\",\"width\":800,\"height\":445,\"caption\":\"Formule E - ePrix de Rome - Le Belge Stoffel Vandoorne vainqueur de la course 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formule E &#8211; ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2\",\"name\":\"Tanguy Le Jeune\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg\",\"caption\":\"Tanguy Le Jeune\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis novembre 2020 - Lionel Messi, Kobe Bryant, Lewis Hamilton. Quel rapport entre ces trois l\u00e9gendes ? Aucun, hormis leur statut de l\u00e9gende. Mais, pour moi, ces stars ont quelque chose en commun. Ce sont mes idoles, mes exemples et les grands cr\u00e9ateurs de ma passion pour le sport. Malgr\u00e9 mon cruel manque de talent pour pratiquer le sport au haut niveau, mon amour et ma passion me poussent, chaque jour, \u00e0 vous partager l\u2019actualit\u00e9 au travers de ce que je sais probablement faire le mieux : \u00e9crire.\",\"sameAs\":[\"https:\/\/www.instagram.com\/tanguyljn_\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/LeJeuneT_\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/tanguylj\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2","description":"Formule E - Apr\u00e8s la victoire de Jean-Eric Vergne la veille, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. Stoffel Vandoorne s'est impos\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2","og_description":"Formule E - Apr\u00e8s la victoire de Jean-Eric Vergne la veille, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. Stoffel Vandoorne s'est impos\u00e9.","og_url":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-04-11T12:25:54+00:00","article_modified_time":"2025-07-24T19:57:05+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png","type":"image\/png"}],"author":"Tanguy Le Jeune","twitter_card":"summary_large_image","twitter_title":"Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2","twitter_creator":"@https:\/\/twitter.com\/LeJeuneT_","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/"},"author":{"name":"Tanguy Le Jeune","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2"},"headline":"Formule E &#8211; ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2","datePublished":"2021-04-11T12:25:54+00:00","dateModified":"2025-07-24T19:57:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png","keywords":["Formule E"],"articleSection":["Sports m\u00e9caniques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/","url":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/","name":"Formule E - ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png","datePublished":"2021-04-11T12:25:54+00:00","dateModified":"2025-07-24T19:57:05+00:00","description":"Formule E - Apr\u00e8s la victoire de Jean-Eric Vergne la veille, la course 2 de ce week-end \u00e0 Rome a \u00e9t\u00e9 le th\u00e9\u00e2tre de nombreuses surprises. Stoffel Vandoorne s'est impos\u00e9.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Formule-E-ePrix-de-Rome-Le-Belge-Stoffel-Vandoorne-vainqueur-de-la-course-2.png","width":800,"height":445,"caption":"Formule E - ePrix de Rome - Le Belge Stoffel Vandoorne vainqueur de la course 2"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-eprix-de-rome-le-belge-stoffel-vandoorne-vainqueur-course-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Formule E &#8211; ePrix de Rome : Le Belge Stoffel Vandoorne vainqueur de la course 2"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2","name":"Tanguy Le Jeune","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg","caption":"Tanguy Le Jeune"},"description":"Journaliste\/r\u00e9dacteur depuis novembre 2020 - Lionel Messi, Kobe Bryant, Lewis Hamilton. Quel rapport entre ces trois l\u00e9gendes ? Aucun, hormis leur statut de l\u00e9gende. Mais, pour moi, ces stars ont quelque chose en commun. Ce sont mes idoles, mes exemples et les grands cr\u00e9ateurs de ma passion pour le sport. Malgr\u00e9 mon cruel manque de talent pour pratiquer le sport au haut niveau, mon amour et ma passion me poussent, chaque jour, \u00e0 vous partager l\u2019actualit\u00e9 au travers de ce que je sais probablement faire le mieux : \u00e9crire.","sameAs":["https:\/\/www.instagram.com\/tanguyljn_\/","https:\/\/x.com\/https:\/\/twitter.com\/LeJeuneT_"],"url":"https:\/\/dicodusport.fr\/blog\/author\/tanguylj\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/120158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=120158"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/120158\/revisions"}],"predecessor-version":[{"id":597741,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/120158\/revisions\/597741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/120192"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=120158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=120158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=120158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}