{"id":120468,"date":"2021-04-13T11:39:40","date_gmt":"2021-04-13T09:39:40","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=120468"},"modified":"2021-04-13T11:39:40","modified_gmt":"2021-04-13T09:39:40","slug":"le-fc-nantes-toujours-plus-proche-de-la-ligue-2","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/","title":{"rendered":"Le FC Nantes toujours plus proche de la Ligue 2"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE 1 &#8211; Une nouvelle fois d\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent. Dix-neuvi\u00e8mes \u00e0 six journ\u00e9es de la fin de la saison, les Canaris se rapprochent encore un peu plus de la Ligue 2. <\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Ce dimanche, le FC Nantes a perdu le derby face au Stade Rennais (1-0). Sur une frappe sublime de <strong>Martin Terrier<\/strong>, les rouge et noir enfoncent encore un peu les Canaris dans la crise. Avant-derniers de Ligue 1, les hommes d\u2019<strong>Antoine Kombouar\u00e9<\/strong> luttent pour leur survie dans l\u2019\u00e9lite. \u00c0 quatre points du premier non rel\u00e9gable (Lorient), et \u00e0 six journ\u00e9es de la fin, math\u00e9matiquement, tout est encore possible. Seulement, l\u2019absence de caract\u00e8re ou encore de leadership laisse penser que cette \u00e9quipe n\u2019a pas les armes pour se maintenir.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Un combat perdu d\u2019avance\u00a0?<\/strong><\/h2>\n<p style=\"text-align: justify;\">En effet, aucun joueur ou m\u00eame l\u2019entra\u00eeneur, ne semblent vouloir tirer la sonnette d\u2019alarme. Et ce, malgr\u00e9 les trois diff\u00e9rents coachs qu\u2019a connu Nantes cette saison. Si on avait cru que Nantes se relancerait apr\u00e8s la victoire contre le Paris Saint-Germain (2-1) le mois dernier, les Canaris retourn\u00e9s \u00e0 la r\u00e9alit\u00e9. <strong>Depuis cet exploit, aucune victoire n\u2019est \u00e0 signaler<\/strong>. Un nul contre Lorient (1-1), concurrent \u00e0 la rel\u00e9gation, et deux d\u00e9faites contre Nice (2-1) et Rennes donc. Avec seulement deux victoires sur les 23 derniers matchs, les Nantais eux-m\u00eames semblent avoir abdiqu\u00e9.<\/p>\n<p style=\"text-align: justify;\">Avec 28 points, Le <strong>FC Nantes<\/strong> r\u00e9alise l\u00e0, le plus mauvais total de son histoire \u00e0 ce stade de la comp\u00e9tition. Bien que <strong>Ludovic Blas<\/strong> (23 ans) essaye, par moment, de montrer la voie \u00e0 ses co\u00e9quipiers qui ne le suivent pas. Ainsi, sur le terrain, les Nantais ne se procurent que tr\u00e8s peu d\u2019occasions et ne parviennent pas \u00e0 les transformer en but. Pour preuve, les Canaris ont la troisi\u00e8me pire attaque de Ligue 1 avec 32 buts marqu\u00e9s en 32 matchs, devant Dijon (20 buts \u2013 20<sup>\u00e8me<\/sup>) et N\u00eemes (31 buts \u2013 18<sup>\u00e8me<\/sup>). Si la rel\u00e9gation semble plus proche que jamais, le calendrier des Canaris pourrait bien leur permettre de se sauver, ou de couler.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Un calendrier \u00e0 double tranchant<\/strong><\/h2>\n<p style=\"text-align: justify;\">\u00c0 six matchs de la fin du championnat, les Nantais peuvent au moins se targuer d\u2019avoir un calendrier favorable. En effet, lors de ces six matchs, ils affronteront quatre concurrents \u00e0 la rel\u00e9gation : <strong>Strasbourg (14<sup>\u00e8me<\/sup>)<\/strong>, <strong>Brest (16<sup>\u00e8me<\/sup>)<\/strong>, <strong>Bordeaux (15<sup>\u00e8me<\/sup>)<\/strong> et <strong>Dijon (20<sup>\u00e8me<\/sup>)<\/strong>. Des victoires lors de ces matchs pourraient donc permettre au club nantais de rattraper puis distancer ses concurrents. Dans le cas contraire, les Canaris sombreraient en direction de la Ligue 2.<\/p>\n<p style=\"text-align: justify;\">Avant ces rencontres ils recevront Lyon dimanche, et il est tr\u00e8s difficile de pronostiquer un sc\u00e9nario favorable pour les vert et jaune. Face \u00e0 une \u00e9quipe lyonnaise qui doit imp\u00e9rativement l\u2019emporter pour rester dans la course au titre, les Nantais partent logiquement outsiders. Enfin, lors de la derni\u00e8re journ\u00e9e, les Canaris affronteront Montpellier (8<sup>\u00e8me<\/sup>) qui pourrait bien encore se battre pour l\u2019Europa League.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Prochain rendez-vous d\u00e8s  (21h00) pour la r\u00e9ception de l&rsquo;<a href=\"https:\/\/twitter.com\/OL?ref_src=twsrc%5Etfw\">@OL<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/fcnol?src=hash&amp;ref_src=twsrc%5Etfw\">#fcnol<\/a> <a href=\"https:\/\/t.co\/GSlLQYVkop\">pic.twitter.com\/GSlLQYVkop<\/a><\/p>\n<p>\u2014 FC Nantes (@FCNantes) <a href=\"https:\/\/twitter.com\/FCNantes\/status\/1381545628015075335?ref_src=twsrc%5Etfw\">April 12, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Le maintien de Nantes dans l\u2019\u00e9lite semble donc plus que compromis et s\u2019il est probable de le voir en Ligue 2 l\u2019ann\u00e9e prochaine, il lui reste encore de belles opportunit\u00e9s pour se maintenir.<\/p>\n<p style=\"text-align: justify;\"><strong> <em>Jean Bod\u00e9r\u00e9<\/em><br \/>\n<a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-e1617919845690.png\" alt=\"\" width=\"37\" height=\"37\" \/><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 &#8211; Une nouvelle fois d\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent. Dix-neuvi\u00e8mes \u00e0 six journ\u00e9es de la fin de la saison, les Canaris se rapprochent encore un peu plus de la Ligue 2.<\/p>\n","protected":false},"author":52,"featured_media":120578,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[2300,75,1554],"class_list":["post-120468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-fc-nantes","tag-football","tag-ligue-1"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le FC Nantes toujours plus proche de la Ligue 2<\/title>\n<meta name=\"description\" content=\"LIGUE 1 - D\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent et se rapprochent encore un peu plus de la Ligue 2.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le FC Nantes toujours plus proche de la Ligue 2\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 - D\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent et se rapprochent encore un peu plus de la Ligue 2.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T09:39:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jean Bod\u00e9r\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le FC Nantes toujours plus proche de la Ligue 2\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/\"},\"author\":{\"name\":\"Jean Bod\u00e9r\u00e9\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05\"},\"headline\":\"Le FC Nantes toujours plus proche de la Ligue 2\",\"datePublished\":\"2021-04-13T09:39:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png\",\"keywords\":[\"fc nantes\",\"Football\",\"Ligue 1\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/\",\"name\":\"Le FC Nantes toujours plus proche de la Ligue 2\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png\",\"datePublished\":\"2021-04-13T09:39:40+00:00\",\"description\":\"LIGUE 1 - D\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent et se rapprochent encore un peu plus de la Ligue 2.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png\",\"width\":800,\"height\":445,\"caption\":\"Le FC Nantes toujours plus proche de la Ligue 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le FC Nantes toujours plus proche de la Ligue 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05\",\"name\":\"Jean Bod\u00e9r\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"caption\":\"Jean Bod\u00e9r\u00e9\"},\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/jeanb\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le FC Nantes toujours plus proche de la Ligue 2","description":"LIGUE 1 - D\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent et se rapprochent encore un peu plus de la Ligue 2.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Le FC Nantes toujours plus proche de la Ligue 2","og_description":"LIGUE 1 - D\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent et se rapprochent encore un peu plus de la Ligue 2.","og_url":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-04-13T09:39:40+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png","type":"image\/png"}],"author":"Jean Bod\u00e9r\u00e9","twitter_card":"summary_large_image","twitter_title":"Le FC Nantes toujours plus proche de la Ligue 2","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/"},"author":{"name":"Jean Bod\u00e9r\u00e9","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05"},"headline":"Le FC Nantes toujours plus proche de la Ligue 2","datePublished":"2021-04-13T09:39:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png","keywords":["fc nantes","Football","Ligue 1"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/","url":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/","name":"Le FC Nantes toujours plus proche de la Ligue 2","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png","datePublished":"2021-04-13T09:39:40+00:00","description":"LIGUE 1 - D\u00e9faits dimanche contre Rennes (1-0), le FC Nantes et ses joueurs succombent et se rapprochent encore un peu plus de la Ligue 2.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Le-FC-Nantes-toujours-plus-proche-de-la-Ligue-2.png","width":800,"height":445,"caption":"Le FC Nantes toujours plus proche de la Ligue 2"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-fc-nantes-toujours-plus-proche-de-la-ligue-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le FC Nantes toujours plus proche de la Ligue 2"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05","name":"Jean Bod\u00e9r\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","caption":"Jean Bod\u00e9r\u00e9"},"url":"https:\/\/dicodusport.fr\/blog\/author\/jeanb\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/120468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=120468"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/120468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/120578"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=120468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=120468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=120468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}