{"id":122228,"date":"2021-04-16T20:34:56","date_gmt":"2021-04-16T18:34:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=122228"},"modified":"2021-04-16T21:08:18","modified_gmt":"2021-04-16T19:08:18","slug":"atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/","title":{"rendered":"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Les quarts de finale du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises aujourd\u2019hui. D\u2019abord, l\u2019abandon de Davidovich Fokina, puis la qualification inattendue de Evans, mais surtout la racl\u00e9e inflig\u00e9e par Rublev \u00e0 <a href=\"https:\/\/dicodusport.fr\/blog\/tag\/rafael-nadal\/\" target=\"_blank\" rel=\"noopener\">Rafael Nadal<\/a> (6-2, 4-6, 6-2). En demi-finales, Stefanos Tsitsipas affrontera Daniel Evans alors que Casper Ruud d\u00e9fiera Andrey Rublev.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Aujourd\u2019hui, c\u2019\u00e9tait la suite du <strong>Masters 1000 de Monte-Carlo<\/strong> avec les quarts de finale. Et quelle journ\u00e9e ! Tout avait plut\u00f4t mal commenc\u00e9 lors du match opposant <strong>Tsitsipas<\/strong> \u00e0 <strong>Davidovich Fokina<\/strong>. En effet, l\u2019Espagnol a \u00e9t\u00e9 contraint d\u2019abandonner \u00e0 la fin du premier set apr\u00e8s une blessure au quadriceps. Mais lors du match suivant, <strong>Daniel Evans<\/strong> a pouss\u00e9 son r\u00eave encore un peu plus loin. Apr\u00e8s avoir r\u00e9ussi l\u2019exploit d\u2019\u00e9liminer Djokovic hier, le Britannique s\u2019est d\u00e9fait, au mental, de <strong>David Goffin<\/strong>.<\/p>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, <strong>Fognini<\/strong> a \u00e9t\u00e9 impuissant face \u00e0 Ruud. Vainqueur l\u2019ann\u00e9e pr\u00e9c\u00e9dente, l\u2019Italien ne conservera donc pas son titre. Facilement d\u00e9fait (6-4, 6-3) par le Norv\u00e9gien <strong>Casper Ruud<\/strong>, Fognini doit sa d\u00e9b\u00e2cle \u00e0 son manque de r\u00e9gularit\u00e9 et de concentration sur le court. Ruud s\u2019offre donc une deuxi\u00e8me demi-finale de Masters 1000 d\u2019affil\u00e9e apr\u00e8s Rome l\u2019ann\u00e9e derni\u00e8re. Mais la v\u00e9ritable surprise de cette journ\u00e9e, et de ce tournoi, c\u2019est bel et bien l\u2019\u00e9limination de Rafael Nadal avant m\u00eame le dernier carr\u00e9 par <strong>Andrey Rublev<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Nadal m\u00e9connaissable<\/h2>\n<p style=\"text-align: justify;\">Face au ma\u00eetre des lieux, <strong>Andrey Rublev<\/strong> (8\u00e8me mondial) n\u2019a pas trembl\u00e9. Alors que <strong>Nadal<\/strong> (3\u00e8me mondial) avait terrass\u00e9 son adversaire de la veille, <strong>Grigor Dimitrov<\/strong> (6-1, 6-1), on ne s\u2019attendait pas \u00e0 le voir perdre d\u00e8s aujourd\u2019hui. Seulement, le Russe de 23 ans a su d\u00e9jouer tous les pronostics et terrasser le ma\u00eetre de la terre battue.<\/p>\n<p style=\"text-align: justify;\">Dans le premier set, l\u2019Espagnol \u00e9tait comme absent. Auteur de 5 doubles fautes et d\u2019une multitude d\u2019erreurs dues \u00e0 un jeu trop court, <strong>Nadal<\/strong> n\u2019y \u00e9tait pas aujourd\u2019hui. Dans le deuxi\u00e8me acte, tout semblait repartir de plus belle. Subissant le break d\u2019entr\u00e9e et men\u00e9 4-2, on se dit que Nadal vit ses derni\u00e8res minutes \u00e0 Monaco. Seulement, dans un sursaut d\u2019orgueil, il se r\u00e9veilla soudainement et remporta le set 6-4. Tout le monde pense alors que la machine Nadal est lanc\u00e9e et impossible \u00e0 arr\u00eater.<\/p>\n<p style=\"text-align: justify;\">Mais dans ce set d\u00e9cisif, la machine s\u2019est enray\u00e9e. Pire que \u00e7a, <strong>Rafael Nadal<\/strong> est impuissant face aux assauts du Russe et commet bien trop d\u2019erreurs. Au final, <strong>Rublev<\/strong> cr\u00e9e l\u2019exploit en remportant ce set (6-2), et dans le m\u00eame temps, le match (6-2, 4-6, 6-2).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f4a5; Rublev s&rsquo;offre Nadal ! Le Russe d\u00e9croche avec la mani\u00e8re son premier succ\u00e8s face au roi de la terre battue !<\/p>\n<p>Suivez le d\u00e9nouement du Masters 1000 de Monte-Carlo sur Eurosport et <a href=\"https:\/\/t.co\/7qbNJch1A0\">https:\/\/t.co\/7qbNJch1A0<\/a> <a href=\"https:\/\/t.co\/ckDvbXaBOk\">pic.twitter.com\/ckDvbXaBOk<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/1383123847038271491?ref_src=twsrc%5Etfw\">April 16, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>Une victoire en un set pour Tsitsipas<\/strong><\/h2>\n<p style=\"text-align: justify;\">Cette journ\u00e9e des quarts de finale commen\u00e7ait donc avec un match qui nous a laiss\u00e9 un go\u00fbt d\u2019inachev\u00e9. <strong>Alejandro Davidovich Fokina<\/strong> (58\u00e8me mondial) venait d\u00e9fier <strong>Stefanos Tsitsipas<\/strong> (5\u00e8me mondial). Apr\u00e8s avoir battu <strong>Lucas Pouille<\/strong> hier, l\u2019Espagnol est rentr\u00e9 sur le court en tant qu\u2019outsider mais avait tout de m\u00eame quelques atouts dans sa manche. Malheureusement pour lui, il n\u2019a pas eu le temps de les sortir.<\/p>\n<p style=\"text-align: justify;\">Alors qu\u2019il tenait t\u00eate au Grec, <strong>Davidovich Fokina<\/strong> se blesse au niveau du quadriceps au bout d\u2019une course. Le score \u00e9tait de 3-3 \u00e0 ce moment-l\u00e0 et ce sera le d\u00e9but de la fin pour le joueur de 21 ans. Dans la douleur, il finira ce set et le conc\u00e9dera (7-5), avant d&rsquo;abandonner. Un coup dur alors qu\u2019il disputait l\u00e0 son premier quart de finale en Masters 1000.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Le r\u00eave continue pour Daniel Evans, Ruud facile face \u00e0 Fognini<\/strong><\/h2>\n<p style=\"text-align: justify;\">C\u2019est la surprise de ce tournoi. Apr\u00e8s avoir \u00e9limin\u00e9 <strong>Novak Djokovic<\/strong> (num\u00e9ro 1 mondial) hier, <strong>Daniel Evans<\/strong> (33\u00e8me mondial) s\u2019est offert cet apr\u00e8s-midi <strong>David Goffin<\/strong> (15\u00e8me mondial). Alors qu\u2019il disputait, lui aussi, son premier quart de finale en Masters 1000, le Britannique s\u2019est impos\u00e9 en trois sets contre le Belge (5-7, 6-3, 6-4).<\/p>\n<p style=\"text-align: justify;\">Dans le dur lors du premier set, <strong>Evans<\/strong> semblait ne pas s\u2019\u00eatre remis de son combat contre Djokovic hier. Seulement, il peut remercier Goffin sur les deux manches suivantes qui s\u2019est montr\u00e9 d\u2019une inefficacit\u00e9 rare. En ne convertissant que deux balles de break sur dix-sept dans cette rencontre, le Belge perdait ce match au mental.<\/p>\n<p style=\"text-align: justify;\">Ces demi-finales feront s\u2019affronter, d\u00e8s demain, Stefanos Tsitsipas et Daniel Evans puis Casper Ruud et Andrey Rublev.<\/p>\n<p><em><strong>Jean Bod\u00e9r\u00e9<\/strong><\/em><br \/>\n<a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908 size-full\" src=\"https:\/\/i2.wp.com\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-e1617919845690.png?resize=37%2C37&amp;ssl=1\" alt=\"\" width=\"37\" height=\"37\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les quarts de finale du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises aujourd\u2019hui. D\u2019abord, l\u2019abandon de Davidovich Fokina, puis la qualification inattendue de Evans, mais surtout la racl\u00e9e inflig\u00e9e par Rublev \u00e0 Rafael Nadal (6-2, 4-6, 6-2). En demi-finales, Stefanos Tsitsipas affrontera Daniel Evans alors que Casper Ruud d\u00e9fiera Andrey Rublev.<\/p>\n","protected":false},"author":52,"featured_media":122234,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2302],"tags":[7675,1196,4693,136],"class_list":["post-122228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-masters-monte-carlo","tag-nadal","tag-stefanos-tsitsipas","tag-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !<\/title>\n<meta name=\"description\" content=\"Les quarts de finales du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises, avec notamment la racl\u00e9e inflig\u00e9e par Rublev \u00e0 Nadal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !\" \/>\n<meta property=\"og:description\" content=\"Les quarts de finales du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises, avec notamment la racl\u00e9e inflig\u00e9e par Rublev \u00e0 Nadal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-16T18:34:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-16T19:08:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jean Bod\u00e9r\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/\"},\"author\":{\"name\":\"Jean Bod\u00e9r\u00e9\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05\"},\"headline\":\"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !\",\"datePublished\":\"2021-04-16T18:34:56+00:00\",\"dateModified\":\"2021-04-16T19:08:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/\"},\"wordCount\":829,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png\",\"keywords\":[\"Masters Monte-Carlo\",\"Nadal\",\"Stefanos Tsitsipas\",\"Tennis\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/\",\"name\":\"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png\",\"datePublished\":\"2021-04-16T18:34:56+00:00\",\"dateModified\":\"2021-04-16T19:08:18+00:00\",\"description\":\"Les quarts de finales du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises, avec notamment la racl\u00e9e inflig\u00e9e par Rublev \u00e0 Nadal.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png\",\"width\":800,\"height\":445,\"caption\":\"ATP Monte-Carlo - Andrey Rublev terrasse Rafael Nadal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05\",\"name\":\"Jean Bod\u00e9r\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"caption\":\"Jean Bod\u00e9r\u00e9\"},\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/jeanb\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !","description":"Les quarts de finales du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises, avec notamment la racl\u00e9e inflig\u00e9e par Rublev \u00e0 Nadal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/","og_locale":"fr_FR","og_type":"article","og_title":"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !","og_description":"Les quarts de finales du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises, avec notamment la racl\u00e9e inflig\u00e9e par Rublev \u00e0 Nadal.","og_url":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-04-16T18:34:56+00:00","article_modified_time":"2021-04-16T19:08:18+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png","type":"image\/png"}],"author":"Jean Bod\u00e9r\u00e9","twitter_card":"summary_large_image","twitter_title":"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/"},"author":{"name":"Jean Bod\u00e9r\u00e9","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05"},"headline":"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !","datePublished":"2021-04-16T18:34:56+00:00","dateModified":"2021-04-16T19:08:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/"},"wordCount":829,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png","keywords":["Masters Monte-Carlo","Nadal","Stefanos Tsitsipas","Tennis"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/","url":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/","name":"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png","datePublished":"2021-04-16T18:34:56+00:00","dateModified":"2021-04-16T19:08:18+00:00","description":"Les quarts de finales du tournoi de Monte-Carlo ont r\u00e9serv\u00e9 quelques surprises, avec notamment la racl\u00e9e inflig\u00e9e par Rublev \u00e0 Nadal.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/ATP-Monte-Carlo-Andrey-Rublev-terrasse-Rafael-Nadal.png","width":800,"height":445,"caption":"ATP Monte-Carlo - Andrey Rublev terrasse Rafael Nadal"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/atp-monte-carlo-andrey-rublev-terrasse-rafael-nadal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"ATP Monte-Carlo : Andrey Rublev terrasse Rafael Nadal !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb75f6e4b58e9b98515bdc7902bb5a05","name":"Jean Bod\u00e9r\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","caption":"Jean Bod\u00e9r\u00e9"},"url":"https:\/\/dicodusport.fr\/blog\/author\/jeanb\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/122228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=122228"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/122228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/122234"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=122228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=122228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=122228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}