{"id":124859,"date":"2021-04-29T08:30:46","date_gmt":"2021-04-29T06:30:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=124859&#038;preview=true&#038;preview_id=124859"},"modified":"2021-04-29T08:03:43","modified_gmt":"2021-04-29T06:03:43","slug":"athletisme-relais-mondiaux-les-enjeux-de-la-competition","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/","title":{"rendered":"Athl\u00e9tisme &#8211; Relais mondiaux : les enjeux de la comp\u00e9tition"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>ATHL\u00c9TISME &#8211; Les Mondiaux de relais ont lieu les 1er et 2 mai prochains \u00e0 Chorzow (Pologne). L&rsquo;\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs. Cet \u00e9v\u00e9nement existe depuis 2014 et l&rsquo;\u00e9dition 2021 est la premi\u00e8re que les habitants de France m\u00e9tropolitaine pourront regarder en direct sans d\u00e9calage horaire.<\/em><\/strong><\/p>\n<h2>Des enjeux majeurs<\/h2>\n<p style=\"text-align: justify;\">Les enjeux pour les 36 pays engag\u00e9s sont multiples, mais la qualification pour les <strong>Jeux Olympiques de Tokyo<\/strong> cet \u00e9t\u00e9 et la possibilit\u00e9 d&rsquo;un titre de champion du monde sont les principaux.<\/p>\n<p style=\"text-align: justify;\">Certaines \u00e9quipes sont d\u00e9j\u00e0 qualifi\u00e9es pour les Jeux en ayant termin\u00e9 dans les 8 premiers des derniers Championnats du monde de Doha, en 2019. Les autres pourront se qualifier en terminant dans les 8 premiers ce week-end. S&rsquo;il reste des places, le quota de 16 \u00e9quipes sera compl\u00e9t\u00e9 avec celles ayant r\u00e9alis\u00e9 les meilleures performances avant le 29 juin 2021.<\/p>\n<h2>Les nations d\u00e9j\u00e0 qualifi\u00e9es par \u00e9preuve<\/h2>\n<ul>\n<li><strong>4&#215;100 m femmes<\/strong> : Allemagne &#x1f1e9;&#x1f1ea;, Chine &#x1f1e8;&#x1f1f3;, Etats-Unis &#x1f1fa;&#x1f1f8;, Grande Bretagne &#x1f1ec;&#x1f1e7;, Italie &#x1f1ee;&#x1f1f9;, Jama\u00efque &#x1f1ef;&#x1f1f2;, Suisse &#x1f1e8;&#x1f1ed;, Trinit\u00e9 &amp; Tobago &#x1f1f9;&#x1f1f9;<\/li>\n<li><strong>4&#215;100 m hommes<\/strong> :\u00a0Afrique du Sud &#x1f1ff;&#x1f1e6;, Br\u00e9sil &#x1f1e7;&#x1f1f7;, Chine &#x1f1e8;&#x1f1f3;, Etats-Unis &#x1f1fa;&#x1f1f8;, France &#x1f1eb;&#x1f1f7;, Grande Bretagne &#x1f1ec;&#x1f1e7;, Japon &#x1f1ef;&#x1f1f5;, Pays-Bas &#x1f1f3;&#x1f1f1;<\/li>\n<li><strong>4&#215;400 m femmes<\/strong> : Belgique &#x1f1e7;&#x1f1ea;, Canada &#x1f1e8;&#x1f1e6;, Etats-Unis &#x1f1fa;&#x1f1f8;, Grande Bretagne &#x1f1ec;&#x1f1e7;, Jama\u00efque &#x1f1ef;&#x1f1f2;, Pays-Bas &#x1f1f3;&#x1f1f1;, Pologne &#x1f1f5;&#x1f1f1;, Ukraine &#x1f1fa;&#x1f1e6;<\/li>\n<li><strong>4&#215;400 m hommes<\/strong> : Belgique &#x1f1e7;&#x1f1ea; , Colombie &#x1f1e8;&#x1f1f4;, Etats-Unis &#x1f1fa;&#x1f1f8;, France &#x1f1eb;&#x1f1f7;, Grande Bretagne &#x1f1ec;&#x1f1e7;, Italie &#x1f1ee;&#x1f1f9;, Jama\u00efque &#x1f1ef;&#x1f1f2;, Trinit\u00e9 &amp; Tobago &#x1f1f9;&#x1f1f9;<\/li>\n<li><strong>4&#215;400 m mixte<\/strong> :\u00a0 Bahre\u00efn &#x1f1e7;&#x1f1ed;, Belgique &#x1f1e7;&#x1f1ea;, Br\u00e9sil &#x1f1e7;&#x1f1f7;, Etats-Unis &#x1f1fa;&#x1f1f8;, Grande Bretagne &#x1f1ec;&#x1f1e7;, Inde &#x1f1ee;&#x1f1f3;, Jama\u00efque &#x1f1ef;&#x1f1f2;, Pologne &#x1f1f5;&#x1f1f1;<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les \u00e9quipes de <strong>France<\/strong> du 4&#215;100 m femmes, du 4&#215;400 m femmes et du 4&#215;400 m mixte auront donc pour objectif de figurer parmi les 8 premi\u00e8res \u00e9quipes ce week-end afin de se qualifier pour les <strong>Jeux Olympiques de Tokyo<\/strong>.<\/p>\n<p style=\"text-align: justify;\">A noter que l&rsquo;\u00e9quipe de <strong>France<\/strong> n&rsquo;a obtenu qu&rsquo;un seul titre dans cette comp\u00e9tition depuis sa cr\u00e9ation en 2014. Il s&rsquo;agit de l&rsquo;\u00e9quipe f\u00e9minine du 4&#215;200 m lors de l&rsquo;\u00e9dition 2019 au Japon, compos\u00e9e de <strong>Carolle Zahi<\/strong>, <strong>Estelle Raffai<\/strong>, <strong>Cynthia Leduc<\/strong> et <strong>Maroussia Par\u00e9<\/strong>. Elles ont \u00e9tabli le record de <strong>France<\/strong> qui n&rsquo;a jamais \u00e9t\u00e9 battu depuis.<\/p>\n<p style=\"text-align: justify;\">Cette ann\u00e9e, la FFA n&rsquo;a pas d\u00e9cid\u00e9 d&rsquo;envoyer des \u00e9quipes pour les courses de 4&#215;200 m, en raison de la crise sanitaire et pr\u00e9f\u00e9rant se concentrer sur la pr\u00e9paration des JO. Les \u00e9preuves de 4x200m, le 2x2x400m mixte et le relais de haies mixtes qui se d\u00e9rouleront ce week-end ne sont pas des \u00e9preuves olympiques.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-2021-la-selection-francaise\/\">Relais Mondiaux 2021 : la s\u00e9lection fran\u00e7aise<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>ATHL\u00c9TISME &#8211; Les Mondiaux de relais ont lieu les 1er et 2 mai prochains \u00e0 Chorzow (Pologne). L&rsquo;\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs. Cet \u00e9v\u00e9nement existe depuis 2014 et l&rsquo;\u00e9dition 2021 est la premi\u00e8re que les habitants de France m\u00e9tropolitaine pourront regarder en direct sans d\u00e9calage horaire.<\/p>\n","protected":false},"author":54,"featured_media":125390,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308],"tags":[143,161],"class_list":["post-124859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","tag-athletisme","tag-jeux-olympiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition<\/title>\n<meta name=\"description\" content=\"Les Mondiaux de relais ont lieu les 1er et 2 Mai prochains \u00e0 Chorzow (Pologne). L&#039;\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition\" \/>\n<meta property=\"og:description\" content=\"Les Mondiaux de relais ont lieu les 1er et 2 Mai prochains \u00e0 Chorzow (Pologne). L&#039;\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/roxane.lecacher\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-29T06:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roxane Lecacher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/\"},\"author\":{\"name\":\"Roxane Lecacher\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\"},\"headline\":\"Athl\u00e9tisme &#8211; Relais mondiaux : les enjeux de la comp\u00e9tition\",\"datePublished\":\"2021-04-29T06:30:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png\",\"keywords\":[\"Athl\u00e9tisme\",\"Jeux Olympiques\"],\"articleSection\":[\"Athl\u00e9tisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/\",\"name\":\"Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png\",\"datePublished\":\"2021-04-29T06:30:46+00:00\",\"description\":\"Les Mondiaux de relais ont lieu les 1er et 2 Mai prochains \u00e0 Chorzow (Pologne). L'\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png\",\"width\":800,\"height\":445,\"caption\":\"Athl\u00e9tisme - Relais mondiaux - Les enjeux de la comp\u00e9tition\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Athl\u00e9tisme &#8211; Relais mondiaux : les enjeux de la comp\u00e9tition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\",\"name\":\"Roxane Lecacher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"caption\":\"Roxane Lecacher\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.\",\"sameAs\":[\"https:\/\/www.facebook.com\/roxane.lecacher\",\"https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition","description":"Les Mondiaux de relais ont lieu les 1er et 2 Mai prochains \u00e0 Chorzow (Pologne). L'\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/","og_locale":"fr_FR","og_type":"article","og_title":"Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition","og_description":"Les Mondiaux de relais ont lieu les 1er et 2 Mai prochains \u00e0 Chorzow (Pologne). L'\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs.","og_url":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/roxane.lecacher","article_published_time":"2021-04-29T06:30:46+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png","type":"image\/png"}],"author":"Roxane Lecacher","twitter_card":"summary_large_image","twitter_title":"Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/"},"author":{"name":"Roxane Lecacher","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a"},"headline":"Athl\u00e9tisme &#8211; Relais mondiaux : les enjeux de la comp\u00e9tition","datePublished":"2021-04-29T06:30:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png","keywords":["Athl\u00e9tisme","Jeux Olympiques"],"articleSection":["Athl\u00e9tisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/","url":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/","name":"Athl\u00e9tisme - Relais mondiaux : les enjeux de la comp\u00e9tition","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png","datePublished":"2021-04-29T06:30:46+00:00","description":"Les Mondiaux de relais ont lieu les 1er et 2 Mai prochains \u00e0 Chorzow (Pologne). L'\u00e9quipe de France a engag\u00e9 plusieurs \u00e9quipes, avec diff\u00e9rents objectifs.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Athletisme-Relais-mondiaux-Les-enjeux-de-la-competition.png","width":800,"height":445,"caption":"Athl\u00e9tisme - Relais mondiaux - Les enjeux de la comp\u00e9tition"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-relais-mondiaux-les-enjeux-de-la-competition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Athl\u00e9tisme &#8211; Relais mondiaux : les enjeux de la comp\u00e9tition"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a","name":"Roxane Lecacher","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","caption":"Roxane Lecacher"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.","sameAs":["https:\/\/www.facebook.com\/roxane.lecacher","https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b"],"url":"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/124859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=124859"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/124859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/125390"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=124859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=124859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=124859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}