{"id":12497,"date":"2018-02-12T11:42:18","date_gmt":"2018-02-12T10:42:18","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=12497"},"modified":"2018-02-12T11:58:29","modified_gmt":"2018-02-12T10:58:29","slug":"jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/","title":{"rendered":"JO 2018 &#8211; Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Apr\u00e8s un sprint remport\u00e9 de main de ma\u00eetre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendez-vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l&rsquo;Allemande.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Sur le premier tir Laura Dahlmeier assure avec un sans-faute pour repartir en t\u00eate. Anastasia Kuzmina et Justine Braisaz font les bonnes op\u00e9rations avec leur sans-fautes qui leur permettent de sortir 3\u00e8me et 5\u00e8me sur le\u00a0pas de tir. Ana\u00efs Bescond fait le plein aussi alors que Marie Dorin-Habert, 2 fautes, et Ana\u00efs Chevalier, 3 fautes, ratent leur d\u00e9but de course.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;Allemande qui arrive en t\u00eate au deuxi\u00e8me tir, r\u00e9alise une faute, tout comme Kuzmina, mais les deux biathl\u00e8tes ressortent en t\u00eate. Braisaz craque et r\u00e9alise 2 fautes pendant que Bescond et Dorin font un sans-faute pour ressortir en 4\u00e8me et 7\u00e8me position.<\/p>\n<p style=\"text-align: justify;\">Kuzmina et\u00a0Dahlmeier, tr\u00e8s rapides sur les skis, arrivent ensemble au premier tir debout. Si la Slovaque craque, avec 2 fautes, l&rsquo;Allemande fait le sans-faute et s&rsquo;envole vers la victoire. Ana\u00efs Bescond, 1 faute, ressort en quatri\u00e8me position derri\u00e8re Kuzmina et Vitkova !<\/p>\n<p style=\"text-align: justify;\">Laura Dahlmeier, sans-faute sur le dernier tir, va remporter cette poursuite sans trembler. Kuzmina, 1 faute, ressort au coude \u00e0 coude avec Bescond, sans faute, pour l&rsquo;argent. Dans un dernier tour dantesque, la Fran\u00e7aise s&rsquo;est accroch\u00e9e pour \u00e9chouer au sprint face \u00e0 la Slovaque. Super m\u00e9daille de bronze pour la Fran\u00e7aise partie 19\u00e8me.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Nicolas Jacquemard<\/strong><br \/>\n<\/em><a style=\"color: #000000;\" href=\"https:\/\/twitter.com\/Nico_Jacquemard\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"color: #000000;\" href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s un sprint remport\u00e9 de main de maitre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendre vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l&rsquo;Allemande.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":12502,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2,2426,3588,2313],"tags":[2427,2936],"class_list":["post-12497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-biathlon","category-pyeongchang-2018","category-sports-dhiver","tag-biathlon","tag-braisaz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>JO 2018 - Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s un sprint remport\u00e9 de main de maitre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendre vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l&#039;Allemande.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JO 2018 - Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s un sprint remport\u00e9 de main de maitre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendre vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l&#039;Allemande.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-12T10:42:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-12T10:58:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/Anais-Bescond-bronze.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"JO 2018 &#8211; Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze\",\"datePublished\":\"2018-02-12T10:42:18+00:00\",\"dateModified\":\"2018-02-12T10:58:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/\"},\"wordCount\":260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Anais-Bescond-bronze.png\",\"keywords\":[\"Biathlon\",\"braisaz\"],\"articleSection\":[\"Actualit\u00e9s\",\"Biathlon\",\"Pyeongchang 2018\",\"Sports d'hiver\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/\",\"name\":\"JO 2018 - Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Anais-Bescond-bronze.png\",\"datePublished\":\"2018-02-12T10:42:18+00:00\",\"dateModified\":\"2018-02-12T10:58:29+00:00\",\"description\":\"Apr\u00e8s un sprint remport\u00e9 de main de maitre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendre vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l'Allemande.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Anais-Bescond-bronze.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Anais-Bescond-bronze.png\",\"width\":800,\"height\":445,\"caption\":\"Anais Bescond bronze\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JO 2018 &#8211; Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JO 2018 - Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze","description":"Apr\u00e8s un sprint remport\u00e9 de main de maitre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendre vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l'Allemande.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/","og_locale":"fr_FR","og_type":"article","og_title":"JO 2018 - Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze","og_description":"Apr\u00e8s un sprint remport\u00e9 de main de maitre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendre vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l'Allemande.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2018-02-12T10:42:18+00:00","article_modified_time":"2018-02-12T10:58:29+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/Anais-Bescond-bronze.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"JO 2018 &#8211; Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze","datePublished":"2018-02-12T10:42:18+00:00","dateModified":"2018-02-12T10:58:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/"},"wordCount":260,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/Anais-Bescond-bronze.png","keywords":["Biathlon","braisaz"],"articleSection":["Actualit\u00e9s","Biathlon","Pyeongchang 2018","Sports d'hiver"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/","url":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/","name":"JO 2018 - Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/Anais-Bescond-bronze.png","datePublished":"2018-02-12T10:42:18+00:00","dateModified":"2018-02-12T10:58:29+00:00","description":"Apr\u00e8s un sprint remport\u00e9 de main de maitre par Laura Dahlmeier, les meilleures biathl\u00e8tes f\u00e9minines avaient rendre vous sur la poursuite pour tenter de d\u00e9tr\u00f4ner l'Allemande.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/Anais-Bescond-bronze.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/Anais-Bescond-bronze.png","width":800,"height":445,"caption":"Anais Bescond bronze"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-biathlon-poursuite-dahlmeier-reine-bescond-bronze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"JO 2018 &#8211; Biathlon (Poursuite F) : Dahlmeier est la reine, Bescond en bronze"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/12497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=12497"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/12497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/12502"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=12497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=12497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=12497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}