{"id":126291,"date":"2021-05-02T10:50:51","date_gmt":"2021-05-02T08:50:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=126291&#038;preview=true&#038;preview_id=126291"},"modified":"2021-05-02T10:50:51","modified_gmt":"2021-05-02T08:50:51","slug":"boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/","title":{"rendered":"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><i>BOXE POIDS LOURDS &#8211; Pour son premier combat depuis plus d&rsquo;un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.<\/i><\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/boxe-le-grand-retour-andy-ruiz-jr\/\">Changement payant<\/a> pour <strong>Andy Ruiz Jr<\/strong>. L&rsquo;ancien champion du monde a battu <strong>Cristobal Arreola<\/strong> aux points par d\u00e9cision unanime (117-110, 118-109, 118-109). N\u00e9anmoins, le combat a \u00e9t\u00e9 beaucoup plus disput\u00e9 que ce que les cartes des 3 juges laissent entendre. Bien qu&rsquo;\u00e9tant outsider, <strong>Chris Arreola<\/strong> a jou\u00e9 sa chance \u00e0 fond. Le v\u00e9t\u00e9ran a m\u00eame envoy\u00e9 Ruiz au tapis lors de la 2\u00e8me reprise sur une belle droite.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Andy Ruiz est mis knock-down au 2e round !! &#x1f92f; <a href=\"https:\/\/t.co\/WMw0ofrFh2\">pic.twitter.com\/WMw0ofrFh2<\/a><\/p>\n<p>\u2014 La Sueur (@lasueur_off) <a href=\"https:\/\/twitter.com\/lasueur_off\/status\/1388703294525214722?ref_src=twsrc%5Etfw\">May 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Malgr\u00e9 cette petite frayeur, <strong>Andy Ruiz Jr<\/strong> a continu\u00e9 \u00e0 d\u00e9rouler son gameplan. Et a acc\u00e9l\u00e9r\u00e9 au fil des rounds pour prendre l&rsquo;avantage.<\/p>\n<p style=\"text-align: justify;\">Plus petit que son adversaire, <strong>Ruiz<\/strong> n&rsquo;avait pas d&rsquo;autre choix que de le travailler de pr\u00e8s, en utilisant des combinaisons rapides pour lui faire mal. <i>The Destroyer<\/i> commen\u00e7ait souvent par toucher au corps, avant de remonter au visage. Un travail de sape payant. G\u00ean\u00e9 par la vitesse de bras de son adversaire,<strong> Arreola<\/strong> prenait beaucoup de coups sans pouvoir r\u00e9pliquer. Au final, le Mexicain aura port\u00e9 161 coups et en aura re\u00e7u 109. Dominateur la majorit\u00e9 du combat, Ruiz s&rsquo;est logiquement impos\u00e9 aux points et va pouvoir se projeter sur la suite.<\/p>\n<h2 style=\"text-align: justify;\">Vers une demi-finale mondiale face \u00e0 Wilder ?<\/h2>\n<p style=\"text-align: justify;\">Cette victoire permet \u00e0 l&rsquo;ancien champion de se replacer dans la course au titre. <a href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-la-date-du-choc-fury-joshua-est-quasiment-connue\/\">En attendant que <strong>Tyson Fury<\/strong> et <strong>Anthony Joshua<\/strong> ne r\u00e8glent leur compte cet \u00e9t\u00e9<\/a>, <strong>Andy Ruiz<\/strong> pourrait affronter <strong>Deontay Wilder<\/strong> dans le cadre d&rsquo;une demi-finale mondiale. Le gagnant affrontant ensuite le vainqueur du choc Fury-Joshua.<\/p>\n<p style=\"text-align: justify;\">Plus affut\u00e9 et motiv\u00e9 que jamais, Ruiz sera au prendre au s\u00e9rieux dans sa cat\u00e9gorie. N\u00e9anmoins, il faudra qu&rsquo;il am\u00e9liore sa garde pour esp\u00e9rer retrouver les sommets.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE POIDS LOURDS &#8211; Pour son premier combat depuis plus d&rsquo;un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.<\/p>\n","protected":false},"author":39,"featured_media":126306,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8672],"tags":[622,13179],"class_list":["post-126291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxe","tag-boxe-poids-lourds"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr<\/title>\n<meta name=\"description\" content=\"BOXE POIDS LOURDS - Pour son premier combat depuis plus d&#039;un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr\" \/>\n<meta property=\"og:description\" content=\"BOXE POIDS LOURDS - Pour son premier combat depuis plus d&#039;un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-02T08:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Idriss Ahamada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/idriss_ia7\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/\"},\"author\":{\"name\":\"Idriss Ahamada\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f3797823174b5e2975b9efe0302f16f4\"},\"headline\":\"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr\",\"datePublished\":\"2021-05-02T08:50:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/\"},\"wordCount\":343,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png\",\"keywords\":[\"boxe\",\"boxe poids lourds\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/\",\"name\":\"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png\",\"datePublished\":\"2021-05-02T08:50:51+00:00\",\"description\":\"BOXE POIDS LOURDS - Pour son premier combat depuis plus d'un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png\",\"width\":800,\"height\":445,\"caption\":\"Boxe poids lourds - Retour gagnant pour Andy Ruiz Jr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/f3797823174b5e2975b9efe0302f16f4\",\"name\":\"Idriss Ahamada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Maillot-Idriss-Dicodusport-150x150.png\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Maillot-Idriss-Dicodusport-150x150.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Maillot-Idriss-Dicodusport-150x150.png\",\"caption\":\"Idriss Ahamada\"},\"description\":\"Passionn\u00e9 de sport depuis toujours, c\u2019est tout naturellement qu\u2019apr\u00e8s avoir compris que je n\u2019avais pas le niveau pour jouer \u00e0 Manchester United, et pas la force n\u00e9cessaire pour combattre \u00e0 l\u2019UFC que je me suis tourn\u00e9 vers le journalisme pour raconter les exploits et les histoires de ceux qui en sont capables. Le football, surtout quand il est jou\u00e9 en Angleterre, reste mon premier amour. Mais j\u2019aime aussi veiller la nuit pour vous parler de KO et de victoires unanimes \u00e0 l\u2019UFC ou sur les rings de boxe. Mon c\u00f4t\u00e9 fan de Wayne Rooney m\u2019a \u00e9galement pouss\u00e9 \u00e0 devenir polyvalent et \u00e0 parler aussi de rugby (\u00e0 XIII comme \u00e0 XV) et occasionnellement de cyclisme. C\u2019est donc logiquement que j\u2019ai rejoint Dicodusport, pour pouvoir parler de l\u2019actualit\u00e9, sur tous les terrains.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/idriss_ia7\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/idriss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr","description":"BOXE POIDS LOURDS - Pour son premier combat depuis plus d'un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/","og_locale":"fr_FR","og_type":"article","og_title":"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr","og_description":"BOXE POIDS LOURDS - Pour son premier combat depuis plus d'un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.","og_url":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-05-02T08:50:51+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png","type":"image\/png"}],"author":"Idriss Ahamada","twitter_card":"summary_large_image","twitter_title":"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr","twitter_creator":"@https:\/\/twitter.com\/idriss_ia7","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/"},"author":{"name":"Idriss Ahamada","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/f3797823174b5e2975b9efe0302f16f4"},"headline":"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr","datePublished":"2021-05-02T08:50:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/"},"wordCount":343,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png","keywords":["boxe","boxe poids lourds"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/","url":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/","name":"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png","datePublished":"2021-05-02T08:50:51+00:00","description":"BOXE POIDS LOURDS - Pour son premier combat depuis plus d'un an, Andy Ruiz Jr est revenu des enfers pour vaincre Cristobal Arreola aux points.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Boxe-poids-lourds-Retour-gagnant-pour-Andy-Ruiz-Jr.png","width":800,"height":445,"caption":"Boxe poids lourds - Retour gagnant pour Andy Ruiz Jr"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-retour-gagnant-pour-andy-ruiz-jr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Boxe poids lourds : Retour gagnant pour Andy Ruiz Jr"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/f3797823174b5e2975b9efe0302f16f4","name":"Idriss Ahamada","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Idriss-Dicodusport-150x150.png","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Idriss-Dicodusport-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Idriss-Dicodusport-150x150.png","caption":"Idriss Ahamada"},"description":"Passionn\u00e9 de sport depuis toujours, c\u2019est tout naturellement qu\u2019apr\u00e8s avoir compris que je n\u2019avais pas le niveau pour jouer \u00e0 Manchester United, et pas la force n\u00e9cessaire pour combattre \u00e0 l\u2019UFC que je me suis tourn\u00e9 vers le journalisme pour raconter les exploits et les histoires de ceux qui en sont capables. Le football, surtout quand il est jou\u00e9 en Angleterre, reste mon premier amour. Mais j\u2019aime aussi veiller la nuit pour vous parler de KO et de victoires unanimes \u00e0 l\u2019UFC ou sur les rings de boxe. Mon c\u00f4t\u00e9 fan de Wayne Rooney m\u2019a \u00e9galement pouss\u00e9 \u00e0 devenir polyvalent et \u00e0 parler aussi de rugby (\u00e0 XIII comme \u00e0 XV) et occasionnellement de cyclisme. C\u2019est donc logiquement que j\u2019ai rejoint Dicodusport, pour pouvoir parler de l\u2019actualit\u00e9, sur tous les terrains.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/idriss_ia7"],"url":"https:\/\/dicodusport.fr\/blog\/author\/idriss\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/126291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=126291"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/126291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/126306"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=126291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=126291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=126291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}