{"id":126720,"date":"2021-05-03T18:42:44","date_gmt":"2021-05-03T16:42:44","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=126720&#038;preview=true&#038;preview_id=126720"},"modified":"2021-10-18T16:27:16","modified_gmt":"2021-10-18T14:27:16","slug":"xv-de-france-programme-tournee-automne-connu","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/","title":{"rendered":"XV de France : le programme de la tourn\u00e9e d&rsquo;automne est connu"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/tag\/xv-de-france\/\">XV DE FRANCE<\/a> &#8211; Selon les informations de RMC Sport, l&rsquo;\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l&rsquo;automne 2021, avec en point d&rsquo;orgue, la Nouvelle-Z\u00e9lande.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">On le sait d\u00e9sormais, les Bleus se d\u00e9placeront bien en Australie en juillet prochain. Ils y disputeront trois matchs face aux Wallabies, les 7, 13 et 17 juillet. Et selon nos confr\u00e8res de <a href=\"https:\/\/rmcsport.bfmtv.com\/rugby\/xv-de-france-l-argentine-la-georgie-et-la-nouvelle-zelande-en-novembre_AV-202105030312.html?\" rel=\"nofollow\"><em>RMC Sport<\/em><\/a>, le programme de la tourn\u00e9e d&rsquo;automne semble \u00e9galement act\u00e9. L&rsquo;\u00e9quipe de France devrait affronter l&rsquo;<strong>Argentine<\/strong> au Stade de France, le 6 novembre. La semaine suivante (13 novembre), Fabien Galthi\u00e9 et ses troupes d\u00e9fieront la <strong>G\u00e9orgie<\/strong> \u00e0 Bordeaux. Enfin, <a href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-un-match-a-domicile-face-aux-all-blacks-en-2021\/\">comme cela \u00e9tait pressenti depuis de nombreuses semaines<\/a>, le <strong>XV de France<\/strong> livrera une belle bataille face aux <strong>All Blacks<\/strong> au Stade de France, le 20 novembre.<\/p>\n<p style=\"text-align: justify;\">Pour rappel, les trois derni\u00e8res rencontres des Bleus face \u00e0 la Nouvelle-Z\u00e9lande remontent \u00e0 l&rsquo;\u00e9t\u00e9 2018 : l&rsquo;\u00e9quipe de France, alors men\u00e9e par Jacques Brunel, avait conc\u00e9d\u00e9 trois d\u00e9faites (52-11, 26-13 et 49-14).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">XV de France: l\u2019Argentine, la G\u00e9orgie et la Nouvelle-Z\u00e9lande en novembre <a href=\"https:\/\/t.co\/rguQJR5CEN\">https:\/\/t.co\/rguQJR5CEN<\/a> via <a href=\"https:\/\/twitter.com\/RMCsport?ref_src=twsrc%5Etfw\">@RMCsport<\/a> <a href=\"https:\/\/twitter.com\/JFPaturaud?ref_src=twsrc%5Etfw\">@JFPaturaud<\/a><\/p>\n<p>\u2014 Wilfried Templier (@WilTemplier) <a href=\"https:\/\/twitter.com\/WilTemplier\/status\/1389242496396431364?ref_src=twsrc%5Etfw\">May 3, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV DE FRANCE &#8211; Selon les informations de RMC Sport, l&rsquo;\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l&rsquo;automne 2021, avec en point d&rsquo;orgue, la Nouvelle-Z\u00e9lande.<\/p>\n","protected":false},"author":4,"featured_media":115316,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,19951],"tags":[13,24,6016,1638],"class_list":["post-126720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-rugby","tag-sport","tag-tournee-dautomne","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>XV de France : le programme de la tourn\u00e9e d&#039;automne est connu<\/title>\n<meta name=\"description\" content=\"XV DE FRANCE - Selon les informations de RMC Sport, l&#039;\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l&#039;automne 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France : le programme de la tourn\u00e9e d&#039;automne est connu\" \/>\n<meta property=\"og:description\" content=\"XV DE FRANCE - Selon les informations de RMC Sport, l&#039;\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l&#039;automne 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T16:42:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T14:27:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France : le programme de la tourn\u00e9e d&#039;automne est connu\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"XV de France : le programme de la tourn\u00e9e d&rsquo;automne est connu\",\"datePublished\":\"2021-05-03T16:42:44+00:00\",\"dateModified\":\"2021-10-18T14:27:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/\"},\"wordCount\":210,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png\",\"keywords\":[\"Rugby\",\"sport\",\"tourn\u00e9e d'automne\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/\",\"name\":\"XV de France : le programme de la tourn\u00e9e d'automne est connu\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png\",\"datePublished\":\"2021-05-03T16:42:44+00:00\",\"dateModified\":\"2021-10-18T14:27:16+00:00\",\"description\":\"XV DE FRANCE - Selon les informations de RMC Sport, l'\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l'automne 2021.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png\",\"width\":800,\"height\":445,\"caption\":\"XV de France : le programme de la tourn\u00e9e d'automne est connu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XV de France : le programme de la tourn\u00e9e d&rsquo;automne est connu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France : le programme de la tourn\u00e9e d'automne est connu","description":"XV DE FRANCE - Selon les informations de RMC Sport, l'\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l'automne 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France : le programme de la tourn\u00e9e d'automne est connu","og_description":"XV DE FRANCE - Selon les informations de RMC Sport, l'\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l'automne 2021.","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-05-03T16:42:44+00:00","article_modified_time":"2021-10-18T14:27:16+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"XV de France : le programme de la tourn\u00e9e d'automne est connu","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"XV de France : le programme de la tourn\u00e9e d&rsquo;automne est connu","datePublished":"2021-05-03T16:42:44+00:00","dateModified":"2021-10-18T14:27:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/"},"wordCount":210,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png","keywords":["Rugby","sport","tourn\u00e9e d'automne","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/","name":"XV de France : le programme de la tourn\u00e9e d'automne est connu","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png","datePublished":"2021-05-03T16:42:44+00:00","dateModified":"2021-10-18T14:27:16+00:00","description":"XV DE FRANCE - Selon les informations de RMC Sport, l'\u00e9quipe de France dirig\u00e9e par Fabien Galthi\u00e9 disputera bien trois matchs \u00e0 l'automne 2021.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/03\/Bleus-Les-notes-du-XV-de-France-face-au-Pays-de-Galles.png","width":800,"height":445,"caption":"XV de France : le programme de la tourn\u00e9e d'automne est connu"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-programme-tournee-automne-connu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"XV de France : le programme de la tourn\u00e9e d&rsquo;automne est connu"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/126720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=126720"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/126720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/115316"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=126720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=126720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=126720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}