{"id":129251,"date":"2021-05-14T08:00:37","date_gmt":"2021-05-14T06:00:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=129251"},"modified":"2021-05-13T21:52:09","modified_gmt":"2021-05-13T19:52:09","slug":"14-mai-1900-les-jeux-olympiques-a-paris","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/","title":{"rendered":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Si Pierre de Coubertin est parvenu \u00e0 faire venir les seconds Jeux Olympiques de l\u2019<a href=\"https:\/\/dicodusport.fr\/blog\/6-avril-1896-premiers-jeux-olympiques-de-lere-moderne\/\">\u00e8re moderne<\/a> en France, tout ne s\u2019est pas particuli\u00e8rement bien pass\u00e9. Dicodusport revient sur cette \u00e9dition plut\u00f4t particuli\u00e8re de Paris 1900.<\/strong> <\/em><\/p>\n<h2 style=\"text-align: justify;\">\u00c7a s&rsquo;est pass\u00e9 le 14 mai 1900<\/h2>\n<p style=\"text-align: justify;\">Quel capharna\u00fcm ! \u00a0En voulant faire co\u00efncider les <strong>Jeux Olympiques<\/strong> avec l\u2019<strong>Exposition Universelle<\/strong>, le CIO a eu l\u00e0 une bien mauvaise id\u00e9e. Alors oui, financi\u00e8rement c\u2019est mieux, niveau organisation c\u2019est autre chose. Premi\u00e8rement, \u00e7a a \u00e9tal\u00e9 les \u00e9preuves sur cinq mois -entre mai et octobre- mais celles-ci \u00e9taient perdues parmi d\u2019autres comp\u00e9titions annuelles. Difficile de faire le tri entre m\u00e9daill\u00e9s olympiques ou non. De plus, m\u00e9diatiquement, l\u2019\u00e9v\u00e9nement n\u2019a pas du tout pris, faute de promotion \u00e9galement. Pas de c\u00e9r\u00e9monie d\u2019ouverture, les affiches publicitaires n\u2019annoncent aucunement les JO mais des \u00ab concours internationaux \u00bb. Pas \u00e9tonnant donc que les spectateurs soient peu nombreux, surtout que politiquement, la comp\u00e9tition n&rsquo;attire pas non plus. Et que dire des sites qu\u2019il aurait fallu am\u00e9nager \u2026 une histoire de sous encore.<\/p>\n<p style=\"text-align: justify;\">Pourtant, il y a des choses \u00e0 garder de cette premi\u00e8re \u00e9dition fran\u00e7aise, notamment l\u2019apparition des femmes dans les Jeux Olympiques. Ainsi, la Britannique <strong>Charlotte Cooper<\/strong> devient la premi\u00e8re championne olympique de tennis. L\u2019Am\u00e9ricaine <strong>Margaret Abbott<\/strong> s\u2019impose de son c\u00f4t\u00e9 en golf. Parall\u00e8lement, des \u00e9quipes mixtes de voile, \u00e9quitation et croquet sont aussi organis\u00e9es. De plus, ce sera la seule et unique fois o\u00f9 la France arrivera en t\u00eate du classement olympique, si on peut appeler \u00e7a un classement officiel, les m\u00e9dailles olympiques voyant le jour quatre ans plus tard. Bon, l\u2019\u00e9quipe de France repr\u00e9sentait la moiti\u00e9 des athl\u00e8tes, mais prenons le verre \u00e0 moiti\u00e9 plein. Individuellement, c\u2019est <strong>Alvin Kraenzlein<\/strong> qui a brill\u00e9. L\u2019Am\u00e9ricain a d\u00e9croch\u00e9 pas moins de quatre sacres en athl\u00e9tisme, s\u2019imposant sur le sprint du 60m mais aussi sur 110 et 200 m haies et compl\u00e9tant avec le saut en longueur. Bien que ces Jeux aient connu un flop, il n\u2019y a pas eu que des mauvaises choses. Et puis, il \u00e9tait toujours possible de faire mieux en 1924. Quoi que \u2026 En 2024 alors ? Patientons, concentrons-nous d\u00e9j\u00e0 sur Tokyo, il reste 70 jours. 70 jours !<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: Avec l\u2019organisation des Jeux 2024, Paris arrive dans le club ferm\u00e9 des villes ayant accueilli la comp\u00e9tition \u00e0 trois reprises. Londres y figurait depuis 2012, Los Angeles y entrera en 2028.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 14 mai 1900, la premi\u00e8re \u00e9dition des Jeux Olympiques de Paris d\u00e9butait. Retour sur cette comp\u00e9tition &#8230; relativement particuli\u00e8re.<\/p>\n","protected":false},"author":18,"featured_media":129367,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8,2366],"tags":[161],"class_list":["post-129251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-multisports","tag-jeux-olympiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>14 mai 1900 : Les Jeux Olympiques \u00e0 Paris<\/title>\n<meta name=\"description\" content=\"Le 14 mai 1900, la premi\u00e8re \u00e9dition des Jeux Olympiques de Paris d\u00e9butait. Retour sur cette comp\u00e9tition ... relativement particuli\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris\" \/>\n<meta property=\"og:description\" content=\"Le 14 mai 1900, la premi\u00e8re \u00e9dition des Jeux Olympiques de Paris d\u00e9butait. Retour sur cette comp\u00e9tition ... relativement particuli\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-14T06:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris\",\"datePublished\":\"2021-05-14T06:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/\"},\"wordCount\":430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png\",\"keywords\":[\"Jeux Olympiques\"],\"articleSection\":[\"Histoire\",\"Multisports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/\",\"name\":\"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png\",\"datePublished\":\"2021-05-14T06:00:37+00:00\",\"description\":\"Le 14 mai 1900, la premi\u00e8re \u00e9dition des Jeux Olympiques de Paris d\u00e9butait. Retour sur cette comp\u00e9tition ... relativement particuli\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png\",\"width\":800,\"height\":445,\"caption\":\"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris","description":"Le 14 mai 1900, la premi\u00e8re \u00e9dition des Jeux Olympiques de Paris d\u00e9butait. Retour sur cette comp\u00e9tition ... relativement particuli\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/","og_locale":"fr_FR","og_type":"article","og_title":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris","og_description":"Le 14 mai 1900, la premi\u00e8re \u00e9dition des Jeux Olympiques de Paris d\u00e9butait. Retour sur cette comp\u00e9tition ... relativement particuli\u00e8re.","og_url":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-05-14T06:00:37+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris","datePublished":"2021-05-14T06:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/"},"wordCount":430,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png","keywords":["Jeux Olympiques"],"articleSection":["Histoire","Multisports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/","url":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/","name":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png","datePublished":"2021-05-14T06:00:37+00:00","description":"Le 14 mai 1900, la premi\u00e8re \u00e9dition des Jeux Olympiques de Paris d\u00e9butait. Retour sur cette comp\u00e9tition ... relativement particuli\u00e8re.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/14-mai-1900-Les-Jeux-Olympiques-a-Paris.png","width":800,"height":445,"caption":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/14-mai-1900-les-jeux-olympiques-a-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"14 mai 1900 : Les Jeux Olympiques \u00e0 Paris"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/129251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=129251"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/129251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/129367"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=129251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=129251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=129251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}