{"id":129845,"date":"2021-05-15T20:47:11","date_gmt":"2021-05-15T18:47:11","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=129845&#038;preview=true&#038;preview_id=129845"},"modified":"2021-05-15T20:47:11","modified_gmt":"2021-05-15T18:47:11","slug":"pronostic-lille-saint-etienne-37eme-journee-de-ligue-1","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/","title":{"rendered":"Pronostic Lille &#8211; Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-ligue-1-2020-2021-37eme-journee-programme-et-resultats\/\" target=\"_blank\" rel=\"noopener\"><strong>LIGUE 1 &#8211; 37\u00c8ME JOURN\u00c9E<\/strong><\/a><b> &#8211; Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Pronostic Lille &#8211; Saint-\u00c9tienne : Dimanche 16 mai, 21h00<\/h2>\n<p style=\"text-align: justify;\"><strong>Lille<\/strong> peut faire un nouveau grand pas vers le titre puisqu&rsquo;il faut que les Nordistes prennent quatre points sur leurs deux derniers matchs pour \u00eatre sacr\u00e9s champions. <strong>Saint-\u00c9tienne<\/strong> est de son c\u00f4t\u00e9 sauv\u00e9 gr\u00e2ce \u00e0 ses derni\u00e8res victoires et peut finir la saison en roue libre. On ne voit pas Lille faire autre chose que gagner mais comme la cote n&rsquo;est pas tr\u00e8s int\u00e9ressante, on part sur un but de l&rsquo;homme en forme, <strong>Burak Yilmaz<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; height: 23px; vertical-align: middle; width: 550px;\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 16 mai, 21h00<\/span><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; text-align: center; vertical-align: middle; width: 250px;\"><span style=\"font-size: 12px; color: #ffffff;\">Buteur<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; height: 47px; width: 550px;\"><strong>Burak Yilmaz<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; height: 47px; text-align: center; vertical-align: middle; width: 250px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22651059?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d8ac7;border-radius:5px;text-shadow:none\"> 2.05<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 &#8211; 37\u00c8ME JOURN\u00c9E &#8211; Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.<\/p>\n","protected":false},"author":1,"featured_media":129890,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[75,1554,451,4949,457],"class_list":["post-129845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-football","tag-ligue-1","tag-lille","tag-pronostics","tag-saint-etienne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1 - Dicodusport<\/title>\n<meta name=\"description\" content=\"LIGUE 1 - 37\u00c8ME JOURN\u00c9E - Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 - 37\u00c8ME JOURN\u00c9E - Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-15T18:47:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Pronostic Lille &#8211; Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1\",\"datePublished\":\"2021-05-15T18:47:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/\"},\"wordCount\":168,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png\",\"keywords\":[\"Football\",\"Ligue 1\",\"Lille\",\"Pronostics\",\"Saint-Etienne\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/\",\"name\":\"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1 - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png\",\"datePublished\":\"2021-05-15T18:47:11+00:00\",\"description\":\"LIGUE 1 - 37\u00c8ME JOURN\u00c9E - Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png\",\"width\":1200,\"height\":670,\"caption\":\"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronostic Lille &#8211; Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1 - Dicodusport","description":"LIGUE 1 - 37\u00c8ME JOURN\u00c9E - Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/","og_locale":"fr_FR","og_type":"article","og_title":"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1","og_description":"LIGUE 1 - 37\u00c8ME JOURN\u00c9E - Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","og_url":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-05-15T18:47:11+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Pronostic Lille &#8211; Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1","datePublished":"2021-05-15T18:47:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/"},"wordCount":168,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png","keywords":["Football","Ligue 1","Lille","Pronostics","Saint-Etienne"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/","url":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/","name":"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1 - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png","datePublished":"2021-05-15T18:47:11+00:00","description":"LIGUE 1 - 37\u00c8ME JOURN\u00c9E - Lille accueille Saint-\u00c9tienne dans le cadre de la 37\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Pronostic-Lille-Saint-Etienne-37eme-journee-de-Ligue-1.png","width":1200,"height":670,"caption":"Pronostic Lille - Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-lille-saint-etienne-37eme-journee-de-ligue-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pronostic Lille &#8211; Saint-\u00c9tienne, 37\u00e8me journ\u00e9e de Ligue 1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/129845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=129845"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/129845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/129890"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=129845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=129845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=129845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}