{"id":130995,"date":"2021-05-19T23:09:46","date_gmt":"2021-05-19T21:09:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=130995"},"modified":"2021-05-19T23:37:04","modified_gmt":"2021-05-19T21:37:04","slug":"le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/","title":{"rendered":"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>COUPE DE FRANCE &#8211; Dans un match tr\u00e8s ferm\u00e9 o\u00f9 les deux \u00e9quipes se sont cr\u00e9\u00e9es peu de situations, les joueurs de la capitale sont sortis vainqueurs gr\u00e2ce \u00e0 une efficacit\u00e9 clinique. Icardi a ouvert le score en premi\u00e8re p\u00e9riode et Mbapp\u00e9 a marqu\u00e9 le but du break en fin de match. Pochettino tient son premier troph\u00e9e.\u00a0\u00a0<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\"><strong>Une ouverture du score offerte par Monaco dans un premier acte insipide<\/strong><\/h2>\n<p style=\"text-align: justify;\">Le d\u00e9but de rencontre a \u00e9t\u00e9 domin\u00e9 par les Parisiens qui ont pris le jeu \u00e0 leur compte en laissant tr\u00e8s peu de ballons \u00e0 leur adversaire. Cette ma\u00eetrise du cuir reste assez st\u00e9rile, les joueurs de Pochettino \u00e9tant incapables de cr\u00e9er du danger. Ils b\u00e9n\u00e9ficient m\u00eame d\u2019un cadeau d\u2019<strong>Axel Disasi<\/strong> pour ouvrir le score. Le d\u00e9fenseur du Rocher laisse \u00e9chapper le ballon et permet \u00e0<strong> Kylian Mbapp\u00e9<\/strong> de se pr\u00e9senter face \u00e0 <strong>Radoslaw Majecki<\/strong>. L\u2019attaquant de la capitale fait le bon choix en d\u00e9calant <strong>Mauro Icardi<\/strong> qui marque dans le but vide (20e).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x26bd;&#x1f3c6; Le PSG ouvre le score ! Kylian Mbapp\u00e9 profite d&rsquo;une grosse erreur d&rsquo;Axel Disasi et sert Mauro Icardi qui marque dans le but vide ! <a href=\"https:\/\/twitter.com\/hashtag\/ASMPSG?src=hash&amp;ref_src=twsrc%5Etfw\">#ASMPSG<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/CDF?src=hash&amp;ref_src=twsrc%5Etfw\">#CDF<\/a><\/p>\n<p>&#x25b6; Suivez la finale de la Coupe de France en direct : <a href=\"https:\/\/t.co\/qkRFVGabaW\">https:\/\/t.co\/qkRFVGabaW<\/a> <a href=\"https:\/\/t.co\/LUhcegqNon\">pic.twitter.com\/LUhcegqNon<\/a><\/p>\n<p>\u2014 France tv sport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1395102863215452171?ref_src=twsrc%5Etfw\">May 19, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">La seule v\u00e9ritable occasion cr\u00e9\u00e9e par les Parisiens fait suite \u00e0 un beau mouvement se terminant par une frappe d\u2019<strong>Alessandro Florenzi<\/strong> d\u00e9vi\u00e9e en corner par le portier adverse (33e). Cette tentative fait suite au bon d\u00e9calage d\u2019Angel Di Maria. Du c\u00f4t\u00e9 Mon\u00e9gasque, pas grand chose \u00e0 signaler mis \u00e0 part ce frisson sur la cage de Navas sur un coup franc excentr\u00e9 que<strong> Maripan<\/strong> et <strong>Disasi<\/strong> ne peuvent reprendre (37e). Les Parisiens rentrent aux vestiaires avec un avantage d\u2019un but.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Monaco r\u00e9agit trop tard et se fait punir<\/strong><\/h2>\n<p style=\"text-align: justify;\">La seconde p\u00e9riode d\u00e9marre sur les m\u00eames bases, les Parisiens se contentant de g\u00e9rer leur avantage et les Mon\u00e9gasques \u00e9tant incapables de se montrer dangereux. Ainsi passent 25 minutes sans situations dangereuses. <strong>Nico Kovac<\/strong> tente alors de remanier son \u00e9quipe, avec les bonnes entr\u00e9es de <strong>Diatta<\/strong>, <strong>Jovetic<\/strong> et surtout <strong>Gelson Martins<\/strong>. Ce dernier est d\u2019ailleurs \u00e0 l\u2019origine du r\u00e9veil des siens avec un centre tir qui s\u2019\u00e9crase sur la transversale de Navas (69e). Deux minutes plus tard, \u00e0 la suite d\u2019un centre d\u2019<strong>Aur\u00e9lien Tchouam\u00e9ni<\/strong>, Jovetic prend sa chance mais sa tentative est contr\u00e9e et revient sur <strong>Axel Disasi<\/strong>. Ce dernier frappe mais le portier adverse capte le ballon. Les Mon\u00e9gasques ne trouveront plus d\u2019ouvertures dans une d\u00e9fense parisienne bien en place.<\/p>\n<p style=\"text-align: justify;\">Kylian Mbapp\u00e9 manque ensuite de r\u00e9ussite sur un lob des trente m\u00e8tres qui trouve la barre (80e). L\u2019international tricolore scellera finalement le sort de la rencontre une minute apr\u00e8s, suite \u00e0 une excellente passe de <strong>Di Maria<\/strong> (2-0, 81e). Les joueurs de la capitale ont g\u00e9r\u00e9 leur avantage pour remporter leur quatorzi\u00e8me Coupe de France.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x26bd;&#x1f4aa; Kylian Mbapp\u00e9 inscrit le but du break ! D&rsquo;un subtil ballon piqu\u00e9, il rapproche le PSG du sacre en Coupe de France <a href=\"https:\/\/twitter.com\/hashtag\/ASMPSG?src=hash&amp;ref_src=twsrc%5Etfw\">#ASMPSG<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/CDF?src=hash&amp;ref_src=twsrc%5Etfw\">#CDF<\/a><\/p>\n<p>&#x25b6; Suivez la finale en direct : <a href=\"https:\/\/t.co\/qkRFVGabaW\">https:\/\/t.co\/qkRFVGabaW<\/a> <a href=\"https:\/\/t.co\/dPNTy0wPuB\">pic.twitter.com\/dPNTy0wPuB<\/a><\/p>\n<p>\u2014 France tv sport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1395123330403999749?ref_src=twsrc%5Etfw\">May 19, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-de-france-notes-monaco-psg\/\">Les notes de Monaco &#8211; PSG<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DE FRANCE &#8211; Dans un match tr\u00e8s ferm\u00e9 o\u00f9 les deux \u00e9quipes se sont cr\u00e9\u00e9es peu de situations, les joueurs de la capitale sont sortis vainqueurs gr\u00e2ce \u00e0 une efficacit\u00e9 clinique. Icardi a ouvert le score en premi\u00e8re p\u00e9riode et Mbapp\u00e9 a marqu\u00e9 le but du break en fin de match. Pochettino tient son premier troph\u00e9e.\u00a0\u00a0<\/p>\n","protected":false},"author":57,"featured_media":131001,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[2870,75,1678,910],"class_list":["post-130995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-coupe-de-france","tag-football","tag-monaco","tag-psg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco<\/title>\n<meta name=\"description\" content=\"COUPE DE FRANCE - Dans un match ferm\u00e9, le PSG a fait tomber l&#039;AS Monaco (0-2) et s&#039;offre une 14\u00e8me Coupe de France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco\" \/>\n<meta property=\"og:description\" content=\"COUPE DE FRANCE - Dans un match ferm\u00e9, le PSG a fait tomber l&#039;AS Monaco (0-2) et s&#039;offre une 14\u00e8me Coupe de France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-19T21:09:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-19T21:37:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Vincent Soubab\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/\"},\"author\":{\"name\":\"Vincent Soubab\u00e8re\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\"},\"headline\":\"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco\",\"datePublished\":\"2021-05-19T21:09:46+00:00\",\"dateModified\":\"2021-05-19T21:37:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/\"},\"wordCount\":597,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png\",\"keywords\":[\"Coupe de France\",\"Football\",\"Monaco\",\"PSG\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/\",\"name\":\"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png\",\"datePublished\":\"2021-05-19T21:09:46+00:00\",\"dateModified\":\"2021-05-19T21:37:04+00:00\",\"description\":\"COUPE DE FRANCE - Dans un match ferm\u00e9, le PSG a fait tomber l'AS Monaco (0-2) et s'offre une 14\u00e8me Coupe de France.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png\",\"width\":800,\"height\":445,\"caption\":\"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\",\"name\":\"Vincent Soubab\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"caption\":\"Vincent Soubab\u00e8re\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/vincents\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco","description":"COUPE DE FRANCE - Dans un match ferm\u00e9, le PSG a fait tomber l'AS Monaco (0-2) et s'offre une 14\u00e8me Coupe de France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/","og_locale":"fr_FR","og_type":"article","og_title":"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco","og_description":"COUPE DE FRANCE - Dans un match ferm\u00e9, le PSG a fait tomber l'AS Monaco (0-2) et s'offre une 14\u00e8me Coupe de France.","og_url":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-05-19T21:09:46+00:00","article_modified_time":"2021-05-19T21:37:04+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png","type":"image\/png"}],"author":"Vincent Soubab\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/"},"author":{"name":"Vincent Soubab\u00e8re","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b"},"headline":"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco","datePublished":"2021-05-19T21:09:46+00:00","dateModified":"2021-05-19T21:37:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/"},"wordCount":597,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png","keywords":["Coupe de France","Football","Monaco","PSG"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/","url":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/","name":"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png","datePublished":"2021-05-19T21:09:46+00:00","dateModified":"2021-05-19T21:37:04+00:00","description":"COUPE DE FRANCE - Dans un match ferm\u00e9, le PSG a fait tomber l'AS Monaco (0-2) et s'offre une 14\u00e8me Coupe de France.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Le-PSG-remporte-sa-14eme-Coupe-de-France-en-dominant-Monaco.png","width":800,"height":445,"caption":"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-psg-remporte-sa-14eme-coupe-de-france-en-dominant-monaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le PSG remporte sa 14\u00e8me Coupe de France en dominant Monaco"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b","name":"Vincent Soubab\u00e8re","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","caption":"Vincent Soubab\u00e8re"},"description":"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.","url":"https:\/\/dicodusport.fr\/blog\/author\/vincents\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/130995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=130995"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/130995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/131001"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=130995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=130995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=130995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}