{"id":131815,"date":"2021-05-22T11:59:04","date_gmt":"2021-05-22T09:59:04","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=131815"},"modified":"2021-05-22T19:44:46","modified_gmt":"2021-05-22T17:44:46","slug":"atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/","title":{"rendered":"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>ATP LYON &#8211; Dans une partie qui s\u2019est \u00e9tal\u00e9e sur deux jours \u00e0 cause de la pluie, Arthur Rinderknech a fini par c\u00e9der contre Cameron Norrie (6-3\/3-6\/6-3). Le Britannique affrontera Karen Khachanov en demi-finales.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">Un jeu de service rat\u00e9 qui co\u00fbte cher au Fran\u00e7ais<\/h2>\n<p style=\"text-align: justify;\">Bien rentr\u00e9 dans le match, <strong>Arthur Rinderknech<\/strong> n\u2019a pas saisi sa double opportunit\u00e9 de breaker son adversaire \u00e0 1-1, permettant \u00e0 Norrie de mener 2-1. Certainement d\u00e9\u00e7u, il est ensuite pass\u00e9 \u00e0 c\u00f4t\u00e9 de sa deuxi\u00e8me mise en jeu, conc\u00e9dant un break blanc et plusieurs fautes \u00e9vitables. Le Varois va pourtant montrer de la qualit\u00e9 sur ses trois autres jeux de service, ne laissant que deux points \u00e0 son adversaire.<\/p>\n<p style=\"text-align: justify;\">Appliqu\u00e9 sur ses engagements, il n\u2019a laiss\u00e9 aucune autre opportunit\u00e9 de break sur cette premi\u00e8re manche, preuve que cette seconde mise en jeu n\u2019\u00e9tait qu\u2019un accident. Malheureusement, il ne s&rsquo;est pas procur\u00e9 d\u2019autres balles de break &#8211; malgr\u00e9 plusieurs jeux serr\u00e9s sur le service du Britannique &#8211; et doit c\u00e9der la premi\u00e8re manche 6-4. Il devra faire moins de fautes directes en seconde manche pour esp\u00e9rer mieux.<\/p>\n<h2 style=\"text-align: justify;\">Une deuxi\u00e8me manche serr\u00e9e<\/h2>\n<p style=\"text-align: justify;\">Le Fran\u00e7ais repart sur les m\u00eames bases dans le second set, ne conc\u00e9dant pas le moindre point sur ses deux premi\u00e8res mises en jeu. <strong>Norrie<\/strong> est lui en difficult\u00e9 sur son engagement, mais s\u2019en sort sans conc\u00e9der de balle de break pour recoller d\u2019abord \u00e0 1-1 puis \u00e0 2-2. On croit alors que le local, men\u00e9 0-30, va r\u00e9\u00e9diter le m\u00eame jeu de service rat\u00e9 sur sa premi\u00e8re manche. Port\u00e9 par le public, il marque les quatre points suivants pour mener 3-2. Les deux joueurs remportent ensuite facilement leur mise en jeu, et c\u2019est finalement \u00e0 4-3 que le Fran\u00e7ais saisit la seule opportunit\u00e9 de break de la manche pour mener 5-3. Il conclut sur son service une seconde manche o\u00f9 il s\u2019est montr\u00e9 un peu plus r\u00e9gulier.<\/p>\n<h2 style=\"text-align: justify;\">Une coupure profitant au Britannique ?<\/h2>\n<p style=\"text-align: justify;\">C\u2019est alors que les spectateurs sortent les parapluies et on comprend que l\u2019avenir du match est compromis. <strong>Norrie<\/strong> remporte son jeu de service et se dirige vers l\u2019arbitre, lui demandant d\u2019arr\u00eater la partie. Ce dernier accepte sa demande apr\u00e8s avoir consult\u00e9 le Fran\u00e7ais. Le jeu devra attendre samedi 11 heures pour reprendre. Et malheureusement, apr\u00e8s un premier jeu de service ma\u00eetris\u00e9, le Fran\u00e7ais craque sur sa seconde mise en jeu, conc\u00e9dant deux balles de break.<\/p>\n<p style=\"text-align: justify;\">Le Britannique saisit la premi\u00e8re opportunit\u00e9 pour mener 3-1, puis 4-1. <strong>Rinderknech<\/strong> ne va pas l\u00e2cher, remportant son jeu de service mais derri\u00e8re, Norrie marque un jeu blanc. Le Varois s\u2019incline finalement 3-6 dans la derni\u00e8re manche, et ne verra pas les demi-finales. <strong>Norrie<\/strong> affrontera <strong>Khachanov<\/strong> pour une place en finale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Norrie stoppe Rinderknech<\/p>\n<p>Fin de l&rsquo;aventure \u00e0 Lyon pour Arthur Rinderknech, battu en deux jours par Cameron Norrie 6-3 3-6 6-3. Le Britannique rejoint Khachanov en demie <a href=\"https:\/\/t.co\/Fw03n1U3G2\">pic.twitter.com\/Fw03n1U3G2<\/a><\/p>\n<p>\u2014 We Are Tennis France (@WeAreTennisFR) <a href=\"https:\/\/twitter.com\/WeAreTennisFR\/status\/1396038070726807558?ref_src=twsrc%5Etfw\">May 22, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ATP LYON &#8211; Dans une partie qui s\u2019est \u00e9tal\u00e9e sur deux jours \u00e0 cause de la pluie, Arthur Rinderknech a fini par c\u00e9der contre Cameron Norrie (6-3\/3-6\/6-3). Le Britannique affrontera Karen Khachanov en demi-finales.<\/p>\n","protected":false},"author":57,"featured_media":131827,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2302],"tags":[],"class_list":["post-131815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie<\/title>\n<meta name=\"description\" content=\"Arthur Rinderknech ne verra pas les demi-finales de l&#039;ATP Lyon ! Le Fran\u00e7ais s&#039;est inclin\u00e9 contre Norrie, qui affrontera Khachanov.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie\" \/>\n<meta property=\"og:description\" content=\"Arthur Rinderknech ne verra pas les demi-finales de l&#039;ATP Lyon ! Le Fran\u00e7ais s&#039;est inclin\u00e9 contre Norrie, qui affrontera Khachanov.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-22T09:59:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-22T17:44:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Vincent Soubab\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/\"},\"author\":{\"name\":\"Vincent Soubab\u00e8re\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\"},\"headline\":\"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie\",\"datePublished\":\"2021-05-22T09:59:04+00:00\",\"dateModified\":\"2021-05-22T17:44:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/\"},\"wordCount\":541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png\",\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/\",\"name\":\"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png\",\"datePublished\":\"2021-05-22T09:59:04+00:00\",\"dateModified\":\"2021-05-22T17:44:46+00:00\",\"description\":\"Arthur Rinderknech ne verra pas les demi-finales de l'ATP Lyon ! Le Fran\u00e7ais s'est inclin\u00e9 contre Norrie, qui affrontera Khachanov.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png\",\"width\":800,\"height\":445,\"caption\":\"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\",\"name\":\"Vincent Soubab\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"caption\":\"Vincent Soubab\u00e8re\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/vincents\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie","description":"Arthur Rinderknech ne verra pas les demi-finales de l'ATP Lyon ! Le Fran\u00e7ais s'est inclin\u00e9 contre Norrie, qui affrontera Khachanov.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/","og_locale":"fr_FR","og_type":"article","og_title":"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie","og_description":"Arthur Rinderknech ne verra pas les demi-finales de l'ATP Lyon ! Le Fran\u00e7ais s'est inclin\u00e9 contre Norrie, qui affrontera Khachanov.","og_url":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-05-22T09:59:04+00:00","article_modified_time":"2021-05-22T17:44:46+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png","type":"image\/png"}],"author":"Vincent Soubab\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/"},"author":{"name":"Vincent Soubab\u00e8re","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b"},"headline":"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie","datePublished":"2021-05-22T09:59:04+00:00","dateModified":"2021-05-22T17:44:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/"},"wordCount":541,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png","articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/","url":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/","name":"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png","datePublished":"2021-05-22T09:59:04+00:00","dateModified":"2021-05-22T17:44:46+00:00","description":"Arthur Rinderknech ne verra pas les demi-finales de l'ATP Lyon ! Le Fran\u00e7ais s'est inclin\u00e9 contre Norrie, qui affrontera Khachanov.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/ATP-Lyon-Arthur-Rinderknech-sincline-en-trois-sets-contre-Cameron-Norrie.png","width":800,"height":445,"caption":"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/atp-lyon-arthur-rinderknech-sincline-en-trois-sets-contre-cameron-norrie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"ATP Lyon : Arthur Rinderknech s\u2019incline en trois sets contre Cameron Norrie"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b","name":"Vincent Soubab\u00e8re","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","caption":"Vincent Soubab\u00e8re"},"description":"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.","url":"https:\/\/dicodusport.fr\/blog\/author\/vincents\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/131815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=131815"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/131815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/131827"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=131815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=131815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=131815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}