{"id":132488,"date":"2021-05-25T08:25:30","date_gmt":"2021-05-25T06:25:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=132488"},"modified":"2021-05-25T08:24:15","modified_gmt":"2021-05-25T06:24:15","slug":"25-mai-1935-pluie-de-records-pour-jesse-owens","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/","title":{"rendered":"25 mai 1935 : Pluie de records pour Jesse Owens"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/athletisme\/\">ATHL\u00c9TISME<\/a> &#8211; Un an avant les Jeux de Berlin 1936, Jesse Owens participe aux Championnats universitaires am\u00e9ricains. Incertain de prendre le d\u00e9part des \u00e9preuves, il r\u00e9alise pourtant \u00e0 Ann Arbor une performance unique, r\u00e9\u00e9crivant l\u2019histoire du sport et de l\u2019athl\u00e9tisme.<\/strong> <\/em><\/p>\n<h2 style=\"text-align: justify;\">\u00c7a s&rsquo;est pass\u00e9 le 25 mai 1935<\/h2>\n<p style=\"text-align: justify;\">Quelques jours avant le Big Ten, <strong>Jesse Owens<\/strong> est victime d\u2019une chute dans les escaliers. La douleur au dos est insoutenable, son entra\u00eeneur pense alors le retirer de la comp\u00e9tition. Finalement, l\u2019athl\u00e8te originaire de l\u2019Alabama d\u00e9cide de prendre course apr\u00e8s course. <strong>15h15<\/strong> : Tout commence avec le <strong>100 yards<\/strong>, Owens \u00e9gale alors le record mondial plac\u00e9 \u00e0 9,4 s. \u00c7a aurait pu \u00eatre un sixi\u00e8me record pour lui, certains juges ayant chronom\u00e9tr\u00e9 9,3. Mais la r\u00e9glementation de l\u2019\u00e9poque prenait en compte le temps le moins rapide. Dommage. Car ensuite, les records mondiaux se sont multipli\u00e9s. Lors du <strong>saut en longueur<\/strong>, avec un timing trop serr\u00e9, l\u2019Am\u00e9ricain n\u2019a le temps que pour un saut. Un seul essai qui se transforme en pulv\u00e9risation du record du monde. Avec une marque \u00e0 8,13 m, il explose l\u2019ancienne de 15 cm et devient le premier au-dessus de la barre des 8m. A peine quelques minutes pour respirer que le <strong>220 yards<\/strong> arrive. Cette course, qui prendra en compte le <strong>200 m<\/strong> \u00e9galement apporte ainsi deux nouveaux records au futur m\u00e9daill\u00e9 olympique. Pour finir sa moisson, <strong>Jesse Owens<\/strong> s\u2019offre un nouveau temps r\u00e9f\u00e9rence et deux records lors du <strong>220 yards haies<\/strong>, valable pour le <strong>200 m haies<\/strong> apr\u00e8s officialisation &#8211; comme le 200 m &#8211; quelques ann\u00e9es plus tard. <strong>Un record \u00e9gal\u00e9 et cinq battus en 45 minutes<\/strong>. En moyenne, sur les pistes du Ferry Field, \u00e7a en fait un toutes les neuf minutes. Non mais quelle insolence !<\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: Lors des Jeux de Berlin 1936, Jesse Owens d\u00e9crochera quatre m\u00e9dailles d\u2019or olympiques sous la <span style=\"text-decoration: line-through;\">barbe<\/span> moustache d\u2019Adolf Hitler. Un succ\u00e8s inspirant le film <em>La Couleur de la victoire<\/em> (sorti en 2016) et\u00a0faisant de lui un mod\u00e8le pour les athl\u00e8tes afro-am\u00e9ricains et une figure de la lutte contre le racisme, un peu malgr\u00e9 lui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 25 mai 1935, Jesse Owens fr\u00f4lait les six records du monde aux Championnats universitaires am\u00e9ricains. Retour sur cette journ\u00e9e historique.<\/p>\n","protected":false},"author":18,"featured_media":132534,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308,8],"tags":[143],"class_list":["post-132488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-histoire","tag-athletisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>25 mai 1935 : Pluie de records pour Jesse Owens<\/title>\n<meta name=\"description\" content=\"Le 25 mai 1935, Jesse Owens fr\u00f4lait les six records du monde aux Championnats universitaires am\u00e9ricains. Retour sur cette journ\u00e9e historique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 mai 1935 : Pluie de records pour Jesse Owens\" \/>\n<meta property=\"og:description\" content=\"Le 25 mai 1935, Jesse Owens fr\u00f4lait les six records du monde aux Championnats universitaires am\u00e9ricains. Retour sur cette journ\u00e9e historique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-25T06:25:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"25 mai 1935 : Pluie de records pour Jesse Owens\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"25 mai 1935 : Pluie de records pour Jesse Owens\",\"datePublished\":\"2021-05-25T06:25:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/\"},\"wordCount\":374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png\",\"keywords\":[\"Athl\u00e9tisme\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/\",\"name\":\"25 mai 1935 : Pluie de records pour Jesse Owens\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png\",\"datePublished\":\"2021-05-25T06:25:30+00:00\",\"description\":\"Le 25 mai 1935, Jesse Owens fr\u00f4lait les six records du monde aux Championnats universitaires am\u00e9ricains. Retour sur cette journ\u00e9e historique.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png\",\"width\":800,\"height\":445,\"caption\":\"25 mai 1935 : Pluie de records pour Jesse Owens\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"25 mai 1935 : Pluie de records pour Jesse Owens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"25 mai 1935 : Pluie de records pour Jesse Owens","description":"Le 25 mai 1935, Jesse Owens fr\u00f4lait les six records du monde aux Championnats universitaires am\u00e9ricains. Retour sur cette journ\u00e9e historique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/","og_locale":"fr_FR","og_type":"article","og_title":"25 mai 1935 : Pluie de records pour Jesse Owens","og_description":"Le 25 mai 1935, Jesse Owens fr\u00f4lait les six records du monde aux Championnats universitaires am\u00e9ricains. Retour sur cette journ\u00e9e historique.","og_url":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-05-25T06:25:30+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"25 mai 1935 : Pluie de records pour Jesse Owens","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"25 mai 1935 : Pluie de records pour Jesse Owens","datePublished":"2021-05-25T06:25:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/"},"wordCount":374,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png","keywords":["Athl\u00e9tisme"],"articleSection":["Athl\u00e9tisme","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/","url":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/","name":"25 mai 1935 : Pluie de records pour Jesse Owens","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png","datePublished":"2021-05-25T06:25:30+00:00","description":"Le 25 mai 1935, Jesse Owens fr\u00f4lait les six records du monde aux Championnats universitaires am\u00e9ricains. Retour sur cette journ\u00e9e historique.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/25-mai-1935-Pluie-de-records-pour-Jesse-Owens.png","width":800,"height":445,"caption":"25 mai 1935 : Pluie de records pour Jesse Owens"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/25-mai-1935-pluie-de-records-pour-jesse-owens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"25 mai 1935 : Pluie de records pour Jesse Owens"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/132488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=132488"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/132488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/132534"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=132488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=132488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=132488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}