{"id":13273,"date":"2018-02-22T19:54:19","date_gmt":"2018-02-22T18:54:19","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=13273"},"modified":"2018-02-23T07:46:41","modified_gmt":"2018-02-23T06:46:41","slug":"jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/","title":{"rendered":"JO 2018 &#8211; Programme du 23 f\u00e9vrier : Fourcade &#038; co pour terminer en apoth\u00e9ose ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.<br \/>\n<\/b><\/em><\/p>\n<h4 style=\"text-align: justify;\">2h00 : Patinage artistique &#8211; Individuelle (F)<\/h4>\n<p style=\"text-align: justify;\">22\u00e8me \u00e0 l&rsquo;issue du programme court, Ma\u00e9-B\u00e9r\u00e9nice Meit\u00e9 visera le Top 20 lors du programme libre de cette nuit. Qualifi\u00e9e pour la finale, il lui sera difficile de faire mieux. Pour le titre, la Russe Alina Zagitova, 15 ans, est la grande favorite, apr\u00e8s avoir battu le record du monde du court il y a deux jours.<\/p>\n<h4 style=\"text-align: justify;\">2h00 : Ski freestyle &#8211; Ski cross (F)<\/h4>\n<p style=\"text-align: justify;\">Sans Oph\u00e9lie David, bless\u00e9e lors des entrainements en d\u00e9but de semaine, les Fran\u00e7aises conservent de tr\u00e8s grandes chances de m\u00e9dailles avec Marielle Berger Sabbatel et Aliz\u00e9e Baron. Cinqui\u00e8me et huiti\u00e8me au classement g\u00e9n\u00e9ral de la Coupe du Monde cette saison, elles auront fort \u00e0 faire face \u00e0 la Su\u00e9doise Sandra Naeslund, archi-favorite pour la m\u00e9daille d&rsquo;or.<\/p>\n<h4 style=\"text-align: justify;\">12h15 : Biathlon &#8211; Relais masculin<\/h4>\n<p style=\"text-align: justify;\">Derni\u00e8re course en biathlon, et pas n&rsquo;importe laquelle ! Le relais masculin se d\u00e9roulera demain, avec quatre nations favorites pour le podium : l&rsquo;Allemagne, la Norv\u00e8ge, la Su\u00e8de et bien \u00e9videmment, la France. Si Martin Fourcade et Simon Desthieux sont s\u00fbrs de participer, les deux derni\u00e8res places sont encore incertaines. A priori, Antonin Guigonnat, qui r\u00e9alise de bons Jeux Olympiques devrait \u00eatre sur la piste, alors que le dernier ticket se jouera entre Emilien Jacquelin, Simon Fourcade et Quentin Fillon Maillet, m\u00eame si ce dernier risque de faire les frais de ses mauvaises performances.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Flo Ostermann<\/strong><\/em><em><br \/>\n<\/em><a href=\"https:\/\/www.facebook.com\/florent.ostermann\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/SportInsideMag\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.<\/p>\n","protected":false},"author":4,"featured_media":12126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2,3588,2313],"tags":[2427,3544,2429,2289,3241,2687],"class_list":["post-13273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-pyeongchang-2018","category-sports-dhiver","tag-biathlon","tag-jo-de-pyeongchang","tag-martin-fourcade","tag-patinage-artistique","tag-ski-cross","tag-ski-freestyle"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>JO 2018 - Programme du 23 f\u00e9vrier : Fourcade &amp; co pour terminer en apoth\u00e9ose ?<\/title>\n<meta name=\"description\" content=\"Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JO 2018 - Programme du 23 f\u00e9vrier : Fourcade &amp; co pour terminer en apoth\u00e9ose ?\" \/>\n<meta property=\"og:description\" content=\"Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-22T18:54:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-23T06:46:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/JO-2018-Programme-23-f\u00e9vrier.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"JO 2018 &#8211; Programme du 23 f\u00e9vrier : Fourcade &#038; co pour terminer en apoth\u00e9ose ?\",\"datePublished\":\"2018-02-22T18:54:19+00:00\",\"dateModified\":\"2018-02-23T06:46:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/JO-2018-Programme-23-f\u00e9vrier.png\",\"keywords\":[\"Biathlon\",\"JO de Pyeongchang\",\"Martin Fourcade\",\"Patinage artistique\",\"Ski cross\",\"ski freestyle\"],\"articleSection\":[\"Actualit\u00e9s\",\"Pyeongchang 2018\",\"Sports d'hiver\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/\",\"name\":\"JO 2018 - Programme du 23 f\u00e9vrier : Fourcade & co pour terminer en apoth\u00e9ose ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/JO-2018-Programme-23-f\u00e9vrier.png\",\"datePublished\":\"2018-02-22T18:54:19+00:00\",\"dateModified\":\"2018-02-23T06:46:41+00:00\",\"description\":\"Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/JO-2018-Programme-23-f\u00e9vrier.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/JO-2018-Programme-23-f\u00e9vrier.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JO 2018 &#8211; Programme du 23 f\u00e9vrier : Fourcade &#038; co pour terminer en apoth\u00e9ose ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JO 2018 - Programme du 23 f\u00e9vrier : Fourcade & co pour terminer en apoth\u00e9ose ?","description":"Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/","og_locale":"fr_FR","og_type":"article","og_title":"JO 2018 - Programme du 23 f\u00e9vrier : Fourcade & co pour terminer en apoth\u00e9ose ?","og_description":"Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.","og_url":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2018-02-22T18:54:19+00:00","article_modified_time":"2018-02-23T06:46:41+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/JO-2018-Programme-23-f\u00e9vrier.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"JO 2018 &#8211; Programme du 23 f\u00e9vrier : Fourcade &#038; co pour terminer en apoth\u00e9ose ?","datePublished":"2018-02-22T18:54:19+00:00","dateModified":"2018-02-23T06:46:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/JO-2018-Programme-23-f\u00e9vrier.png","keywords":["Biathlon","JO de Pyeongchang","Martin Fourcade","Patinage artistique","Ski cross","ski freestyle"],"articleSection":["Actualit\u00e9s","Pyeongchang 2018","Sports d'hiver"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/","url":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/","name":"JO 2018 - Programme du 23 f\u00e9vrier : Fourcade & co pour terminer en apoth\u00e9ose ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/JO-2018-Programme-23-f\u00e9vrier.png","datePublished":"2018-02-22T18:54:19+00:00","dateModified":"2018-02-23T06:46:41+00:00","description":"Quatorzi\u00e8me jour de comp\u00e9tition en Cor\u00e9e du Sud ! Ce vendredi, le relais masculin peut permettre au biathlon fran\u00e7ais de terminer en apoth\u00e9ose, tandis que le ski cross f\u00e9minin peut nous offrir une nouvelle m\u00e9daille.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/JO-2018-Programme-23-f\u00e9vrier.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/02\/JO-2018-Programme-23-f\u00e9vrier.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jo-2018-programme-du-23-fevrier-fourcade-co-terminer-apotheose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"JO 2018 &#8211; Programme du 23 f\u00e9vrier : Fourcade &#038; co pour terminer en apoth\u00e9ose ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/13273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=13273"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/13273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/12126"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=13273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=13273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=13273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}