{"id":134747,"date":"2021-06-01T19:17:22","date_gmt":"2021-06-01T17:17:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=134747&#038;preview=true&#038;preview_id=134747"},"modified":"2021-06-09T13:01:14","modified_gmt":"2021-06-09T11:01:14","slug":"equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/","title":{"rendered":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>EURO 2020 &#8211; Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l&rsquo;attaque tricolore face au Pays de Galles ce mercredi.\u00a0<\/b><\/em><\/p>\n<p style=\"text-align: justify;\">Les Bleus jouent leur premier match amical face au <a href=\"https:\/\/dicodusport.fr\/blog\/euro-2020-equipe-de-france-le-calendrier-des-bleus\/\" target=\"_blank\" rel=\"noopener\">Pays de Galles ce mercredi 2 juin \u00e0 21h10<\/a>. L&rsquo;attaque devrait \u00eatre compos\u00e9e de <strong>Karim Benzema<\/strong> et <strong>Kylian Mbapp\u00e9<\/strong> avec<strong> Antoine Griezmann<\/strong> en soutien. L&rsquo;\u00e9quipe de France devrait \u00e9voluer en 4-3-3 losange avec <strong>Corentin Tolisso<\/strong> en sentinelle \u00e0 la place de N&rsquo;Golo Kant\u00e9, pr\u00e9serv\u00e9 apr\u00e8s la finale de la Ligue des Champions. Pas de surprise en d\u00e9fense avec les quatre joueurs attendus pour \u00eatre titulaire lors du prochain Euro.<\/p>\n<p style=\"text-align: justify;\">Hormis le milieu de Chelsea, ce onze pourrait \u00eatre proche de celui qui d\u00e9butera la comp\u00e9tition face \u00e0 l&rsquo;Allemagne. Les relations entre les trois joueurs offensifs seront scrut\u00e9es de pr\u00e8s.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f1eb;&#x1f1f7; La compo probable des Bleus pour le match de pr\u00e9paration face aux Pays de Galles avec un 4-4-2 losange \u25ba <a href=\"https:\/\/t.co\/8xAy0OOb9R\">https:\/\/t.co\/8xAy0OOb9R<\/a> <a href=\"https:\/\/t.co\/ek7UtOqfyo\">pic.twitter.com\/ek7UtOqfyo<\/a><\/p>\n<p>\u2014 RMC Sport (@RMCsport) <a href=\"https:\/\/twitter.com\/RMCsport\/status\/1399771875803287552?ref_src=twsrc%5Etfw\">June 1, 2021<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EURO 2020 &#8211; Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l&rsquo;attaque tricolore face au Pays de Galles ce mercredi.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":134750,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47044],"tags":[6966,30,4727,2236,338],"class_list":["post-134747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euro-de-football","tag-equipe-de-france-de-football","tag-france","tag-karim-benzema","tag-kylian-mbappe","tag-pays-de-galles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles<\/title>\n<meta name=\"description\" content=\"EURO 2020 - Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l&#039;attaque tricolore face au Pays de Galles ce mercredi.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles\" \/>\n<meta property=\"og:description\" content=\"EURO 2020 - Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l&#039;attaque tricolore face au Pays de Galles ce mercredi.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-01T17:17:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T11:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles\",\"datePublished\":\"2021-06-01T17:17:22+00:00\",\"dateModified\":\"2021-06-09T11:01:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/\"},\"wordCount\":207,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png\",\"keywords\":[\"Equipe de France de football\",\"France\",\"Karim Benzema\",\"Kylian Mbapp\u00e9\",\"Pays De Galles\"],\"articleSection\":[\"Euro de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/\",\"name\":\"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png\",\"datePublished\":\"2021-06-01T17:17:22+00:00\",\"dateModified\":\"2021-06-09T11:01:14+00:00\",\"description\":\"EURO 2020 - Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l'attaque tricolore face au Pays de Galles ce mercredi.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png\",\"width\":800,\"height\":445,\"caption\":\"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles","description":"EURO 2020 - Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l'attaque tricolore face au Pays de Galles ce mercredi.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles","og_description":"EURO 2020 - Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l'attaque tricolore face au Pays de Galles ce mercredi.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-06-01T17:17:22+00:00","article_modified_time":"2021-06-09T11:01:14+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles","datePublished":"2021-06-01T17:17:22+00:00","dateModified":"2021-06-09T11:01:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/"},"wordCount":207,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png","keywords":["Equipe de France de football","France","Karim Benzema","Kylian Mbapp\u00e9","Pays De Galles"],"articleSection":["Euro de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/","url":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/","name":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png","datePublished":"2021-06-01T17:17:22+00:00","dateModified":"2021-06-09T11:01:14+00:00","description":"EURO 2020 - Selon plusieurs de nos confr\u00e8res dont RMC Sport, Karim Benzema et Kylian Mbapp\u00e9 devraient \u00eatre align\u00e9s \u00e0 la pointe de l'attaque tricolore face au Pays de Galles ce mercredi.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Equipe-de-France-Karim-Benzema-et-Kylian-Mbappe-associes-face-au-Pays-de-Galles.png","width":800,"height":445,"caption":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-karim-benzema-et-kylian-mbappe-associes-face-au-pays-de-galles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9quipe de France : Karim Benzema et Kylian Mbapp\u00e9 associ\u00e9s face au Pays de Galles"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/134747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=134747"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/134747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/134750"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=134747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=134747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=134747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}