{"id":13719,"date":"2018-03-03T08:00:41","date_gmt":"2018-03-03T07:00:41","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=13719"},"modified":"2018-03-02T22:18:15","modified_gmt":"2018-03-02T21:18:15","slug":"quiz-connaissez-emmanuel-riviere","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/","title":{"rendered":"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?"},"content":{"rendered":"<p style=\"text-align: justify\"><em><strong>Tous \u00e0 vos crampons, aujourd&rsquo;hui c&rsquo;est football ! Vous pensez tout savoir d&rsquo;Emmanuel Rivi\u00e8re ? Saviez-vous d\u00e9j\u00e0 qu&rsquo;il f\u00eatait son anniversaire aujourd&rsquo;hui ? C&rsquo;est l&rsquo;heure de jouer et de tester vos connaissances sur le footballeur tricolore. Le coup d&rsquo;envoi est donn\u00e9 !<\/strong><\/em><\/p>\n[WpProQuiz 27]\n<p style=\"text-align: justify\"><em><strong>Sophie Clapier<\/strong><br \/>\n<\/em><a href=\"https:\/\/twitter.com\/soocube\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.facebook.com\/soocube\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaussez tous vos crampons, c&rsquo;est un quiz football qui vous attend aujourd&rsquo;hui pour souhaiter un bon anniversaire \u00e0 Emmanuel Rivi\u00e8re ! GO !<\/p>\n","protected":false},"author":18,"featured_media":13718,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2,2301,3692],"tags":[75,2895],"class_list":["post-13719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-football","category-quiz","tag-football","tag-quiz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?<\/title>\n<meta name=\"description\" content=\"Chaussez tous vos crampons, c&#039;est un quiz football qui vous attend aujourd&#039;hui pour souhaiter un bon anniversaire \u00e0 Emmanuel Rivi\u00e8re ! GO !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?\" \/>\n<meta property=\"og:description\" content=\"Chaussez tous vos crampons, c&#039;est un quiz football qui vous attend aujourd&#039;hui pour souhaiter un bon anniversaire \u00e0 Emmanuel Rivi\u00e8re ! GO !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-03T07:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?\",\"datePublished\":\"2018-03-03T07:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/\"},\"wordCount\":56,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png\",\"keywords\":[\"Football\",\"Quiz\"],\"articleSection\":[\"Actualit\u00e9s\",\"Football\",\"Quiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/\",\"name\":\"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png\",\"datePublished\":\"2018-03-03T07:00:41+00:00\",\"description\":\"Chaussez tous vos crampons, c'est un quiz football qui vous attend aujourd'hui pour souhaiter un bon anniversaire \u00e0 Emmanuel Rivi\u00e8re ! GO !\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?","description":"Chaussez tous vos crampons, c'est un quiz football qui vous attend aujourd'hui pour souhaiter un bon anniversaire \u00e0 Emmanuel Rivi\u00e8re ! GO !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/","og_locale":"fr_FR","og_type":"article","og_title":"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?","og_description":"Chaussez tous vos crampons, c'est un quiz football qui vous attend aujourd'hui pour souhaiter un bon anniversaire \u00e0 Emmanuel Rivi\u00e8re ! GO !","og_url":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2018-03-03T07:00:41+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?","datePublished":"2018-03-03T07:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/"},"wordCount":56,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png","keywords":["Football","Quiz"],"articleSection":["Actualit\u00e9s","Football","Quiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/","url":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/","name":"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png","datePublished":"2018-03-03T07:00:41+00:00","description":"Chaussez tous vos crampons, c'est un quiz football qui vous attend aujourd'hui pour souhaiter un bon anniversaire \u00e0 Emmanuel Rivi\u00e8re ! GO !","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/03\/Emmanuel-Rivi\u00e8re.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/quiz-connaissez-emmanuel-riviere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Quiz : connaissez-vous Emmanuel Rivi\u00e8re ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/13719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=13719"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/13719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/13718"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=13719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=13719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=13719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}