{"id":139572,"date":"2021-06-17T08:00:32","date_gmt":"2021-06-17T06:00:32","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=139572"},"modified":"2021-06-17T07:39:38","modified_gmt":"2021-06-17T05:39:38","slug":"17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/","title":{"rendered":"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/football\/\">FOOTBALL<\/a> &#8211; En cette date m\u00e9morable pour les amateurs de football, l\u2019Italie, championne d\u2019Europe en titre, rencontre l\u2019Allemagne, finaliste de la derni\u00e8re Coupe du monde. Et justement, c\u2019est une demi-finale de Mondial qui se joue entre les deux \u00e9quipes.<\/strong> <\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 17 juin 1970<\/h2>\n<p style=\"text-align: justify;\">Dans le stade d\u2019Azteca de Mexico, plus de 100\u00a0000 personnes se sont rassembl\u00e9es pour assister \u00e0 ce duel. Apr\u00e8s un rapide but pour l\u2019Italie sign\u00e9 <strong>Roberto Boninsegna<\/strong>, la rencontre est loin de tenir le nom qu\u2019on lui donnera plus tard de \u00ab\u00a0match du si\u00e8cle\u00a0\u00bb. Les minutes passent et la Nazionale semble se diriger tout droit vers une victoire, surtout qu\u2019on avance dans le temps additionnel. Mais une erreur d\u00e9fensive et tout est \u00e0 refaire. Sur un centre de <strong>J\u00fcrgen Grabowski<\/strong>, <strong>Schnellinger<\/strong> est un peu trop seul et pousse le ballon au fond des filets. L\u2019heure des prolongations sonne alors. C\u2019est \u00e0 cet instant que l\u2019histoire se fait. D\u2019abord parce que, bless\u00e9 \u00e0 la clavicule, <strong>Franz Beckenbauer<\/strong> terminera son match avec le bras en \u00e9charpe, les changements allemands ayant \u00e9t\u00e9 effectu\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Ensuite, parce que sous la chaleur mexicaine, la partie s\u2019enflamme. Par l\u2019interm\u00e9diaire de <strong>Gerd M\u00fcller<\/strong>, la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne prend l\u2019avantage \u00e0 la 94<sup>\u00e8me<\/sup> minute. Sit\u00f4t fait, sit\u00f4t suivi par <strong>Tarcisio Burgnich<\/strong> qui \u00e9galise pour l\u2019Italie. Cette derni\u00e8re reprend m\u00eame les commandes 3-2 peu avant le changement de c\u00f4t\u00e9 gr\u00e2ce \u00e0 <strong>Luigi Riva<\/strong>. Mais les corps sont \u00e9puis\u00e9s, les d\u00e9fenses \u00e0 terre. <strong>M\u00fcller<\/strong> une nouvelle fois trouve la faille et ram\u00e8ne la Mannschaft \u00e0 3-3. Quatre buts marqu\u00e9s en prolongations, auxquels vient s\u2019ajouter un cinqui\u00e8me et dernier. Celui-ci, r\u00e9alisation de <strong>Gianni Rivera<\/strong> offre finalement la victoire \u00e0 l\u2019Italie 4-3.<\/p>\n<p><span class=\"nb8hKeutFWwB6UjTR3s7a1pVL05H\"><iframe loading=\"lazy\" title=\"Le plus grand match de football du XX\u00e8me si\u00e8cle ?\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/YiuvbOTnLPI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: En hommage \u00e0 ce \u00ab Match du si\u00e8cle \u00bb, \u00ab Partido del siglo \u00bb ou encore \u00ab Jahrhundertspiel \u00bb, une plaque comm\u00e9morative orne, depuis, le stade Azteca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Loin de tenir ses promesses pendant 90 minutes, la rencontre Italie &#8211; Allemagne du 17 juin 1970 est finalement devenue le match du si\u00e8cle.<\/p>\n","protected":false},"author":18,"featured_media":139602,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301,8],"tags":[355,1530,75,374],"class_list":["post-139572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-histoire","tag-allemagne","tag-coupe-du-monde","tag-football","tag-italie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne<\/title>\n<meta name=\"description\" content=\"Loin de tenir ses promesses pendant 90 minutes, la rencontre Italie - Allemagne du 17 juin 1970 est finalement devenue le match du si\u00e8cle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne\" \/>\n<meta property=\"og:description\" content=\"Loin de tenir ses promesses pendant 90 minutes, la rencontre Italie - Allemagne du 17 juin 1970 est finalement devenue le match du si\u00e8cle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T06:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne\",\"datePublished\":\"2021-06-17T06:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png\",\"keywords\":[\"Allemagne\",\"Coupe du monde\",\"Football\",\"Italie\"],\"articleSection\":[\"Football\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/\",\"name\":\"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png\",\"datePublished\":\"2021-06-17T06:00:32+00:00\",\"description\":\"Loin de tenir ses promesses pendant 90 minutes, la rencontre Italie - Allemagne du 17 juin 1970 est finalement devenue le match du si\u00e8cle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png\",\"width\":800,\"height\":445,\"caption\":\"17 juin 1970 - Le match du si\u00e8cle entre Italie et Allemagne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne","description":"Loin de tenir ses promesses pendant 90 minutes, la rencontre Italie - Allemagne du 17 juin 1970 est finalement devenue le match du si\u00e8cle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/","og_locale":"fr_FR","og_type":"article","og_title":"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne","og_description":"Loin de tenir ses promesses pendant 90 minutes, la rencontre Italie - Allemagne du 17 juin 1970 est finalement devenue le match du si\u00e8cle.","og_url":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-06-17T06:00:32+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne","datePublished":"2021-06-17T06:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png","keywords":["Allemagne","Coupe du monde","Football","Italie"],"articleSection":["Football","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/","url":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/","name":"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png","datePublished":"2021-06-17T06:00:32+00:00","description":"Loin de tenir ses promesses pendant 90 minutes, la rencontre Italie - Allemagne du 17 juin 1970 est finalement devenue le match du si\u00e8cle.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/17-juin-1970-Le-match-du-siecle-entre-Italie-et-Allemagne.png","width":800,"height":445,"caption":"17 juin 1970 - Le match du si\u00e8cle entre Italie et Allemagne"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/17-juin-1970-le-match-du-siecle-entre-italie-et-allemagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"17 juin 1970 : Le \u00ab match du si\u00e8cle \u00bb entre Italie et Allemagne"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/139572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=139572"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/139572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/139602"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=139572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=139572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=139572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}