{"id":140727,"date":"2021-06-20T15:43:18","date_gmt":"2021-06-20T13:43:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=140727"},"modified":"2021-06-20T15:51:19","modified_gmt":"2021-06-20T13:51:19","slug":"atp-halle-ugo-humbert-titre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/","title":{"rendered":"ATP Halle : Ugo Humbert titr\u00e9 !"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>ATP HALLE &#8211; Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s&rsquo;est impos\u00e9 en deux manches (6-3\/7-6) contre Rublev. Gr\u00e2ce \u00e0 une superbe semaine, le Tricolore remporte son premier tournoi de la saison \u00e0 Halle.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">Un break au meilleur des moments<\/h2>\n<p style=\"text-align: justify;\">Le Fran\u00e7ais r\u00e9alise un tr\u00e8s bon premier engagement. Il profite de la qualit\u00e9 de sa premi\u00e8re balle, servant deux aces. Il signe aussi une tr\u00e8s belle amortie. <strong>Rublev<\/strong> lui r\u00e9pond parfaitement avec un jeu blanc, mais <strong>Humbert<\/strong> l\u2019imite pour mener 2-1. Dans ce d\u00e9but de match, les deux joueurs ma\u00eetrisent totalement leurs mises en jeu, s\u2019appuyant sur un excellent service. De plus, <strong>Humbert<\/strong> et <strong>Rublev<\/strong> manquent tous deux une grande partie de leurs retours sur seconde balle. Les points sont donc extr\u00eamement courts. Apr\u00e8s trois engagements, le tricolore en est \u00e0 75% de premi\u00e8re balle, ce qui est particuli\u00e8rement int\u00e9ressant. Alors qu\u2019il m\u00e8ne 4-3, <strong>Humbert<\/strong> s\u2019offre les deux premi\u00e8res balles de break de cette finale gr\u00e2ce \u00e0 plusieurs fautes directes du Russe. Ce dernier s\u2019\u00e9nerve d\u2019ailleurs \u201cOut, out, out, out !\u201d. Au terme du premier rallye du match, la t\u00eate de s\u00e9rie num\u00e9ro quatre manque son revers long de ligne et offre le break \u00e0 son adversaire au meilleur des moments.<\/p>\n<p style=\"text-align: justify;\">Alors qu\u2019il sert pour le gain de la premi\u00e8re manche, le Fran\u00e7ais se crispe et donne deux points. Il se rattrape bien et remporte les trois \u00e9changes suivants pour s\u2019offrir une balle de set. Le Russe la sauve. <strong>Humbert<\/strong> se cr\u00e9e une seconde opportunit\u00e9, elle aussi effac\u00e9e. <strong>Rublev<\/strong> a d\u00e9sormais une chance de d\u00e9breaker, mais il perd le point. Le jeu commence \u00e0 durer, <strong>Humbert<\/strong> conc\u00e8de une seconde balle de d\u00e9break mais il s\u2019en sort. Le Fran\u00e7ais obtient ensuite une troisi\u00e8me balle de set, mais c\u2019est finalement la quatri\u00e8me qui lui permet de sortir vainqueur de cette premi\u00e8re manche.<\/p>\n<h2 style=\"text-align: justify;\">Un nouveau tie-break remport\u00e9 par le tricolore<\/h2>\n<p style=\"text-align: justify;\">Les deux joueurs commencent bien le second set en remportant facilement leur premier engagement. <strong>Rublev<\/strong> signe ses deux premiers aces de la rencontre pour mener 2-1. Les \u00e9changes s\u2019intensifient depuis le dernier jeu de la premi\u00e8re manche, mais les serveurs continuent de dominer. A 3-3, <strong>Humbert<\/strong> m\u00e8ne 15-30 sur le service de son adversaire, mais il ne parvient pas \u00e0 saisir l\u2019opportunit\u00e9. Le Fran\u00e7ais part \u00e0 la faute et permet \u00e0 <strong>Rublev<\/strong> de mener 4-3. Les deux joueurs ma\u00eetrisent ensuite tous leurs engagements sans conc\u00e9der la moindre balle de break.<\/p>\n<p style=\"text-align: justify;\">Ils s\u2019affrontent donc dans un jeu d\u00e9cisif. <strong>Humbert<\/strong> comme <strong>Rublev<\/strong> s\u2019appuient de nouveau sur un excellent service pour conserver leurs points de service. A 4-4, le Russe craque et le tricolore r\u00e9alise le mini-break. <strong>Humbert<\/strong> le confirme et s\u2019offre deux balles de match. La premi\u00e8re est la bonne pour le Fran\u00e7ais qui remporte son premier titre en ATP 500. Il confirme son excellente gestion des tie-breaks avec 5 jeux decisifs remport\u00e9s sur 6 cette semaine.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u00c9norme Ugo Humbert ! Apr\u00e8s avoir notamment battu Zverev et Auger-Aliassime, le Fran\u00e7ais se paye Rublev (6-3, 7-6) et remporte le tournoi de Halle, son premier sacre en ATP 500.<\/p>\n<p>3 finales, 3 titres. La marque des grands.<\/p>\n<p>Humbert sera 25e mondial demain, son meilleur classement.<\/p>\n<p>\u2014 Quentin Moynet (@QuentinMoynet) <a href=\"https:\/\/twitter.com\/QuentinMoynet\/status\/1406607282742439943?ref_src=twsrc%5Etfw\">June 20, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ATP HALLE &#8211; Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s&rsquo;est impos\u00e9 en deux manches (6-4\/7-6) contre Rublev. Gr\u00e2ce \u00e0 une superbe semaine, le Tricolore remporte son premier tournoi de la saison \u00e0 Halle.<\/p>\n","protected":false},"author":57,"featured_media":140740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2302],"tags":[24,6520],"class_list":["post-140727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-sport","tag-ugo-humbert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ATP Halle : Ugo Humbert titr\u00e9 !<\/title>\n<meta name=\"description\" content=\"ATP HALLE - Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s&#039;est impos\u00e9 en deux manches (6-4\/7-6) contre Rublev.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATP Halle : Ugo Humbert titr\u00e9 !\" \/>\n<meta property=\"og:description\" content=\"ATP HALLE - Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s&#039;est impos\u00e9 en deux manches (6-4\/7-6) contre Rublev.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-20T13:43:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-20T13:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Vincent Soubab\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/\"},\"author\":{\"name\":\"Vincent Soubab\u00e8re\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\"},\"headline\":\"ATP Halle : Ugo Humbert titr\u00e9 !\",\"datePublished\":\"2021-06-20T13:43:18+00:00\",\"dateModified\":\"2021-06-20T13:51:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/\"},\"wordCount\":576,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png\",\"keywords\":[\"sport\",\"Ugo Humbert\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/\",\"name\":\"ATP Halle : Ugo Humbert titr\u00e9 !\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png\",\"datePublished\":\"2021-06-20T13:43:18+00:00\",\"dateModified\":\"2021-06-20T13:51:19+00:00\",\"description\":\"ATP HALLE - Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s'est impos\u00e9 en deux manches (6-4\/7-6) contre Rublev.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png\",\"width\":800,\"height\":445,\"caption\":\"ATP Halle : Ugo Humbert titr\u00e9 !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATP Halle : Ugo Humbert titr\u00e9 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\",\"name\":\"Vincent Soubab\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"caption\":\"Vincent Soubab\u00e8re\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/vincents\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ATP Halle : Ugo Humbert titr\u00e9 !","description":"ATP HALLE - Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s'est impos\u00e9 en deux manches (6-4\/7-6) contre Rublev.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/","og_locale":"fr_FR","og_type":"article","og_title":"ATP Halle : Ugo Humbert titr\u00e9 !","og_description":"ATP HALLE - Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s'est impos\u00e9 en deux manches (6-4\/7-6) contre Rublev.","og_url":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-06-20T13:43:18+00:00","article_modified_time":"2021-06-20T13:51:19+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png","type":"image\/png"}],"author":"Vincent Soubab\u00e8re","twitter_card":"summary_large_image","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/"},"author":{"name":"Vincent Soubab\u00e8re","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b"},"headline":"ATP Halle : Ugo Humbert titr\u00e9 !","datePublished":"2021-06-20T13:43:18+00:00","dateModified":"2021-06-20T13:51:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/"},"wordCount":576,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png","keywords":["sport","Ugo Humbert"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/","url":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/","name":"ATP Halle : Ugo Humbert titr\u00e9 !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png","datePublished":"2021-06-20T13:43:18+00:00","dateModified":"2021-06-20T13:51:19+00:00","description":"ATP HALLE - Troisi\u00e8me finale et troisi\u00e8me titre pour Ugo Humbert ! Le Fran\u00e7ais s'est impos\u00e9 en deux manches (6-4\/7-6) contre Rublev.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/ATP-Halle-Ugo-Humbert-titre.png","width":800,"height":445,"caption":"ATP Halle : Ugo Humbert titr\u00e9 !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/atp-halle-ugo-humbert-titre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"ATP Halle : Ugo Humbert titr\u00e9 !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b","name":"Vincent Soubab\u00e8re","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","caption":"Vincent Soubab\u00e8re"},"description":"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.","url":"https:\/\/dicodusport.fr\/blog\/author\/vincents\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/140727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=140727"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/140727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/140740"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=140727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=140727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=140727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}