{"id":143257,"date":"2021-06-29T20:32:28","date_gmt":"2021-06-29T18:32:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=143257&#038;preview=true&#038;preview_id=143257"},"modified":"2021-06-30T09:36:25","modified_gmt":"2021-06-30T07:36:25","slug":"euro-2020-notes-angleterre-allemagne","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/","title":{"rendered":"Euro 2020 : les notes d&rsquo;Angleterre &#8211; Allemagne"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EURO 2020 &#8211; Solide et s\u00fbre de sa force, <a href=\"https:\/\/dicodusport.fr\/blog\/euro-2020-solide-l-angleterre-elimine-allemagne-et-file-en-quarts\/\">l&rsquo;Angleterre a domin\u00e9 l&rsquo;Allemagne en 8\u00e8mes de finale de l&rsquo;Euro<\/a>. Les notes du match.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les notes de l&rsquo;Angleterre face \u00e0 l&rsquo;Allemagne<\/h2>\n<p style=\"text-align: justify;\"><strong>Jordan Pickford : 6<\/strong><\/p>\n<p style=\"text-align: justify;\">Il a r\u00e9pondu pr\u00e9sent quand son \u00e9quipe en a eu besoin. Il remporte son un contre un face \u00e0 Werner (33e) et effectue une belle claquette sur la demi-vol\u00e9e de Havertz (49e). On ne lui en voudra pas pour sa relance manqu\u00e9e en seconde p\u00e9riode (63e).<\/p>\n<p style=\"text-align: justify;\"><strong>Kyle Walker : 5<\/strong><\/p>\n<p style=\"text-align: justify;\">Il a r\u00e9alis\u00e9 un match discret mais pr\u00e9cieux. D\u00e8s le d\u00e9but de match, il est essentiel en d\u00e9fense, avec une bonne t\u00eate d\u00e9fensive (4e) et un super retour sur Goretzka permettant \u00e0 Rice de ne pas \u00eatre dernier d\u00e9fenseur (8e).<\/p>\n<p style=\"text-align: justify;\"><strong>Harry Maguire : 6<\/strong><\/p>\n<p style=\"text-align: justify;\">Important d\u00e9fensivement, il a surtout convaincu par son \u00e9tat d\u2019esprit. Tr\u00e8s agressif, il s\u2019impose notamment en passant devant M\u00fcller (18e). Il est aussi essentiel par son jeu de t\u00eate comme sur cette intervention a\u00e9rienne (30e). Offensivement, sa t\u00eate est trop axiale sur un corner o\u00f9 il est laiss\u00e9 libre (17e). Il manque son coup de casque dix minutes plus tard (28e).<\/p>\n<p style=\"text-align: justify;\"><strong>John Stones : 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Tr\u00e8s solide, il est \u00e0 cr\u00e9diter de plusieurs retours d\u00e9fensifs (39e, 57). Il s\u2019est montr\u00e9 tr\u00e8s propre avec 96% de passes r\u00e9ussies, soit plus que tout autre titulaire.<\/p>\n<p style=\"text-align: justify;\"><strong>Kieran Trippier : 4<\/strong><\/p>\n<p style=\"text-align: justify;\">Match tr\u00e8s moyen pour le d\u00e9fenseur de l\u2019Atl\u00e9tico de Madrid. Il n\u2019a que trop peu apport\u00e9 offensivement, ne prenant pas assez son couloir. Il n\u2019a r\u00e9ussi que 69% de ses transmissions. Enfin, ses centres se sont av\u00e9r\u00e9s assez mauvais (61e).<\/p>\n<p style=\"text-align: justify;\"><strong>Luke Shaw : 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Assez discret en premi\u00e8re p\u00e9riode, il est mont\u00e9 en r\u00e9gime tout au long de la rencontre. Il a su investir son couloir pour amener du danger. Il est \u00e0 cr\u00e9diter d\u2019un tr\u00e8s bon centre sur l\u2019ouverture du score (75e). Sur le second but, il d\u00e9cale parfaitement Grealish (86e).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Luke Shaw :<\/p>\n<p>&#x1f449; Passeur d\u00e9cisive sur le but de Sterling<br \/>\n&#x1f449; r\u00e9cup\u00e8re le ballon et est l&rsquo;avant dernier passeur sur le but de Kane<\/p>\n<p>L&rsquo;actuel meilleur lat\u00e9ral gauche au monde. N&rsquo;en d\u00e9plaise \u00e0 certains <a href=\"https:\/\/t.co\/tgko6PRl5D\">pic.twitter.com\/tgko6PRl5D<\/a><\/p>\n<p>\u2014 \u00a3|z0 &#x1f60c;&#x1f1f8;&#x1f1f3;&#x1f1f5;&#x1f1f9; (@ElhadjiKandji1) <a href=\"https:\/\/twitter.com\/ElhadjiKandji1\/status\/1409931104702943245?ref_src=twsrc%5Etfw\">June 29, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Kalvin Phillips : 4.5<\/strong><\/p>\n<p style=\"text-align: justify;\">Tr\u00e8s bon depuis le d\u00e9but de l\u2019Euro, il a \u00e9t\u00e9 un peu en retrait ce soir. Il est l\u2019auteur d\u2019une grosse faute sur Kroos qui aurait peut-\u00eatre m\u00e9rit\u00e9 le carton rouge (45e+1). Il n\u2019a r\u00e9ussi que 82% de ses passes et s\u2019est souvent appuy\u00e9 sur la bonne prestation de son co\u00e9quipier du milieu de terrain. Toutefois, il a \u00e9t\u00e9 pr\u00e9cieux dans le domaine a\u00e9rien.<\/p>\n<p style=\"text-align: justify;\"><strong>Declan Rice : 6.5<\/strong><\/p>\n<p style=\"text-align: justify;\">Mis \u00e0 part sa grosse faute sur Goretzka qui partait en contre (8e), il a r\u00e9alis\u00e9 un bon match. Il a beaucoup jou\u00e9 vers l\u2019avant, toujours avec l\u2019intention de cr\u00e9er du jeu. Surtout, ses transmissions se sont av\u00e9r\u00e9es justes, avec 95% de r\u00e9ussite.<\/p>\n<p style=\"text-align: justify;\"><strong>Bukayo Saka : 6<\/strong><\/p>\n<p style=\"text-align: justify;\">Sa premi\u00e8re p\u00e9riode est plut\u00f4t bonne. Il a apport\u00e9 sa vitesse et ses qualit\u00e9s de provocation, notamment pour obtenir un excellent coup franc (13e). Il a r\u00e9cup\u00e9r\u00e9 un ballon important devant Kroos (28e). Un peu moins en vue apr\u00e8s la pause, il est remplac\u00e9 par Grealish (69e).<\/p>\n<p style=\"text-align: justify;\"><strong>Harry Kane : 4<\/strong><\/p>\n<p style=\"text-align: justify;\">Invisible dans le premier acte avec seulement 9 ballons touch\u00e9s, il manque tout ce qu\u2019il tente : sa mauvaise transmission pour Philips (41e) et surtout son contr\u00f4le pr\u00e8s du but alors qu\u2019il doit marquer (45e+1). C\u2019est un peu mieux en seconde p\u00e9riode jusqu\u2019\u00e0 la d\u00e9livrance en fin de match pour son premier but de l\u2019Euro (86e).<\/p>\n<p style=\"text-align: justify;\"><strong>Raheem Sterling : 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Il s\u2019est montr\u00e9 tr\u00e8s concern\u00e9 ce soir avec beaucoup d\u2019envie et d\u2019intentions positives. Il est le premier \u00e0 se montrer dangereux dans le camp des siens avec une excellente frappe aux 25 m\u00e8tres stopp\u00e9e par Neuer (16e). Il reprend l\u2019excellent centre de Shaw pour ouvrir le score (75e). Il signe \u00e9galement une bonne acc\u00e9l\u00e9ration (45e+1) et une excellente intervention d\u00e9fensive devant Havertz (54e). Cependant, il manque parfois de justesse technique comme sur ce mauvais contr\u00f4le (22e) ou cette perte de balle b\u00eate en fin de match qui aurait pu co\u00fbter tr\u00e8s cher (82e).<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/2\/#notesallemagne\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 26px;font-size:20px;line-height:40px;border-color:#4d8ac7;border-radius:4px;text-shadow:none\"> Les notes de l&rsquo;Allemagne<\/span><\/a>\n<p style=\"text-align: justify;\"><!--nextpage--><a id=\"notesallemagne\"><\/a><strong><em>EURO 2020 &#8211;\u00a0<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\"><strong>Les notes de l&rsquo;Allemagne face \u00e0 l&rsquo;Angleterre<\/strong><\/h2>\n<p style=\"text-align: justify;\"><strong>Manuel Neuer : 4<\/strong><\/p>\n<p style=\"text-align: justify;\">Il ne peut rien sur les deux buts. A noter une belle d\u00e9tente sur la frappe de Sterling (16e) et un arr\u00eat tranquille sur la t\u00eate de Maguire (17e). Sinon, il n\u2019a pas eu \u00e0 intervenir.<\/p>\n<p style=\"text-align: justify;\"><strong>Mats Hummels : 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Quel match de Mats Hummels ! Le d\u00e9fenseur de Dortmund a multipli\u00e9 les interventions a\u00e9riennes (27e, 44e, 45e+1, 51e). Il a \u00e9galement particip\u00e9 au jeu, avec notamment cette bonne ouverture pour M\u00fcller (64e).<\/p>\n<p style=\"text-align: justify;\"><strong>Antonio R\u00fcdiger : 4.5<\/strong><\/p>\n<p style=\"text-align: justify;\">Certainement le moins bon des d\u00e9fenseurs centraux allemands ce soir. Il offre un bon coup franc aux Anglais avec une faute idiote sur Saka (13e). Il ne s\u2019aligne pas toujours avec sa d\u00e9fense et couvre les attaquants anglais. Il signe cependant une bonne intervention devant Walker (51e)<\/p>\n<p style=\"text-align: justify;\"><strong>Matthias Ginter : 6<\/strong><\/p>\n<p style=\"text-align: justify;\">Toujours tr\u00e8s juste dans ses interventions, Ginter s\u2019est distingu\u00e9 par ses tacles (7e,11e). Il a bien musel\u00e9 Saka. Les deux buts viennent en revanche de son c\u00f4t\u00e9 (75e).<\/p>\n<p style=\"text-align: justify;\"><strong>Joshua Kimmich : 4.5<\/strong><\/p>\n<p style=\"text-align: justify;\">Beaucoup de d\u00e9chet dans le jeu de Kimmich aujourd\u2019hui. Cependant, il s\u2019est montr\u00e9 pr\u00e9cieux \u00e0 la fois d\u00e9fensivement avec une t\u00eate salvatrice (26e) et offensivement bon centre pour Gosens qui ne peut reprendre (32e). Il est \u00e9galement trouv\u00e9 sur un bon appel en profondeur pour obtenir un superbe coup franc (78e).<\/p>\n<p style=\"text-align: justify;\"><strong>Robin Gosens : 3<\/strong><\/p>\n<p style=\"text-align: justify;\">Il a manqu\u00e9 son match, incapable de cr\u00e9er du danger que ce soit par une frappe ou une passe. Il est logiquement remplac\u00e9 en seconde p\u00e9riode par Leroy San\u00e9 (87e).<\/p>\n<p style=\"text-align: justify;\"><strong>Toni Kroos : 5<\/strong><\/p>\n<p style=\"text-align: justify;\">Difficile de juger le match de Kroos tant il a \u00e9t\u00e9 disparate. D\u00e9pass\u00e9 en premi\u00e8re mi-temps avec de nombreux ballons perdus (28e), il s\u2019est montr\u00e9 bien plus s\u00e9rieux apr\u00e8s la pause quand ses co\u00e9quipiers \u00e9taient plus en difficult\u00e9. Il est \u00e0 cr\u00e9diter de plusieurs tacles importants.<\/p>\n<p style=\"text-align: justify;\"><strong>Leon Goretzka : 6<\/strong><\/p>\n<p style=\"text-align: justify;\">C\u2019est le joueur avec la plus grande activit\u00e9 en d\u00e9but de match : une belle perc\u00e9e (3e) suivie d\u2019une r\u00e9cup\u00e9ration importante (4e) et d\u2019un excellent appel en profondeur avant de subir la faute de Rice (8e). Il a \u00e9galement tent\u00e9 sa chance \u00e0 plusieurs reprises. Il est pris par l\u2019appel de Kane (43e) en fin de premi\u00e8re p\u00e9riode. Apr\u00e8s la pause, c\u2019est un peu moins bien.<\/p>\n<p style=\"text-align: justify;\"><strong>Thomas M\u00fcller : 3<\/strong><\/p>\n<p style=\"text-align: justify;\">Le joueur du Bayern a manqu\u00e9 son match. Il a commis plusieurs pertes de balle dangereuses (18e, 45e+1). Il a \u00e9norm\u00e9ment manqu\u00e9 de justesse dans ses transmissions, comme sur ce mauvais ballon pour Werner (19e). Il manque son face-\u00e0-face apr\u00e8s l\u2019excellente ouverture de Havertz (82e).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Thomas M\u00fcller n&rsquo;a jamais marqu\u00e9 en 15 matchs de Championnat d&rsquo;Europe.<\/p>\n<p>EURO 2012<br \/>\n&#x274c; Portugal<br \/>\n&#x274c; Pays-Bas<br \/>\n&#x274c; Danemark<br \/>\n&#x274c; Gr\u00e8ce<br \/>\n&#x274c; Italie<\/p>\n<p>EURO 2016<br \/>\n&#x274c; Ukraine<br \/>\n&#x274c; Pologne<br \/>\n&#x274c; Irlande du Nord<br \/>\n&#x274c; Slovaquie<br \/>\n&#x274c; Italie<br \/>\n&#x274c; France<\/p>\n<p>EURO 2020<br \/>\n&#x274c; France<br \/>\n&#x274c; Portugal<br \/>\n&#x274c; Hongrie<br \/>\n&#x274c; Angleterre <a href=\"https:\/\/t.co\/KIB1G26DKc\">pic.twitter.com\/KIB1G26DKc<\/a><\/p>\n<p>\u2014 Vines Foot (@VinesFoot) <a href=\"https:\/\/twitter.com\/VinesFoot\/status\/1409941394920181760?ref_src=twsrc%5Etfw\">June 29, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Kai Havertz : 6<\/strong><\/p>\n<p style=\"text-align: justify;\">Il donne un excellent ballon en profondeur pour Werner qui s\u2019en va d\u00e9fier Pickford (33e). Il se montre important par sa bonne conservation de balle (45e+1). Il signe une superbe reprise de vol\u00e9e mise au-dessus (49e). Il r\u00e9alise \u00e9galement une bonne acc\u00e9l\u00e9ration avant de transmettre \u00e0 Werner (57e). En fin de match, il est auteur d\u2019une ouverture pour M\u00fcller qui aurait d\u00fb \u00e9galiser (82e).<\/p>\n<p style=\"text-align: justify;\"><strong>Timo Werner : 3<\/strong><\/p>\n<p style=\"text-align: justify;\">Il touche tr\u00e8s peu de ballons avec 20 ballons touch\u00e9s. Surtout, il est tr\u00e8s d\u00e9cevant dans son utilisation du cuir avec neuf ballons perdus. Il manque son face-\u00e0-face devant Pickford (33e). Il est logiquement remplac\u00e9 par Gnabry (69e).<\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-euro-2020\/\"><strong>Toute l\u2019actualit\u00e9 de l\u2019Euro 2020<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 26px;font-size:20px;line-height:40px;border-color:#4d8ac7;border-radius:4px;text-shadow:none\"> Revenir aux notes de l&rsquo;Angleterre<\/span><\/a>\n","protected":false},"excerpt":{"rendered":"<p>EURO 2020 &#8211; Solide et s\u00fbre de sa force, l&rsquo;Angleterre a domin\u00e9 l&rsquo;Allemagne en 8\u00e8me de finale de l&rsquo;Euro. Les notes du match.<\/p>\n","protected":false},"author":57,"featured_media":143300,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47044],"tags":[355,51],"class_list":["post-143257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euro-de-football","tag-allemagne","tag-angleterre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euro 2020 : les notes d&#039;Angleterre - Allemagne<\/title>\n<meta name=\"description\" content=\"EURO 2020 - Solide et s\u00fbre de sa force, l&#039;Angleterre a domin\u00e9 l&#039;Allemagne en 8\u00e8me de finale de l&#039;Euro. Les notes du match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\" \/>\n<link rel=\"next\" href=\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro 2020 : les notes d&#039;Angleterre - Allemagne\" \/>\n<meta property=\"og:description\" content=\"EURO 2020 - Solide et s\u00fbre de sa force, l&#039;Angleterre a domin\u00e9 l&#039;Allemagne en 8\u00e8me de finale de l&#039;Euro. Les notes du match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-29T18:32:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-30T07:36:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Vincent Soubab\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euro 2020 : les notes d&#039;Angleterre - Allemagne\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\"},\"author\":{\"name\":\"Vincent Soubab\u00e8re\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\"},\"headline\":\"Euro 2020 : les notes d&rsquo;Angleterre &#8211; Allemagne\",\"datePublished\":\"2021-06-29T18:32:28+00:00\",\"dateModified\":\"2021-06-30T07:36:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\"},\"wordCount\":1472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png\",\"keywords\":[\"Allemagne\",\"Angleterre\"],\"articleSection\":[\"Euro de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\",\"name\":\"Euro 2020 : les notes d'Angleterre - Allemagne\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png\",\"datePublished\":\"2021-06-29T18:32:28+00:00\",\"dateModified\":\"2021-06-30T07:36:25+00:00\",\"description\":\"EURO 2020 - Solide et s\u00fbre de sa force, l'Angleterre a domin\u00e9 l'Allemagne en 8\u00e8me de finale de l'Euro. Les notes du match.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png\",\"width\":800,\"height\":445,\"caption\":\"Euro 2020 : les notes d'Angleterre - Allemagne\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b\",\"name\":\"Vincent Soubab\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg\",\"caption\":\"Vincent Soubab\u00e8re\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/vincents\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro 2020 : les notes d'Angleterre - Allemagne","description":"EURO 2020 - Solide et s\u00fbre de sa force, l'Angleterre a domin\u00e9 l'Allemagne en 8\u00e8me de finale de l'Euro. Les notes du match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/","next":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/2\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro 2020 : les notes d'Angleterre - Allemagne","og_description":"EURO 2020 - Solide et s\u00fbre de sa force, l'Angleterre a domin\u00e9 l'Allemagne en 8\u00e8me de finale de l'Euro. Les notes du match.","og_url":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-06-29T18:32:28+00:00","article_modified_time":"2021-06-30T07:36:25+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png","type":"image\/png"}],"author":"Vincent Soubab\u00e8re","twitter_card":"summary_large_image","twitter_title":"Euro 2020 : les notes d'Angleterre - Allemagne","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/"},"author":{"name":"Vincent Soubab\u00e8re","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b"},"headline":"Euro 2020 : les notes d&rsquo;Angleterre &#8211; Allemagne","datePublished":"2021-06-29T18:32:28+00:00","dateModified":"2021-06-30T07:36:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/"},"wordCount":1472,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png","keywords":["Allemagne","Angleterre"],"articleSection":["Euro de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/","url":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/","name":"Euro 2020 : les notes d'Angleterre - Allemagne","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png","datePublished":"2021-06-29T18:32:28+00:00","dateModified":"2021-06-30T07:36:25+00:00","description":"EURO 2020 - Solide et s\u00fbre de sa force, l'Angleterre a domin\u00e9 l'Allemagne en 8\u00e8me de finale de l'Euro. Les notes du match.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-notes-angleterre-allemagne\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/06\/Euro-2020-Les-notes-dAngleterre-Allemagne.png","width":800,"height":445,"caption":"Euro 2020 : les notes d'Angleterre - Allemagne"},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/ba9487b5b85f57eecfb00513e982c05b","name":"Vincent Soubab\u00e8re","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Vincent-Soubabere-150x150.jpg","caption":"Vincent Soubab\u00e8re"},"description":"Journaliste\/r\u00e9dacteur depuis ao\u00fbt 2018 - Passionn\u00e9 de sport depuis tout petit, je me suis logiquement tourn\u00e9 vers le journalisme sportif depuis ao\u00fbt 2018. Grand supporter des Girondins, je suis aussi un fan de football. Je pratique le tennis et suis l'actualit\u00e9 de la petite balle jaune. En juillet, vous risquez de me croiser sur les routes du Tour.","url":"https:\/\/dicodusport.fr\/blog\/author\/vincents\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/143257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=143257"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/143257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/143300"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=143257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=143257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=143257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}