{"id":143575,"date":"2021-07-01T08:05:04","date_gmt":"2021-07-01T06:05:04","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=143575"},"modified":"2021-08-13T15:38:04","modified_gmt":"2021-08-13T13:38:04","slug":"nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/","title":{"rendered":"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/actualites\/basket-ball\/nba\/nba-2020-2021\/\">NBA 2020\/21<\/a><b> &#8211; Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs 4-2 face aux Clippers et rejoint les Finales NBA !<\/b><\/em><\/p>\n<p style=\"text-align: justify;\">Les Suns commencent \u00e0 merveille ce Game 6, en retrouvant l&rsquo;insolence offensive qui leur a manqu\u00e9 il y a deux jours. <strong>DeAndre Ayton<\/strong> est de retour aux affaires, en marquant autant de points en 12 minutes que sur tout le Game 5. <strong>Chris Paul<\/strong> a lui aussi retrouv\u00e9 un peu d&rsquo;adresse ext\u00e9rieure, tandis que <strong>Devin Booker<\/strong> et <strong>Cameron Payne<\/strong> contribuent eux aussi \u00e0 la f\u00eate. Forc\u00e9ment, cela permet aux Suns de passer le 1<sup>er<\/sup> quart avec 4 points d&rsquo;avance puis d&rsquo;atteindre la mi-temps avec un \u00e9cart de +9.<\/p>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 Clippers, apr\u00e8s un step-back \u00e0 3 points au buzzer du 1<sup>er<\/sup> quart, <strong>DeMarcus Cousins<\/strong> continue comme sur le match pr\u00e9c\u00e9dent de compenser efficacement le forfait d&rsquo;<strong>Ivica Zubac<\/strong>. En tout cas offensivement (10 points \u00e0 la pause) car d\u00e9fensivement le pivot est \u00e0 la peine et est syst\u00e9matiquement cibl\u00e9 par <strong>Monty Williams<\/strong>. 3 autres Clippers sont en <em>double-figure<\/em> \u00e0 la mi-temps : <strong>Reggie Jackson<\/strong>,<strong> Marcus Morris<\/strong> et <strong>Pat Beverley<\/strong>. Ce dernier est toujours aussi&#8230;sp\u00e9cial et continue \u00e0 c\u00e9l\u00e9brer des double pas r\u00e9ussis comme un titre NBA.<\/p>\n<p style=\"text-align: justify;\">Seule d\u00e9ception : <strong>Paul George, qui n&rsquo;a que 6 petits points au compteur \u00e0 la pause<\/strong>. Mais bon, selon certains fans des Clippers sur Twitter, il para\u00eet que ce n&rsquo;est pas grave de manquer de constance et que c&rsquo;est normal de faire un excellent match puis deux matchs horribles.<\/p>\n<h2 style=\"text-align: justify;\">Chris Paul prend les choses en main<\/h2>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">CP3 steps back and this time it&rsquo;s a 4-point play&#8230; he&rsquo;s got 32 PTS!<a href=\"https:\/\/twitter.com\/Suns?ref_src=twsrc%5Etfw\">@Suns<\/a> 111<a href=\"https:\/\/twitter.com\/LAClippers?ref_src=twsrc%5Etfw\">@LAClippers<\/a> 92<\/p>\n<p>4th quarter of Game 6 on ESPN <a href=\"https:\/\/t.co\/ptlTyIrZKe\">pic.twitter.com\/ptlTyIrZKe<\/a><\/p>\n<p>\u2014 NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1410440911981617152?ref_src=twsrc%5Etfw\">July 1, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Avec 9 points d&rsquo;avance \u00e0 la pause donc, <strong>les Suns m\u00e8nent mais les Clippers ne l\u00e2chent rien<\/strong>. Alors que l&rsquo;\u00e9cart est redescendu \u00e0 +7 pour Phoenix, c&rsquo;est le moment que choisit <strong>Chris Paul pour prendre le contr\u00f4le du match<\/strong>. D&rsquo;abord par une adresse au tir encore une fois retrouv\u00e9e, contrairement aux derniers matchs. <strong>CP3 inscrit ainsi 31 points sur la deuxi\u00e8me mi-temps<\/strong> <strong>\u00e0 12\/16 au tir dont 5\/5 \u00e0 3 points<\/strong>, portant son total sur l&rsquo;ensemble du match \u00e0 <strong>41 points.<\/strong> Ensuite, par des petits coups de vice, comme cette belle simulation devant DeMarcus Cousins qui vaut \u00e0 ce dernier une faute technique.<\/p>\n<p style=\"text-align: justify;\">En face, personne n&rsquo;arrive \u00e0 prendre le leadership pour revenir dans le match. <strong>Marcus Morris est le seul au dessus des 20 unit\u00e9s (26 points)<\/strong>, Paul George est invisible (-25 de plus\/minus !) et <strong>Pat Beverley a autant de sel dans ses veines que dans celles de Thibaut Courtois et de V\u00e9ronique Rabiot cumul\u00e9es<\/strong>. Le teigneux s&rsquo;\u00e9nerve sur Chris Paul (encore un coup de vice au passage de ce dernier qui le provoque) et se fait donc expulser \u00e0 5 minutes de la fin. Cette expulsion, comme un symbole, sonne le glas des espoirs des Clippers, qui abandonnent le match \u00e0 partir de cet instant.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">The <a href=\"https:\/\/twitter.com\/Suns?ref_src=twsrc%5Etfw\">@Suns<\/a> lift the <a href=\"https:\/\/twitter.com\/hashtag\/NBAWCF?src=hash&amp;ref_src=twsrc%5Etfw\">#NBAWCF<\/a> presented by AT&amp;T trophy and will represent the Western Conference in the <a href=\"https:\/\/twitter.com\/hashtag\/NBAFinals?src=hash&amp;ref_src=twsrc%5Etfw\">#NBAFinals<\/a> presented by YouTube TV for the first time since 1993! <a href=\"https:\/\/twitter.com\/hashtag\/ThatsGame?src=hash&amp;ref_src=twsrc%5Etfw\">#ThatsGame<\/a> <a href=\"https:\/\/t.co\/M6ImKWgkzF\">pic.twitter.com\/M6ImKWgkzF<\/a><\/p>\n<p>\u2014 NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1410449514960404483?ref_src=twsrc%5Etfw\">July 1, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Les Suns s&rsquo;imposent donc 130 \u00e0 103 et atteignent les Finales NBA de ces Playoffs 2021 ! Une belle r\u00e9compense pour la meilleure \u00e9quipe \u00e0 l&rsquo;Ouest cette saison, que ce soit en saison r\u00e9guli\u00e8re ou en Playoffs. La cons\u00e9cration aussi pour Chris Paul, apr\u00e8s de nombreuses ann\u00e9es \u00e0 tourner autour des Finales.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NBA 2020\/21 &#8211; Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs 4-2 face aux Clippers et rejoint les Finales NBA !<\/p>\n","protected":false},"author":21,"featured_media":158196,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[10533],"tags":[3919,4416,3205,7708,179,3688,2053,4707],"class_list":["post-143575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-chris-paul","tag-conference-ouest","tag-devin-booker","tag-los-angeles-clippers","tag-nba","tag-paul-george","tag-phoenix-suns","tag-playoffs-nba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !<\/title>\n<meta name=\"description\" content=\"NBA 2020\/21 - Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs face aux Clippers et rejoint les Finales NBA !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !\" \/>\n<meta property=\"og:description\" content=\"NBA 2020\/21 - Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs face aux Clippers et rejoint les Finales NBA !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-01T06:05:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-13T13:38:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mathieu Veillon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/MathieuVeillon\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/\"},\"author\":{\"name\":\"Mathieu Veillon\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806\"},\"headline\":\"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !\",\"datePublished\":\"2021-07-01T06:05:04+00:00\",\"dateModified\":\"2021-08-13T13:38:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/\"},\"wordCount\":594,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png\",\"keywords\":[\"chris paul\",\"conference ouest\",\"Devin Booker\",\"Los Angeles Clippers\",\"NBA\",\"Paul George\",\"Phoenix Suns\",\"Playoffs NBA\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/\",\"name\":\"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png\",\"datePublished\":\"2021-07-01T06:05:04+00:00\",\"dateModified\":\"2021-08-13T13:38:04+00:00\",\"description\":\"NBA 2020\/21 - Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs face aux Clippers et rejoint les Finales NBA !\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806\",\"name\":\"Mathieu Veillon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg\",\"caption\":\"Mathieu Veillon\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/MathieuVeillon\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/mathieu\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !","description":"NBA 2020\/21 - Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs face aux Clippers et rejoint les Finales NBA !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/","og_locale":"fr_FR","og_type":"article","og_title":"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !","og_description":"NBA 2020\/21 - Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs face aux Clippers et rejoint les Finales NBA !","og_url":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-07-01T06:05:04+00:00","article_modified_time":"2021-08-13T13:38:04+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png","type":"image\/png"}],"author":"Mathieu Veillon","twitter_card":"summary_large_image","twitter_title":"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !","twitter_creator":"@https:\/\/twitter.com\/MathieuVeillon","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/"},"author":{"name":"Mathieu Veillon","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806"},"headline":"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !","datePublished":"2021-07-01T06:05:04+00:00","dateModified":"2021-08-13T13:38:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/"},"wordCount":594,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png","keywords":["chris paul","conference ouest","Devin Booker","Los Angeles Clippers","NBA","Paul George","Phoenix Suns","Playoffs NBA"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/","url":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/","name":"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png","datePublished":"2021-07-01T06:05:04+00:00","dateModified":"2021-08-13T13:38:04+00:00","description":"NBA 2020\/21 - Apr\u00e8s la victoire 130-103 des Suns, Phoenix remporte sa s\u00e9rie de Playoffs face aux Clippers et rejoint les Finales NBA !","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/NBA-Playoffs-Les-Phoenix-Suns-atteignent-les-Finales-NBA.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nba-playoffs-les-phoenix-suns-atteignent-les-finales-nba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"NBA Playoffs : les Phoenix Suns atteignent les Finales NBA !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806","name":"Mathieu Veillon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","caption":"Mathieu Veillon"},"description":"Journaliste\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/MathieuVeillon"],"url":"https:\/\/dicodusport.fr\/blog\/author\/mathieu\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/143575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=143575"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/143575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/158196"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=143575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=143575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=143575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}