{"id":144085,"date":"2021-07-02T22:59:21","date_gmt":"2021-07-02T20:59:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=144085"},"modified":"2021-07-02T23:10:22","modified_gmt":"2021-07-02T21:10:22","slug":"euro-2020-belgique-italie-les-azzuri-en-demi-finales","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/","title":{"rendered":"Euro 2020 : Belgique &#8211; Italie, les Azzuri en demi-finales"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-euro-2020\/\">EURO 2020<\/a> &#8211; Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c&rsquo;est l&rsquo;Italie qui s&rsquo;impose 2 \u00e0 1 contre la Belgique. Un match qui aura tenu toutes ses promesses.\u00a0<\/strong> <\/em><\/p>\n<h2 style=\"text-align: justify;\">Promesses tenues<\/h2>\n<p style=\"text-align: justify;\">Depuis la d\u00e9faite de la France, pourtant promise \u00e0 l&rsquo;Espagne, le quart de finale entre <strong>la Belgique<\/strong> et <strong>l&rsquo;Italie<\/strong> \u00e9tait de loin le plus all\u00e9chant et le plus attendu. Et le moins que l&rsquo;on puisse dire, c&rsquo;est que la premi\u00e8re p\u00e9riode a tenu ses promesses, et peut-\u00eatre plus encore.<\/p>\n<p style=\"text-align: justify;\"><strong>L&rsquo;Italie<\/strong> a assum\u00e9 un statut de favori de plus en plus \u00e9vident en prenant les choses en main. Les Azzuri n&rsquo;h\u00e9sitaient pas \u00e0 contr\u00f4ler la gonfle, \u00e0 attaquer patiemment et \u00e0 man\u0153uvrer pour faire bouger un bloc belge compact. Loin les id\u00e9es d&rsquo;un football de possession \u00e9rig\u00e9 en identit\u00e9 nationale \u00e0 l&rsquo;\u00e9gal des frites, de la bi\u00e8re et de l&rsquo;instabilit\u00e9 gouvernementale. Loin aussi les reproches faits aux \u00e9quipes qui d\u00e9veloppaient un football de transition. <strong>Belgique<\/strong> et <strong>Italie<\/strong> semblaient avoir \u00e9chang\u00e9 leurs r\u00f4les, comme on \u00e9change des mamans ou des maillots.<\/p>\n<h2 style=\"text-align: justify;\">Belgique &#8211; Italie : le grand remplacement<\/h2>\n<p style=\"text-align: justify;\">De cette inversion, quasiment ontologique, a r\u00e9sult\u00e9 la premi\u00e8re p\u00e9riode la plus aboutie de cet Euro 2020. De l&rsquo;intensit\u00e9 partout, des replis d\u00e9fensifs continuels et des efforts les uns pour les autres. Belges et Italiens faisaient surtout preuve d&rsquo;une intelligence d\u00e9mentielle dans tous les compartiments du jeu. Ce sont bien les Italiens qui ont fait montre de l&rsquo;intelligence la plus accrue. D&rsquo;abord avec l&rsquo;ouverture du score de <strong>Barella<\/strong> avec une frappe enroul\u00e9e sur le c\u00f4t\u00e9 droit qui finit petit filet oppos\u00e9. Ensuite avec la confirmation de la domination italienne par <strong>Insigne<\/strong> par une frappe de loin, enroul\u00e9e elle aussi. Sur les deux buts, la d\u00e9fense belge faisait preuve d&rsquo;un rel\u00e2chement coupable.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[&#x26bd;&#xfe0f; VID\u00c9O BUT] &#x1f3c6; <a href=\"https:\/\/twitter.com\/hashtag\/BELITA?src=hash&amp;ref_src=twsrc%5Etfw\">#BELITA<\/a><br \/>\n&#x1f60d;&#x1f60d;&#x1f60d;&#x1f60d; OHHHH LA MERVEILLE DE LORENZO INSIGNE !<br \/>\n&#x1f4a5; Un rush solitaire suivi d&rsquo;un enroul\u00e9 sublime en pleine lucarne ! <a href=\"https:\/\/t.co\/RbkgeFqlDx\">pic.twitter.com\/RbkgeFqlDx<\/a><\/p>\n<p>\u2014 beIN SPORTS (@beinsports_FR) <a href=\"https:\/\/twitter.com\/beinsports_FR\/status\/1411066740528795653?ref_src=twsrc%5Etfw\">July 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 rel\u00e2chement, celui de <strong>Di Lorenzo<\/strong> \u00e9tait particuli\u00e8rement spectaculaire. Pris de vitesse par <strong>Doku<\/strong>, le d\u00e9fenseur lat\u00e9ral italien pousse le Belge. P\u00e9nalty. But. 2-1. Retour vestiaires.<\/p>\n<p style=\"text-align: justify;\">En seconde p\u00e9riode, l&rsquo;intensit\u00e9 n&rsquo;est pas retomb\u00e9e. Les occasions n&rsquo;ont pas manqu\u00e9 non plus, bien que plus rares qu&rsquo;en premi\u00e8re. L&rsquo;h\u00e9catombe amorc\u00e9e en d\u00e9but de comp\u00e9tition n&rsquo;a malheureusement pas fait exception aujourd&rsquo;hui. La blessure la plus cruelle est certainement celle de <strong>Spinazzola<\/strong>. Bless\u00e9 tout seul en pleine course, on pense forc\u00e9ment aux ligaments crois\u00e9s.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Italie<\/strong> a en revanche failli \u00e0 sa r\u00e9putation et n&rsquo;a pas ferm\u00e9 le jeu. Toujours au-dessus en possession du ballon (54-46), l&rsquo;\u00e9quipe transalpine est all\u00e9e au bout de ses id\u00e9es. Finalement, la <strong>Belgique<\/strong> aussi est all\u00e9e au bout des siennes en laissant le ballon \u00e0 ses adversaires. C\u00f4t\u00e9 <strong>Belgique<\/strong>, <strong>Doku<\/strong> et <strong>De Bruyne<\/strong> ont \u00e9t\u00e9 les plus v\u00e9h\u00e9ments ; c\u00f4t\u00e9 <strong>Italie<\/strong> <strong>Insigne<\/strong>, <strong>Jorginho<\/strong> et toute la d\u00e9fense azzurra ont brill\u00e9.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;Italie enquille donc un 32\u00e8me match sans d\u00e9faite ce soir. Elle retrouvera l&rsquo;Espagne en demi-finale de l&rsquo;Euro 2020.<\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/euro-2020-phase-finale-le-tableau-complet\/\"><strong>La tableau complet des phases finales<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-euro-2020\/\"><strong>Toute l\u2019actualit\u00e9 de l\u2019Euro 2020<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>EURO 2020 &#8211; Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c&rsquo;est l&rsquo;Italie qui s&rsquo;impose 2 \u00e0 1 contre la Belgique. Un match qui aura tenu toutes ses promesses.\u00a0<\/p>\n","protected":false},"author":40,"featured_media":144095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47044],"tags":[373,75,374],"class_list":["post-144085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euro-de-football","tag-belgique","tag-football","tag-italie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euro 2020 : Belgique - Italie, les Azzuri en demi-finales<\/title>\n<meta name=\"description\" content=\"EURO 2020 - Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c&#039;est l&#039;Italie qui s&#039;impose 2 \u00e0 1 contre la Belgique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro 2020 : Belgique - Italie, les Azzuri en demi-finales\" \/>\n<meta property=\"og:description\" content=\"EURO 2020 - Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c&#039;est l&#039;Italie qui s&#039;impose 2 \u00e0 1 contre la Belgique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-02T20:59:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-02T21:10:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jordane Mougenot-Pelletier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euro 2020 : Belgique - Italie, les Azzuri en demi-finales\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/jmp_pmj\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/\"},\"author\":{\"name\":\"Jordane Mougenot-Pelletier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040\"},\"headline\":\"Euro 2020 : Belgique &#8211; Italie, les Azzuri en demi-finales\",\"datePublished\":\"2021-07-02T20:59:21+00:00\",\"dateModified\":\"2021-07-02T21:10:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/\"},\"wordCount\":596,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png\",\"keywords\":[\"Belgique\",\"Football\",\"Italie\"],\"articleSection\":[\"Euro de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/\",\"name\":\"Euro 2020 : Belgique - Italie, les Azzuri en demi-finales\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png\",\"datePublished\":\"2021-07-02T20:59:21+00:00\",\"dateModified\":\"2021-07-02T21:10:22+00:00\",\"description\":\"EURO 2020 - Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c'est l'Italie qui s'impose 2 \u00e0 1 contre la Belgique.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png\",\"width\":800,\"height\":445,\"caption\":\"Euro 2020 - Belgique - Italie, les Azzuri en demi-finales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro 2020 : Belgique &#8211; Italie, les Azzuri en demi-finales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040\",\"name\":\"Jordane Mougenot-Pelletier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg\",\"caption\":\"Jordane Mougenot-Pelletier\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis mai 2018 - Dans mon sang coule \u00e0 la fois le feu des penne \u00e0 l'arrabiata et la glace du Grand Colombier. Amoureux des belles lettres et des Talking Heads, je supporte un club olympique. Int\u00e9ress\u00e9 par les relations qu'entretient le sport avec la soci\u00e9t\u00e9, je m'int\u00e9resse autant \u00e0 Marc C\u00e9cillon qu'\u00e0 Pep Guardiola, \u00e0 Tonya Harding qu'\u00e0 Philipp Roth. Enfant des 90's, on ne me fera pas croire qu'il y a eu plus beau \u00e0 voir depuis Zin\u00e9dine Zidane, Marco Pantani et Pete Sampras. La b\u00e9chamel est une invention du diable, la Super Ligue aussi.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/jmp_pmj\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/jordane\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro 2020 : Belgique - Italie, les Azzuri en demi-finales","description":"EURO 2020 - Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c'est l'Italie qui s'impose 2 \u00e0 1 contre la Belgique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro 2020 : Belgique - Italie, les Azzuri en demi-finales","og_description":"EURO 2020 - Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c'est l'Italie qui s'impose 2 \u00e0 1 contre la Belgique.","og_url":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-07-02T20:59:21+00:00","article_modified_time":"2021-07-02T21:10:22+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png","type":"image\/png"}],"author":"Jordane Mougenot-Pelletier","twitter_card":"summary_large_image","twitter_title":"Euro 2020 : Belgique - Italie, les Azzuri en demi-finales","twitter_creator":"@https:\/\/twitter.com\/jmp_pmj","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/"},"author":{"name":"Jordane Mougenot-Pelletier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040"},"headline":"Euro 2020 : Belgique &#8211; Italie, les Azzuri en demi-finales","datePublished":"2021-07-02T20:59:21+00:00","dateModified":"2021-07-02T21:10:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/"},"wordCount":596,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png","keywords":["Belgique","Football","Italie"],"articleSection":["Euro de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/","url":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/","name":"Euro 2020 : Belgique - Italie, les Azzuri en demi-finales","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png","datePublished":"2021-07-02T20:59:21+00:00","dateModified":"2021-07-02T21:10:22+00:00","description":"EURO 2020 - Dans le deuxi\u00e8me quart de finale de la journ\u00e9e, c'est l'Italie qui s'impose 2 \u00e0 1 contre la Belgique.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Euro-2020-Belgique-Italie-les-Azzuri-en-demi-finales.png","width":800,"height":445,"caption":"Euro 2020 - Belgique - Italie, les Azzuri en demi-finales"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-2020-belgique-italie-les-azzuri-en-demi-finales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euro 2020 : Belgique &#8211; Italie, les Azzuri en demi-finales"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/20a73cde459581e727623fffec174040","name":"Jordane Mougenot-Pelletier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Jordane-MP-150x150.jpg","caption":"Jordane Mougenot-Pelletier"},"description":"Journaliste\/r\u00e9dacteur depuis mai 2018 - Dans mon sang coule \u00e0 la fois le feu des penne \u00e0 l'arrabiata et la glace du Grand Colombier. Amoureux des belles lettres et des Talking Heads, je supporte un club olympique. Int\u00e9ress\u00e9 par les relations qu'entretient le sport avec la soci\u00e9t\u00e9, je m'int\u00e9resse autant \u00e0 Marc C\u00e9cillon qu'\u00e0 Pep Guardiola, \u00e0 Tonya Harding qu'\u00e0 Philipp Roth. Enfant des 90's, on ne me fera pas croire qu'il y a eu plus beau \u00e0 voir depuis Zin\u00e9dine Zidane, Marco Pantani et Pete Sampras. La b\u00e9chamel est une invention du diable, la Super Ligue aussi.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/jmp_pmj"],"url":"https:\/\/dicodusport.fr\/blog\/author\/jordane\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/144085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=144085"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/144085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/144095"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=144085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=144085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=144085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}