{"id":147098,"date":"2021-08-05T06:15:13","date_gmt":"2021-08-05T04:15:13","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=147098&#038;preview=true&#038;preview_id=147098"},"modified":"2021-08-05T06:15:44","modified_gmt":"2021-08-05T04:15:44","slug":"skateboard-jeux-olympiques-tokyo-calendrier-et-resultats","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/","title":{"rendered":"Skateboard &#8211; Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020\/\">JO DE TOKYO 2020<\/a> &#8211; Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Voici le calendrier et les r\u00e9sultats de la comp\u00e9tition.<\/em><\/strong><\/p>\n<h2>Femmes<\/h2>\n<h3 style=\"text-align: justify;\">Lundi 26 juillet<\/h3>\n<p style=\"text-align: justify;\"><b>2h : <\/b>s\u00e9rie 1 street<\/p>\n<p><b>2h41 : <\/b>s\u00e9rie 2 street<\/p>\n<p><b>3h22 : <\/b>s\u00e9rie 3 street<\/p>\n<p><b>4h03 : <\/b>s\u00e9rie 4 street<\/p>\n<p><a href=\"https:\/\/olympics.com\/tokyo-2020\/olympic-games\/resOG2020-\/pdf\/OG2020-\/SKB\/OG2020-_SKB_C73SP_SKBWSTREET------------QUAL--------.pdf\"><strong>R\u00e9sultats des s\u00e9ries<\/strong><\/a><\/p>\n<p><strong>5h25 : <a href=\"https:\/\/olympics.com\/tokyo-2020\/olympic-games\/fr\/resultats\/skateboard\/results-street-femmes-fnl-000100-.htm\">finale street<\/a><\/strong><\/p>\n<p><strong>&#x1f947; Momiji Nishiya &#x1f1ef;&#x1f1f5;<br \/>\n<\/strong><strong>&#x1f948; Rayssa Leal &#x1f1e7;&#x1f1f7;<br \/>\n&#x1f949; Funa Nakayama &#x1f1ef;&#x1f1f5;<br \/>\n<\/strong><\/p>\n<h3 style=\"text-align: justify;\">Mercredi 4 ao\u00fbt<\/h3>\n<p style=\"text-align: justify;\"><b>2h : <\/b>s\u00e9rie 1 park<\/p>\n<p><b>2h41 : <\/b>s\u00e9rie 2 park<\/p>\n<p><b>3h22 : <\/b>s\u00e9rie 3 park<\/p>\n<p><b>4h03 : <\/b>s\u00e9rie 4 park<\/p>\n<p><a href=\"https:\/\/olympics.com\/tokyo-2020\/olympic-games\/resOG2020-\/pdf\/OG2020-\/SKB\/OG2020-_SKB_C73PP_SKBWPARK--------------QUAL--------.pdf\" target=\"_blank\" rel=\"noopener\"><strong>R\u00e9sultats des s\u00e9ries<\/strong><\/a><\/p>\n<p><strong>5h30 : <a href=\"https:\/\/olympics.com\/tokyo-2020\/olympic-games\/fr\/resultats\/skateboard\/results-park-femmes-fnl-000100-.htm\" target=\"_blank\" rel=\"noopener\">finale park<\/a><\/strong><\/p>\n<p><strong>&#x1f947; Sakura Yosozumi &#x1f1ef;&#x1f1f5;<br \/>\n<\/strong><strong>&#x1f948; Kokona Hiraki &#x1f1ef;&#x1f1f5;<br \/>\n&#x1f949; Sky Brown &#x1f1ec;&#x1f1e7;<\/strong><\/p>\n<hr \/>\n<h2>Hommes<\/h2>\n<h3 style=\"text-align: justify;\">Dimanche 25 juillet<\/h3>\n<p style=\"text-align: justify;\"><b>2h : <\/b>s\u00e9rie 1 street<\/p>\n<p><b>2h41 : <\/b>s\u00e9rie 2 street<\/p>\n<p><b>3h22 : <\/b>s\u00e9rie 3 street<\/p>\n<p><b>4h03 : <\/b>s\u00e9rie 4 street<\/p>\n<p><a href=\"https:\/\/olympics.com\/tokyo-2020\/olympic-games\/resOG2020-\/pdf\/OG2020-\/SKB\/OG2020-_SKB_C73SP_SKBMSTREET------------QUAL--------.pdf\" target=\"_blank\" rel=\"noopener\"><strong>R\u00e9sultats des s\u00e9ries<\/strong><\/a><\/p>\n<p><strong>5h25 : finale street<\/strong><\/p>\n<p><strong>&#x1f947; Yuto Horigome &#x1f1ef;&#x1f1f5;<br \/>\n<\/strong><strong>&#x1f948; Kelvin Hoefler &#x1f1e7;&#x1f1f7;<br \/>\n&#x1f949; Jagger Eaton &#x1f1fa;&#x1f1f8;<\/strong><\/p>\n<hr \/>\n<h3 style=\"text-align: justify;\">Jeudi 5 ao\u00fbt<\/h3>\n<p style=\"text-align: justify;\"><b>2h : <\/b>s\u00e9rie 1 park<\/p>\n<p><b>2h42 : <\/b>s\u00e9rie 2 park<\/p>\n<p><b>3h24 : <\/b>s\u00e9rie 3 park<\/p>\n<p><b>4h06 : <\/b>s\u00e9rie 4 park<\/p>\n<p><a href=\"https:\/\/olympics.com\/tokyo-2020\/olympic-games\/resOG2020-\/pdf\/OG2020-\/SKB\/OG2020-_SKB_C73PP_SKBMPARK--------------QUAL--------.pdf\" target=\"_blank\" rel=\"noopener\"><strong>R\u00e9sultats des s\u00e9ries<\/strong><\/a><\/p>\n<p><strong>5h30 :<a href=\"https:\/\/olympics.com\/tokyo-2020\/olympic-games\/fr\/resultats\/skateboard\/results-park-hommes-fnl-000100-.htm\" target=\"_blank\" rel=\"noopener\"> finale park<\/a><\/strong><\/p>\n<p><strong>&#x1f947; Keegan Palmer &#x1f1e6;&#x1f1fa;<br \/>\n<\/strong><strong>&#x1f948; Pedro Barros &#x1f1e7;&#x1f1f7;<br \/>\n&#x1f949; Cory Juneau &#x1f1fa;&#x1f1f8;<\/strong><\/p>\n<hr \/>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/jo-2020-le-programme-complet-des-jeux-olympiques-de-tokyo\/\"><strong>Le programme complet des Jeux Olympiques de Tokyo<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>JO DE TOKYO 2020 &#8211; Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Voici le calendrier et les r\u00e9sultats de la comp\u00e9tition.<\/p>\n","protected":false},"author":12,"featured_media":147930,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8433,18143],"tags":[570],"class_list":["post-147098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-tokyo-2020","category-skateboard","tag-skateboard"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats<\/title>\n<meta name=\"description\" content=\"JO DE TOKYO 2020 - Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Calendrier et r\u00e9sultats de la comp\u00e9tition.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats\" \/>\n<meta property=\"og:description\" content=\"JO DE TOKYO 2020 - Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Calendrier et r\u00e9sultats de la comp\u00e9tition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-05T04:15:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-05T04:15:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Skateboard &#8211; Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats\",\"datePublished\":\"2021-08-05T04:15:13+00:00\",\"dateModified\":\"2021-08-05T04:15:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png\",\"keywords\":[\"skateboard\"],\"articleSection\":[\"JO Tokyo 2020\",\"Skateboard\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/\",\"name\":\"Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png\",\"datePublished\":\"2021-08-05T04:15:13+00:00\",\"dateModified\":\"2021-08-05T04:15:44+00:00\",\"description\":\"JO DE TOKYO 2020 - Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Calendrier et r\u00e9sultats de la comp\u00e9tition.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png\",\"width\":1200,\"height\":670,\"caption\":\"Skateboard - Jeux Olympiques de Tokyo calendrier et r\u00e9sultats\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skateboard &#8211; Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats","description":"JO DE TOKYO 2020 - Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Calendrier et r\u00e9sultats de la comp\u00e9tition.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/","og_locale":"fr_FR","og_type":"article","og_title":"Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats","og_description":"JO DE TOKYO 2020 - Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Calendrier et r\u00e9sultats de la comp\u00e9tition.","og_url":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-08-05T04:15:13+00:00","article_modified_time":"2021-08-05T04:15:44+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Skateboard &#8211; Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats","datePublished":"2021-08-05T04:15:13+00:00","dateModified":"2021-08-05T04:15:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png","keywords":["skateboard"],"articleSection":["JO Tokyo 2020","Skateboard"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/","url":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/","name":"Skateboard - Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png","datePublished":"2021-08-05T04:15:13+00:00","dateModified":"2021-08-05T04:15:44+00:00","description":"JO DE TOKYO 2020 - Les \u00e9preuves de skateboard aux Jeux Olympiques se d\u00e9roulent du 25 juillet au 5 ao\u00fbt. Calendrier et r\u00e9sultats de la comp\u00e9tition.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Skateboard-Jeux-Olympiques-de-Tokyo-calendrier-et-resultats.png","width":1200,"height":670,"caption":"Skateboard - Jeux Olympiques de Tokyo calendrier et r\u00e9sultats"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/skateboard-jeux-olympiques-tokyo-calendrier-et-resultats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Skateboard &#8211; Jeux Olympiques de Tokyo : calendrier et r\u00e9sultats"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/147098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=147098"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/147098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/147930"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=147098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=147098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=147098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}