{"id":148029,"date":"2021-07-20T15:57:02","date_gmt":"2021-07-20T13:57:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=148029"},"modified":"2021-07-20T16:50:05","modified_gmt":"2021-07-20T14:50:05","slug":"betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/","title":{"rendered":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco"},"content":{"rendered":"<p align=\"justify\"><em><b>BETCLIC \u00c9LITE &#8211; Excellente nouvelle pour l\u2019AS Monaco. La Roca Team a annonc\u00e9 ce mardi avoir enregistr\u00e9 la signature de Yakuba Ouattara pour la saison prochaine. C\u2019est la troisi\u00e8me fois que l\u2019international fran\u00e7ais de 29 ans retourne sur le Rocher.<\/b><\/em><\/p>\n<p align=\"justify\">L\u2019effectif de l\u2019<b>AS Monaco<\/b> pour la saison 2021-2022 continue \u00e0 prendre forme tout doucement. D\u00e9j\u00e0 bien garnie sur les postes 1 et 2 (Paris Lee, Rudy Demahis-Ballou, Danilo Andjusic, Rob Gray, Marcos Knight), l\u2019\u00e9quipe mon\u00e9gasque vient de compl\u00e9ter son poste 3 en officialisant l\u2019arriv\u00e9e de <b>Yakuba Ouattara<\/b>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"und\">&#x1f929;&#x1f60d;<br \/>\n&#x2764;&#xfe0f;&#x1f90d; <a href=\"https:\/\/t.co\/CN3xrPQ9p1\">pic.twitter.com\/CN3xrPQ9p1<\/a><\/p>\n<p>\u2014 AS Monaco Basket (@ASMonaco_Basket) <a href=\"https:\/\/twitter.com\/ASMonaco_Basket\/status\/1417443354271535105?ref_src=twsrc%5Etfw\">July 20, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\"><b>Un troisi\u00e8me passage \u00e0 l\u2019ASM<\/b><\/h2>\n<p align=\"justify\">A 29 ans, l\u2019international fran\u00e7ais est loin d\u2019\u00eatre un inconnu dans la Principaut\u00e9. Form\u00e9 \u00e0 l\u2019<b>\u00c9lan<\/b><b> Chalon<\/b>, il y a sign\u00e9 une premi\u00e8re fois en 2015 pour obtenir un r\u00f4le important en <b>Betclic <\/b><b>\u00c9lite<\/b> apr\u00e8s avoir r\u00e9alis\u00e9 un pr\u00eat concluant en Pro B, \u00e0 <b>Denain<\/b>. Durant deux saisons, il s\u2019impose alors comme l\u2019une des forces principales du collectif mon\u00e9gasque, r\u00e9alisant deux saisons de haute vol\u00e9e (12,9 points \u00e0 52\u00a0% au shoot, puis 11,7 points \u00e0 51%). Cela lui permet \u00e9galement d\u2019ouvrir son palmar\u00e8s en remportant deux<b> Leaders Cup<\/b> cons\u00e9cutives en 2016 et 2017. Il quitte une premi\u00e8re fois l\u2019ASM \u00e0 l\u2019\u00e9t\u00e9 2017 pour tenter sa chance en NBA, du c\u00f4t\u00e9 des Brooklyn Nets. Malheureusement, l\u2019international fran\u00e7ais n\u2019a jamais sa chance, et ne dispute que quelques rencontres de <b>G-League<\/b> avec les <b>Long Island Nets<\/b>.<\/p>\n<p align=\"justify\">En 2018, il revient donc au sein d\u2019une \u00e9quipe de <b>Monaco<\/b> plus forte, et plus ambitieuse. D\u00e8s la premi\u00e8re saison, il atteint donc les finales de Betclic \u00c9lite avant de disputer une deuxi\u00e8me saison interrompue par le Covid. Ensuite, il prend la direction de <b>S\u00e9ville<\/b> afin de d\u00e9couvrir un nouveau championnat, en Espagne. Au sein de la <b>Liga Endesa<\/b>, il dispose d\u2019une vingtaine de minutes par rencontre, mais ne parvient pas \u00e0 trouver la m\u00eame r\u00e9ussite connue auparavant en France (9 points, \u00e0 seulement 30\u00a0% derri\u00e8re l\u2019arc et 43\u00a0% en global).<\/p>\n<p><span class=\"ibqTCnGc04v9PSdz\"><iframe loading=\"lazy\" title=\"Yakuba Ouattara Highlights 2019\/2020 Monaco\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/07E5YK23YzM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\"><b>Les lignes ext\u00e9rieures mon\u00e9gasques au complet<\/b><\/h2>\n<p align=\"justify\">Cependant, <b>Yakuba Ouattara<\/b> reste un joueur de tr\u00e8s haut niveau. Appel\u00e9 en <strong>\u00e9<\/strong><b>quipe de France<\/b> lors de matchs internationaux disput\u00e9s sans les joueurs NBA et Euroleague, il avait notamment sign\u00e9 une superbe pointe \u00e0 24 points face \u00e0 l\u2019Allemagne en novembre dernier. Exp\u00e9riment\u00e9 et connaissant parfaitement l\u2019environnement, il devrait ainsi \u00eatre apte \u00e0 performer imm\u00e9diatement dans un r\u00f4le important. <b>Zvezdan Mitrovic<\/b> a ainsi le choix de le faire d\u00e9buter en tant qu\u2019ailier titulaire, ou bien en sortie de banc derri\u00e8re un <b>Danilo Andjusic<\/b> ou un <b>Marcos Knight<\/b> d\u00e9cal\u00e9s au poste 3. Derri\u00e8re, le jeune <b>Armel Traor\u00e9<\/b> compl\u00e8te la rotation sur le poste.<\/p>\n<p align=\"justify\">Le roster mon\u00e9gasque est donc bien rempli sur les postes ext\u00e9rieurs, et il ne manque plus qu\u2019\u00e0 construire d\u00e9sormais la raquette. Pour le moment, seuls <b>Ibrahima Fall Faye<\/b> et <b>Jerry Boutsiele<\/b> sont sous contrat. Encore libre, Mathias Lessort pourrait faire son retour afin de disputer l\u2019Euroleague, mais il faudra quoi qu\u2019il arrive engager deux \u00e0 trois joueurs suppl\u00e9mentaires afin d\u2019avoir une rotation cons\u00e9quente pour tenir la grosse cadence impos\u00e9e par le calendrier.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-les-principaux-enseignements-du-calendrier\/\">Ce qu&rsquo;il faut retenir du calendrier de la Betclic \u00c9lite 2021-2022<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>BETCLIC \u00c9LITE &#8211; Excellente nouvelle pour l\u2019AS Monaco. La Roca Team a annonc\u00e9 ce mardi avoir enregistr\u00e9 la signature de Yakuba Ouattara pour la saison prochaine. C\u2019est la troisi\u00e8me fois que l\u2019international fran\u00e7ais de 29 ans retourne sur le Rocher.<\/p>\n","protected":false},"author":55,"featured_media":148040,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46998],"tags":[17909,30,1678,12781],"class_list":["post-148029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-betclic-elite","tag-betclic-elite","tag-france","tag-monaco","tag-yakuba-ouattara"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco<\/title>\n<meta name=\"description\" content=\"D\u00e9j\u00e0 pass\u00e9 \u00e0 deux reprises sur le Rocher, Yakuba Ouattara vient de s&#039;engager une nouvelle fois avec l&#039;AS Monaco en Betclic Elite.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco\" \/>\n<meta property=\"og:description\" content=\"D\u00e9j\u00e0 pass\u00e9 \u00e0 deux reprises sur le Rocher, Yakuba Ouattara vient de s&#039;engager une nouvelle fois avec l&#039;AS Monaco en Betclic Elite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-20T13:57:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-20T14:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco\",\"datePublished\":\"2021-07-20T13:57:02+00:00\",\"dateModified\":\"2021-07-20T14:50:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png\",\"keywords\":[\"Betclic Elite\",\"France\",\"Monaco\",\"Yakuba Ouattara\"],\"articleSection\":[\"Betclic \u00c9lite\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/\",\"name\":\"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png\",\"datePublished\":\"2021-07-20T13:57:02+00:00\",\"dateModified\":\"2021-07-20T14:50:05+00:00\",\"description\":\"D\u00e9j\u00e0 pass\u00e9 \u00e0 deux reprises sur le Rocher, Yakuba Ouattara vient de s'engager une nouvelle fois avec l'AS Monaco en Betclic Elite.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png\",\"width\":800,\"height\":445,\"caption\":\"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco","description":"D\u00e9j\u00e0 pass\u00e9 \u00e0 deux reprises sur le Rocher, Yakuba Ouattara vient de s'engager une nouvelle fois avec l'AS Monaco en Betclic Elite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/","og_locale":"fr_FR","og_type":"article","og_title":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco","og_description":"D\u00e9j\u00e0 pass\u00e9 \u00e0 deux reprises sur le Rocher, Yakuba Ouattara vient de s'engager une nouvelle fois avec l'AS Monaco en Betclic Elite.","og_url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-07-20T13:57:02+00:00","article_modified_time":"2021-07-20T14:50:05+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco","datePublished":"2021-07-20T13:57:02+00:00","dateModified":"2021-07-20T14:50:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png","keywords":["Betclic Elite","France","Monaco","Yakuba Ouattara"],"articleSection":["Betclic \u00c9lite"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/","url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/","name":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png","datePublished":"2021-07-20T13:57:02+00:00","dateModified":"2021-07-20T14:50:05+00:00","description":"D\u00e9j\u00e0 pass\u00e9 \u00e0 deux reprises sur le Rocher, Yakuba Ouattara vient de s'engager une nouvelle fois avec l'AS Monaco en Betclic Elite.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Betclic-Elite-Yakuba-Ouattara-signe-son-retour-a-Monaco.png","width":800,"height":445,"caption":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-yakuba-ouattara-signe-son-retour-a-monaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Betclic Elite\u00a0: Yakuba Ouattara signe son retour \u00e0 Monaco"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/148029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=148029"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/148029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/148040"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=148029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=148029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=148029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}