{"id":149342,"date":"2021-07-24T15:01:36","date_gmt":"2021-07-24T13:01:36","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=149342"},"modified":"2022-10-05T16:59:45","modified_gmt":"2022-10-05T14:59:45","slug":"jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/","title":{"rendered":"JO Tokyo 2020 &#8211; Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&rsquo;Italie"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>JO TOKYO 2020 &#8211; BASKET 3&#215;3 &#8211; L&rsquo;\u00e9quipe de France a parfaitement r\u00e9agi pour sa deuxi\u00e8me rencontre du tournoi olympique. Malmen\u00e9e une bonne partie de la rencontre par l&rsquo;Italie, les Bleues ont r\u00e9agi avec autorit\u00e9 pour finalement l&#8217;emporter 19-16<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-logiquement-dominees-par-les-etats-unis\/\">Trois heures apr\u00e8s avoir subi une premi\u00e8re d\u00e9faite dans la comp\u00e9tition face aux <strong>Etats-Unis<\/strong><\/a>, l&rsquo;<strong>Equipe de France<\/strong> f\u00e9minine \u00e9tait oppos\u00e9e \u00e0 l&rsquo;<strong>Italie<\/strong> pour sa deuxi\u00e8me rencontre de la journ\u00e9e. Malgr\u00e9 ce premier revers, les Bleues n&rsquo;avaient pas encore de quoi s&rsquo;inqui\u00e9ter. Lors du <strong>TQO<\/strong>, elles avaient exactement connu la m\u00eame entame de comp\u00e9tition avant de d\u00e9crocher leur place \u00e0 <strong>Tokyo<\/strong>. Championne du monde en 2018, l&rsquo;Italie \u00e9tait un nouvel adversaire de poids pour <strong>Migna Tour\u00e9<\/strong> et ses partenaires.<\/p>\n<h2 style=\"text-align: justify;\">Un d\u00e9but de rencontre extr\u00eamement compliqu\u00e9<\/h2>\n<p style=\"text-align: justify;\">D&rsquo;entr\u00e9e de jeu, les Italiennes prennent rapidement l&rsquo;ascendant notamment gr\u00e2ce au poignet de velours de <strong>Giulia Rulli<\/strong>, et en ex\u00e9cutant avec fluidit\u00e9 leur jeu. Les premi\u00e8res secondes sont un v\u00e9ritable calvaire pour des Fran\u00e7aises qui subissent un terrible 5-0 stopp\u00e9 par une premi\u00e8re p\u00e9n\u00e9tration de <strong>Migna Tour\u00e9<\/strong>. La d\u00e9fense prend l&rsquo;eau et conc\u00e8de des points sur quasiment chaque possession tandis que l&rsquo;on n&rsquo;arrive pas \u00e0 trouver la solution balle en main pour mettre \u00e0 mal des Italiennes confiantes et agressives, \u00e0 l&rsquo;image d&rsquo;un nombre de fautes \u00e9lev\u00e9es (4 en deux minutes). Maladroites et totalement battues au rebond, les Bleues restent dans la partie gr\u00e2ce \u00e0 des cartouches g\u00e2ch\u00e9es par les Italiennes qui \u00e9crasent le d\u00e9but de rencontre.<\/p>\n<p style=\"text-align: justify;\">Progressivement, du liant est retrouv\u00e9 avec <strong>Migna Tour\u00e9<\/strong> \u00e0 la baguette pour servir avec plus de r\u00e9gularit\u00e9 <strong>Ana-Maria Filip<\/strong> au poste, cette derni\u00e8re ayant l&rsquo;avantage de taille. Auteure de 8 points face \u00e0 la Mongolie, <strong>Raelin Dalie<\/strong> poursuit son festival en mettant au fond ses tentatives pour tenir son \u00e9quipe \u00e0 distance.<\/p>\n<h2 style=\"text-align: justify;\">Guapo et Paget renversent le momentum derri\u00e8re l&rsquo;arc<\/h2>\n<p style=\"text-align: justify;\">Cependant, le trio fran\u00e7ais commence \u00e0 prendre le dessus en trouvant de l&rsquo;adresse. Migna Tour\u00e9 inscrit un gros deux points, suivi d&rsquo;un shoot dans le p\u00e9rim\u00e8tre de <strong>Marie-Eve Paget<\/strong> pour recoller \u00e0 un petit point. Plus intenses, les Bleues \u00e9galisent sur un shoot dans le coin de <strong>La\u00ebtitia Guapo<\/strong> \u00e0 2:30 de la fin du match avant que Marie-Eve Paget n&rsquo;encha\u00eene avec un autre panier derri\u00e8re l&rsquo;arc en d\u00e9s\u00e9quilibre !<\/p>\n<p style=\"text-align: justify;\">De 12-14, le score passe \u00e0 18-14 dans les deux derni\u00e8res minutes. La tendance a \u00e9t\u00e9 renvers\u00e9e et il ne reste plus qu&rsquo;\u00e0 mettre l&rsquo;estocade \u00e0 un adversaire dans le doute. L&rsquo;<strong>Italie<\/strong> s&rsquo;accroche malgr\u00e9 tout avec une Dalie toujours dangereuse qui leur permet de garder un dernier espoir. Mais les Bleues ne l\u00e2chent pas et finissent par assurer d\u00e9finitivement la victoire en d\u00e9fendant le plomb sur les derni\u00e8res s\u00e9quences. Elles l&#8217;emportent ainsi finalement 19-16 pour d\u00e9finitivement lancer leur tournoi, et oublier le premier revers essuy\u00e9 en fin de matin\u00e9e. Le prochain rendez-vous est d\u00e8s demain matin \u00e0 10h55 face au pays h\u00f4te, le <strong>Japon<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f6a8;&#x1f1eb;&#x1f1f7; Pour leur deuxi\u00e8me match de poule, nos Bleues s&rsquo;imposent 19 \u00e0 16 face aux italiennes.<\/p>\n<p>Rendez-vous demain \u00e0 10h55 (UTC+2&#x1f1eb;&#x1f1f7;) pour le prochain match face au Japon !<a href=\"https:\/\/twitter.com\/hashtag\/AllezLesBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezLesBleus<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/UneSeuleEquipe?src=hash&amp;ref_src=twsrc%5Etfw\">#UneSeuleEquipe<\/a> <a href=\"https:\/\/t.co\/Q8kfD0WBoI\">pic.twitter.com\/Q8kfD0WBoI<\/a><\/p>\n<p>\u2014 Equipe France (@EquipeFRA) <a href=\"https:\/\/twitter.com\/EquipeFRA\/status\/1418915589310099466?ref_src=twsrc%5Etfw\">July 24, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JO TOKYO 2020 &#8211; BASKET 3&#215;3 &#8211; L&rsquo;\u00e9quipe de France a parfaitement r\u00e9agi pour sa deuxi\u00e8me rencontre du tournoi olympique. Malmen\u00e9e une bonne partie de la rencontre par l&rsquo;Italie, les Bleues ont r\u00e9agi avec autorit\u00e9 pour finalement l&#8217;emporter 19-16<\/p>\n","protected":false},"author":55,"featured_media":149366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305,27116,8433],"tags":[9140],"class_list":["post-149342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","category-basket-ball-3x3","category-jo-tokyo-2020","tag-basket-3x3"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&#039;Italie<\/title>\n<meta name=\"description\" content=\"JO TOKYO 2020 - L&#039;\u00e9quipe de France f\u00e9minine de basket 3X3 a r\u00e9agi en remportant son deuxi\u00e8me match face \u00e0 l&#039;Italie apr\u00e8s avoir perdu le premier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&#039;Italie\" \/>\n<meta property=\"og:description\" content=\"JO TOKYO 2020 - L&#039;\u00e9quipe de France f\u00e9minine de basket 3X3 a r\u00e9agi en remportant son deuxi\u00e8me match face \u00e0 l&#039;Italie apr\u00e8s avoir perdu le premier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-24T13:01:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T14:59:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&#039;Italie\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"JO Tokyo 2020 &#8211; Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&rsquo;Italie\",\"datePublished\":\"2021-07-24T13:01:36+00:00\",\"dateModified\":\"2022-10-05T14:59:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png\",\"keywords\":[\"Basket 3x3\"],\"articleSection\":[\"Basket-ball\",\"Basket-ball 3x3\",\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/\",\"name\":\"JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l'Italie\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png\",\"datePublished\":\"2021-07-24T13:01:36+00:00\",\"dateModified\":\"2022-10-05T14:59:45+00:00\",\"description\":\"JO TOKYO 2020 - L'\u00e9quipe de France f\u00e9minine de basket 3X3 a r\u00e9agi en remportant son deuxi\u00e8me match face \u00e0 l'Italie apr\u00e8s avoir perdu le premier.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png\",\"width\":800,\"height\":445,\"caption\":\"Les Bleues en lice pour la qualifications en basket 3x3 - Photo Icon Sport\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JO Tokyo 2020 &#8211; Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&rsquo;Italie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l'Italie","description":"JO TOKYO 2020 - L'\u00e9quipe de France f\u00e9minine de basket 3X3 a r\u00e9agi en remportant son deuxi\u00e8me match face \u00e0 l'Italie apr\u00e8s avoir perdu le premier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/","og_locale":"fr_FR","og_type":"article","og_title":"JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l'Italie","og_description":"JO TOKYO 2020 - L'\u00e9quipe de France f\u00e9minine de basket 3X3 a r\u00e9agi en remportant son deuxi\u00e8me match face \u00e0 l'Italie apr\u00e8s avoir perdu le premier.","og_url":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-07-24T13:01:36+00:00","article_modified_time":"2022-10-05T14:59:45+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l'Italie","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"JO Tokyo 2020 &#8211; Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&rsquo;Italie","datePublished":"2021-07-24T13:01:36+00:00","dateModified":"2022-10-05T14:59:45+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png","keywords":["Basket 3x3"],"articleSection":["Basket-ball","Basket-ball 3x3","JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/","url":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/","name":"JO Tokyo 2020 - Basket 3X3 : Les Bleues r\u00e9agissent en renversant l'Italie","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png","datePublished":"2021-07-24T13:01:36+00:00","dateModified":"2022-10-05T14:59:45+00:00","description":"JO TOKYO 2020 - L'\u00e9quipe de France f\u00e9minine de basket 3X3 a r\u00e9agi en remportant son deuxi\u00e8me match face \u00e0 l'Italie apr\u00e8s avoir perdu le premier.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Basket-3X3-Les-Bleues-reagissent-en-renversant-lItalie.png","width":800,"height":445,"caption":"Les Bleues en lice pour la qualifications en basket 3x3 - Photo Icon Sport"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-basket-3x3-les-bleues-reagissent-en-renversant-litalie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"JO Tokyo 2020 &#8211; Basket 3X3 : Les Bleues r\u00e9agissent en renversant l&rsquo;Italie"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/149342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=149342"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/149342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/149366"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=149342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=149342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=149342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}