{"id":150189,"date":"2021-07-26T05:18:56","date_gmt":"2021-07-26T03:18:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=150189&#038;preview=true&#038;preview_id=150189"},"modified":"2021-07-26T07:23:35","modified_gmt":"2021-07-26T05:23:35","slug":"jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/","title":{"rendered":"JO Tokyo 2020 &#8211; Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>JO TOKYO 2020 &#8211; NATATION &#8211; La finale tant attendue du 4x100m homme a tenu toutes ses promesses avec des Fran\u00e7ais ambitieux face aux Am\u00e9ricains, Australiens et autres Italiens. Finalement, la troupe, emmen\u00e9e par Florent Manaudou, termine 6\u00e8me, loin derri\u00e8re les Am\u00e9ricains. Italie et Australie compl\u00e8tent le podium.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Les Fran\u00e7ais (<strong>Maxime Grousset<\/strong>, <strong>Florent Manaudou<\/strong>, <strong>Cl\u00e9ment Mignon<\/strong> et <strong>Mehdy Metella<\/strong>) sont au couloir num\u00e9ro 6. Apr\u00e8s un gros d\u00e9part des Am\u00e9ricains, une derni\u00e8re longueur de <strong>Grousset<\/strong> lui permet de transmettre le relais en 2<sup>\u00e8me<\/sup> place. <strong>Manaudou<\/strong> continue le travail en passant en t\u00eate aux 150 m mais ne peut r\u00e9sister au retour de l\u2019Am\u00e9ricain. <strong>Mignon<\/strong>, lanc\u00e9 3<sup>\u00e8me<\/sup>, ne tient finalement le rythme et l\u00e2che du terrain. <strong>Mehdy Metalla<\/strong> ne peut malheureusement pas revenir et laisse les Am\u00e9ricains, Italiens et Australiens s\u2019envoler pour le podium.<\/p>\n<p style=\"text-align: justify;\">Le quatuor tricolore termine finalement 6<sup>\u00e8me<\/sup>, \u00e0 2.12 secondes des champions olympiques am\u00e9ricains. Ces derniers, emmen\u00e9s par <strong>Caeleb Dressel<\/strong>, se sont montr\u00e9s finalement assez intouchables. Les surprenants Italiens se parent\u00a0 d\u2019argent devant les Australiens. Les Fran\u00e7ais devront se ressaisir sur leurs prochaines courses.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3ca; Les nageurs fran\u00e7ais du 4&#215;100 m\u00e8tres nage libre, apr\u00e8s un bon d\u00e9part, terminent \u00e0 la sixi\u00e8me place de la finale olympique.<\/p>\n<p>Caeleb Dressel, avec les USA, remporte son premier titre de la semaine <a href=\"https:\/\/twitter.com\/hashtag\/Tokyo2020?src=hash&amp;ref_src=twsrc%5Etfw\">#Tokyo2020<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/JeuxOlympiques?src=hash&amp;ref_src=twsrc%5Etfw\">#JeuxOlympiques<\/a><\/p>\n<p>Suivez les J.O. en direct &#x25b6; <a href=\"https:\/\/t.co\/sufil7RauY\">https:\/\/t.co\/sufil7RauY<\/a> <a href=\"https:\/\/t.co\/pyYFxTYaiT\">pic.twitter.com\/pyYFxTYaiT<\/a><\/p>\n<p>\u2014 France tv sport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1419497737175945216?ref_src=twsrc%5Etfw\">July 26, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-des-jeux-olympiques-de-tokyo-2020\/\"><strong>Toute l&rsquo;actualit\u00e9 des Jeux Olympiques de Tokyo<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/jeux-olympiques-tokyo-2020-le-tableau-des-medailles\/\"><strong>Le tableau des m\u00e9dailles<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>JO TOKYO 2020 &#8211; NATATION &#8211; La finale tant attendue du 4x100m homme a tenu toutes ses promesses avec des Fran\u00e7ais ambitieux face aux am\u00e9ricains, Australiens et autres Italiens. Finalement, la troupe, emmen\u00e9e par Florent Manaudou, termine 6\u00e8me, loin derri\u00e8re les Am\u00e9ricains. Italie et Australie compl\u00e8tent le podium.<\/p>\n","protected":false},"author":10,"featured_media":150202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8433],"tags":[9915,69],"class_list":["post-150189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-tokyo-2020","tag-jeux-olympiques-de-tokyo","tag-natation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains<\/title>\n<meta name=\"description\" content=\"JO TOKYO 2020 - NATATION - Les \u00c9tats-Unis ont remport\u00e9 le titre olympique sur le 4x100m nage libre, ce lundi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains\" \/>\n<meta property=\"og:description\" content=\"JO TOKYO 2020 - NATATION - Les \u00c9tats-Unis ont remport\u00e9 le titre olympique sur le 4x100m nage libre, ce lundi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-26T03:18:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T05:23:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Meunier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/DamienMeunier69\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/\"},\"author\":{\"name\":\"Damien Meunier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735\"},\"headline\":\"JO Tokyo 2020 &#8211; Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains\",\"datePublished\":\"2021-07-26T03:18:56+00:00\",\"dateModified\":\"2021-07-26T05:23:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png\",\"keywords\":[\"Jeux Olympiques de Tokyo\",\"natation\"],\"articleSection\":[\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/\",\"name\":\"JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png\",\"datePublished\":\"2021-07-26T03:18:56+00:00\",\"dateModified\":\"2021-07-26T05:23:35+00:00\",\"description\":\"JO TOKYO 2020 - NATATION - Les \u00c9tats-Unis ont remport\u00e9 le titre olympique sur le 4x100m nage libre, ce lundi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png\",\"width\":800,\"height\":445,\"caption\":\"JO Tokyo 2020 - Natation Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JO Tokyo 2020 &#8211; Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735\",\"name\":\"Damien Meunier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Damien Meunier\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis d\u00e9cembre 2016 - Amateur professionnel de sport, d\u2019abord le football, j\u2019aurais pu en faire mon m\u00e9tier. Mais bon, vous savez les \u2026 non, pas les crois\u00e9s, ils vont bien eux. Juste un manque de talent, de technique et de niveau surtout. Mais cette passion est ancr\u00e9e en moi telle la pomme dans la tarte tatin. Le c\u00f4t\u00e9 suiveur\/supporter est \u00e9videmment important au quotidien, que ce soit un soir de juillet 1998 en banlieue lyonnaise ou de juillet 2018 \u00e0 Montr\u00e9al. Car oui, depuis ma France natale, j\u2019ai migr\u00e9 outre-Atlantique, au pays des caribous. L\u00e0, le football se joue \u00e0 la main et non au pied. Et surtout, la religion sportive est plut\u00f4t froide et se joue avec une crosse. Non, ce n\u2019est pas le curling ni le Lacrosse, encore que, mais le hockey sur glace. Une autre vision, une autre culture. On troque les crudit\u00e9s devant la t\u00e9l\u00e9 pour une poutine et on s\u2019installe avec notre chandail pour suivre cela. Et en moins de temps qu\u2019il ne faut pour le dire, ou la vitesse d\u2019un slap shot de McDavid ou un arr\u00eat de la mitaine de Price, j\u2019\u00e9cris sur de l\u2019actualit\u00e9 par ici mais aussi le sport f\u00e9minin, pas assez mis en avant.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/x.com\/DamienMeunier69\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/damien-m\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains","description":"JO TOKYO 2020 - NATATION - Les \u00c9tats-Unis ont remport\u00e9 le titre olympique sur le 4x100m nage libre, ce lundi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/","og_locale":"fr_FR","og_type":"article","og_title":"JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains","og_description":"JO TOKYO 2020 - NATATION - Les \u00c9tats-Unis ont remport\u00e9 le titre olympique sur le 4x100m nage libre, ce lundi.","og_url":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-07-26T03:18:56+00:00","article_modified_time":"2021-07-26T05:23:35+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png","type":"image\/png"}],"author":"Damien Meunier","twitter_card":"summary_large_image","twitter_title":"JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains","twitter_creator":"@https:\/\/x.com\/DamienMeunier69","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/"},"author":{"name":"Damien Meunier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735"},"headline":"JO Tokyo 2020 &#8211; Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains","datePublished":"2021-07-26T03:18:56+00:00","dateModified":"2021-07-26T05:23:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png","keywords":["Jeux Olympiques de Tokyo","natation"],"articleSection":["JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/","url":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/","name":"JO Tokyo 2020 - Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png","datePublished":"2021-07-26T03:18:56+00:00","dateModified":"2021-07-26T05:23:35+00:00","description":"JO TOKYO 2020 - NATATION - Les \u00c9tats-Unis ont remport\u00e9 le titre olympique sur le 4x100m nage libre, ce lundi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/JO-Tokyo-2020-Natation-Le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-Americains.png","width":800,"height":445,"caption":"JO Tokyo 2020 - Natation Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-natation-le-4x100m-bleu-echoue-a-la-6eme-place-loin-des-americains\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"JO Tokyo 2020 &#8211; Natation : Le 4x100m bleu \u00e9choue \u00e0 la 6\u00e8me place, loin des Am\u00e9ricains"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735","name":"Damien Meunier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g","caption":"Damien Meunier"},"description":"Journaliste\/r\u00e9dacteur depuis d\u00e9cembre 2016 - Amateur professionnel de sport, d\u2019abord le football, j\u2019aurais pu en faire mon m\u00e9tier. Mais bon, vous savez les \u2026 non, pas les crois\u00e9s, ils vont bien eux. Juste un manque de talent, de technique et de niveau surtout. Mais cette passion est ancr\u00e9e en moi telle la pomme dans la tarte tatin. Le c\u00f4t\u00e9 suiveur\/supporter est \u00e9videmment important au quotidien, que ce soit un soir de juillet 1998 en banlieue lyonnaise ou de juillet 2018 \u00e0 Montr\u00e9al. Car oui, depuis ma France natale, j\u2019ai migr\u00e9 outre-Atlantique, au pays des caribous. L\u00e0, le football se joue \u00e0 la main et non au pied. Et surtout, la religion sportive est plut\u00f4t froide et se joue avec une crosse. Non, ce n\u2019est pas le curling ni le Lacrosse, encore que, mais le hockey sur glace. Une autre vision, une autre culture. On troque les crudit\u00e9s devant la t\u00e9l\u00e9 pour une poutine et on s\u2019installe avec notre chandail pour suivre cela. Et en moins de temps qu\u2019il ne faut pour le dire, ou la vitesse d\u2019un slap shot de McDavid ou un arr\u00eat de la mitaine de Price, j\u2019\u00e9cris sur de l\u2019actualit\u00e9 par ici mais aussi le sport f\u00e9minin, pas assez mis en avant.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/DamienMeunier69"],"url":"https:\/\/dicodusport.fr\/blog\/author\/damien-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/150189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=150189"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/150189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/150202"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=150189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=150189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=150189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}