{"id":152087,"date":"2021-07-29T11:12:47","date_gmt":"2021-07-29T09:12:47","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=152087&#038;preview=true&#038;preview_id=152087"},"modified":"2021-07-29T14:11:57","modified_gmt":"2021-07-29T12:11:57","slug":"mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/","title":{"rendered":"Mercato : Alexis Beka Beka se rapproche de la Ligue 1"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FOOTBALL MERCATO &#8211; Alexis Beka Beka, l&rsquo;une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Selon nos confr\u00e8res de <em>L&rsquo;\u00c9quipe<\/em>, le milieu de terrain de Caen, <strong>Alexis Beka Beka<\/strong>, va s&rsquo;engager dans les prochains jours avec l&rsquo;OGC Nice. Apr\u00e8s une saison pleine avec Caen et des JO int\u00e9ressants, Beka Beka ne manquait pas de propositions en Ligue 1, mais il aurait donn\u00e9 sa pr\u00e9f\u00e9rence \u00e0 Nice. Titulaire une fois et entr\u00e9 deux fois en jeu au Japon, il n&rsquo;a pas grand-chose \u00e0 se reprocher sur ses prestations pendant les JO, ayant montr\u00e9 de belles qualit\u00e9s. Si le transfert se confirme, il sera d\u00e9j\u00e0 la septi\u00e8me recrue de l&rsquo;OGC Nice apr\u00e8s Calvin Stengs, Justin Kluivert, Pablo Rosario, Mario Lemina, Melvin Bard et Jean-Clair Todibo.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">INFO L&rsquo;\u00c9QUIPE. Apr\u00e8s des Jeux Olympiques r\u00e9ussis, le milieu de Caen Alexis Beka Beka devrait \u00eatre transf\u00e9r\u00e9 \u00e0 Nice <a href=\"https:\/\/t.co\/TxpuJ8QhVB\">https:\/\/t.co\/TxpuJ8QhVB<\/a> <a href=\"https:\/\/t.co\/1hrENroNjB\">pic.twitter.com\/1hrENroNjB<\/a><\/p>\n<p>\u2014 L&rsquo;\u00c9QUIPE (@lequipe) <a href=\"https:\/\/twitter.com\/lequipe\/status\/1420656394911588354?ref_src=twsrc%5Etfw\">July 29, 2021<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FOOTBALL MERCATO &#8211; Alexis Beka Beka, l&rsquo;une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.<\/p>\n","protected":false},"author":1,"featured_media":152095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47045],"tags":[1554,460],"class_list":["post-152087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-ligue-1","tag-nice"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mercato : Alexis Beka Beka se rapproche de la Ligue 1<\/title>\n<meta name=\"description\" content=\"FOOTBALL MERCATO - Alexis Beka Beka, l&#039;une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercato : Alexis Beka Beka se rapproche de la Ligue 1\" \/>\n<meta property=\"og:description\" content=\"FOOTBALL MERCATO - Alexis Beka Beka, l&#039;une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-29T09:12:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-29T12:11:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mercato : Alexis Beka Beka se rapproche de la Ligue 1\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Mercato : Alexis Beka Beka se rapproche de la Ligue 1\",\"datePublished\":\"2021-07-29T09:12:47+00:00\",\"dateModified\":\"2021-07-29T12:11:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png\",\"keywords\":[\"Ligue 1\",\"Nice\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/\",\"name\":\"Mercato : Alexis Beka Beka se rapproche de la Ligue 1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png\",\"datePublished\":\"2021-07-29T09:12:47+00:00\",\"dateModified\":\"2021-07-29T12:11:57+00:00\",\"description\":\"FOOTBALL MERCATO - Alexis Beka Beka, l'une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercato : Alexis Beka Beka se rapproche de la Ligue 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mercato : Alexis Beka Beka se rapproche de la Ligue 1","description":"FOOTBALL MERCATO - Alexis Beka Beka, l'une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/","og_locale":"fr_FR","og_type":"article","og_title":"Mercato : Alexis Beka Beka se rapproche de la Ligue 1","og_description":"FOOTBALL MERCATO - Alexis Beka Beka, l'une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.","og_url":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-07-29T09:12:47+00:00","article_modified_time":"2021-07-29T12:11:57+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Mercato : Alexis Beka Beka se rapproche de la Ligue 1","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Mercato : Alexis Beka Beka se rapproche de la Ligue 1","datePublished":"2021-07-29T09:12:47+00:00","dateModified":"2021-07-29T12:11:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png","keywords":["Ligue 1","Nice"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/","url":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/","name":"Mercato : Alexis Beka Beka se rapproche de la Ligue 1","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png","datePublished":"2021-07-29T09:12:47+00:00","dateModified":"2021-07-29T12:11:57+00:00","description":"FOOTBALL MERCATO - Alexis Beka Beka, l'une des rares satisfactions fran\u00e7aises des Jeux Olympiques, devrait quitter Caen pour \u00e9voluer en Ligue 1.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Mercato-Alexis-Beka-Beka-se-rapproche-de-la-Ligue-1.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-se-rapproche-de-la-ligue-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mercato : Alexis Beka Beka se rapproche de la Ligue 1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/152087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=152087"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/152087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/152095"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=152087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=152087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=152087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}