{"id":153592,"date":"2021-08-01T08:00:09","date_gmt":"2021-08-01T06:00:09","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=153592"},"modified":"2021-08-01T20:48:35","modified_gmt":"2021-08-01T18:48:35","slug":"1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/","title":{"rendered":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/football\/\">FOOTBALL<\/a> &#8211; Il avait d\u00e9j\u00e0 annonc\u00e9 sa retraite internationale un mois auparavant. L\u2019\u00e9quipe de France, c\u2019est termin\u00e9 mais il reste alors \u00e0 Lilian Thuram un dernier challenge au PSG. Malheureusement le d\u00e9fenseur tricolore doit quitter les terrains.<\/strong> <\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 1er ao\u00fbt 2008<\/h2>\n<p style=\"text-align: justify;\">Juin 2008,<strong> Lilian Thuram<\/strong> quitte l\u2019\u00e9quipe de France apr\u00e8s 142 s\u00e9lections. Avec l\u2019intention de partir du FC Barcelone \u00e9galement, il trouve un nouveau club pr\u00eat \u00e0 l\u2019accueillir \u00e0 36 ans, le Paris Saint-Germain. Mais lors d\u2019une conf\u00e9rence de presse avec le club de la capitale, le d\u00e9fenseur s\u00e8me le doute. Suite aux diff\u00e9rents examens m\u00e9dicaux, un probl\u00e8me cardiaque lui a \u00e9t\u00e9 d\u00e9tect\u00e9. Il faut alors attendre un mois et des analyses plus pouss\u00e9es. Fin juillet les r\u00e9sultats tombent, les tests sont plus rassurants, la maladie moins grave que pr\u00e9vue.<\/p>\n<p style=\"text-align: justify;\">Mais <strong>Lilian Thuram<\/strong> ne veut pas prendre de risque ni inqui\u00e9ter sa famille davantage. Son fr\u00e8re ayant succomb\u00e9 de cette anomalie cardiaque, il d\u00e9cide de stopper d\u00e9finitivement sa carri\u00e8re. Une fin pr\u00e9matur\u00e9e -malgr\u00e9 ses 36 printemps- et difficile mais compr\u00e9hensible. Champion d\u2019Europe 2000, il reste \u00e9galement dans les m\u00e9moires fran\u00e7aises comme le grand artisan de la victoire des Bleus en Coupe du monde 1998. Ah ce doubl\u00e9 contre la Croatie en demi-finale \u2026 merci Monsieur !<\/p>\n<p><span class=\"pKbB18kOjm9P6laFDio25vu74sUENqYQC0SJcRw3TegIydHxzLrGVfXZnM\"><iframe loading=\"lazy\" title=\"France-Croatie 98 : Thuram raconte son doubl\u00e9 surr\u00e9aliste\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/Zz_28IX71Zc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: Encore aujourd\u2019hui recordman de s\u00e9lections en \u00e9quipe de France avec 142 unit\u00e9s, <strong>Lilian Thuram<\/strong> est suivi de pr\u00e8s par un certain <strong>Hugo Lloris<\/strong>. Ce dernier se rapproche avec la bagatelle de 129 s\u00e9lections.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 1er ao\u00fbt 2008, apr\u00e8s les r\u00e9sultats d&rsquo;examens m\u00e9dicaux, Lilian Thuram annonce mettre un terme \u00e0 sa carri\u00e8re de footballeur.<\/p>\n","protected":false},"author":18,"featured_media":153643,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301,8],"tags":[75],"class_list":["post-153592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-histoire","tag-football"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re<\/title>\n<meta name=\"description\" content=\"Le 1er ao\u00fbt 2008, apr\u00e8s les r\u00e9sultats d&#039;examens m\u00e9dicaux, Lilian Thuram annonce mettre un terme \u00e0 sa carri\u00e8re de footballeur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re\" \/>\n<meta property=\"og:description\" content=\"Le 1er ao\u00fbt 2008, apr\u00e8s les r\u00e9sultats d&#039;examens m\u00e9dicaux, Lilian Thuram annonce mettre un terme \u00e0 sa carri\u00e8re de footballeur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-01T06:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-01T18:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re\",\"datePublished\":\"2021-08-01T06:00:09+00:00\",\"dateModified\":\"2021-08-01T18:48:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png\",\"keywords\":[\"Football\"],\"articleSection\":[\"Football\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/\",\"name\":\"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png\",\"datePublished\":\"2021-08-01T06:00:09+00:00\",\"dateModified\":\"2021-08-01T18:48:35+00:00\",\"description\":\"Le 1er ao\u00fbt 2008, apr\u00e8s les r\u00e9sultats d'examens m\u00e9dicaux, Lilian Thuram annonce mettre un terme \u00e0 sa carri\u00e8re de footballeur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png\",\"width\":800,\"height\":445,\"caption\":\"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re","description":"Le 1er ao\u00fbt 2008, apr\u00e8s les r\u00e9sultats d'examens m\u00e9dicaux, Lilian Thuram annonce mettre un terme \u00e0 sa carri\u00e8re de footballeur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/","og_locale":"fr_FR","og_type":"article","og_title":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re","og_description":"Le 1er ao\u00fbt 2008, apr\u00e8s les r\u00e9sultats d'examens m\u00e9dicaux, Lilian Thuram annonce mettre un terme \u00e0 sa carri\u00e8re de footballeur.","og_url":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-08-01T06:00:09+00:00","article_modified_time":"2021-08-01T18:48:35+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re","datePublished":"2021-08-01T06:00:09+00:00","dateModified":"2021-08-01T18:48:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png","keywords":["Football"],"articleSection":["Football","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/","url":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/","name":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png","datePublished":"2021-08-01T06:00:09+00:00","dateModified":"2021-08-01T18:48:35+00:00","description":"Le 1er ao\u00fbt 2008, apr\u00e8s les r\u00e9sultats d'examens m\u00e9dicaux, Lilian Thuram annonce mettre un terme \u00e0 sa carri\u00e8re de footballeur.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/1er-aout-2008-Lilian-Thuram-met-un-terme-a-sa-carriere.png","width":800,"height":445,"caption":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/1er-aout-2008-lilian-thuram-met-un-terme-a-sa-carriere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"1er ao\u00fbt 2008 : Lilian Thuram met un terme \u00e0 sa carri\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/153592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=153592"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/153592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/153643"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=153592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=153592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=153592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}