{"id":154491,"date":"2021-08-03T05:00:01","date_gmt":"2021-08-03T03:00:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=154491&#038;preview=true&#038;preview_id=154491"},"modified":"2021-08-03T07:42:35","modified_gmt":"2021-08-03T05:42:35","slug":"jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/","title":{"rendered":"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020\/\">JO DE TOKYO 2020<\/a> &#8211; ATHL\u00c9TISME &#8211; D\u00e9couvrez le classement (top 8) du 400 m haies hommes des Jeux Olympiques de Tokyo, qui s&rsquo;est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.<\/em><\/strong><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">&#x1f3c5;<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>HURDLEURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1f3;&#x1f1f4; KARSTEN WARHOLM<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>45s94<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1fa;&#x1f1f8; RAI BENJAMIN<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>46s17<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1e7;&#x1f1f7; ALISON DOS SANTOS<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>46s72<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1fb;&#x1f1ec; KYRON MCMASTER<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>47s08<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1f6;&#x1f1e6; ABDERRAHMAN SAMBA<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>47s12<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6<\/span><span style=\"font-size: 0.9em\">.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1f9;&#x1f1f7; YASMANI COPELLO<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>47s81<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1ea;&#x1f1ea; RASMUS MAGI\u00a0<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>48s11<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1ee;&#x1f1f9; ALESSANDRO SIBILIO\u00a0<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>48s77<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-des-jeux-olympiques-de-tokyo-2020\/\"><strong>Toute l&rsquo;actualit\u00e9 des Jeux Olympiques de Tokyo<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/jeux-olympiques-tokyo-2020-le-tableau-des-medailles\/\"><strong>Le tableau des m\u00e9dailles<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>JO DE TOKYO 2020 &#8211; ATHL\u00c9TISME &#8211; D\u00e9couvrez le classement (top 8) du 400m haies hommes des Jeux Olympiques de Tokyo, qui s&rsquo;est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.<\/p>\n","protected":false},"author":1,"featured_media":154484,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308,8433],"tags":[143],"class_list":["post-154491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-jo-tokyo-2020","tag-athletisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes<\/title>\n<meta name=\"description\" content=\"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 400m haies hommes des Jeux Olympiques de Tokyo, qui s&#039;est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes\" \/>\n<meta property=\"og:description\" content=\"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 400m haies hommes des Jeux Olympiques de Tokyo, qui s&#039;est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-03T03:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-03T05:42:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes\",\"datePublished\":\"2021-08-03T03:00:01+00:00\",\"dateModified\":\"2021-08-03T05:42:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/\"},\"wordCount\":140,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png\",\"keywords\":[\"Athl\u00e9tisme\"],\"articleSection\":[\"Athl\u00e9tisme\",\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/\",\"name\":\"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png\",\"datePublished\":\"2021-08-03T03:00:01+00:00\",\"dateModified\":\"2021-08-03T05:42:35+00:00\",\"description\":\"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 400m haies hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes","description":"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 400m haies hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/","og_locale":"fr_FR","og_type":"article","og_title":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes","og_description":"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 400m haies hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.","og_url":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-08-03T03:00:01+00:00","article_modified_time":"2021-08-03T05:42:35+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes","datePublished":"2021-08-03T03:00:01+00:00","dateModified":"2021-08-03T05:42:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/"},"wordCount":140,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png","keywords":["Athl\u00e9tisme"],"articleSection":["Athl\u00e9tisme","JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/","url":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/","name":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png","datePublished":"2021-08-03T03:00:01+00:00","dateModified":"2021-08-03T05:42:35+00:00","description":"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 400m haies hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce mardi 3 ao\u00fbt.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-tokyo-2020-400m-haies-hommes.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-400-metres-haies-hommes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 400 m\u00e8tres haies hommes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/154491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=154491"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/154491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/154484"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=154491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=154491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=154491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}