{"id":156832,"date":"2021-08-07T14:30:35","date_gmt":"2021-08-07T12:30:35","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=156832&#038;preview=true&#038;preview_id=156832"},"modified":"2021-08-07T15:01:09","modified_gmt":"2021-08-07T13:01:09","slug":"jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/","title":{"rendered":"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 4&#215;400 m\u00e8tres hommes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020\/\">JO DE TOKYO 2020<\/a> &#8211; ATHL\u00c9TISME &#8211; D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s&rsquo;est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.<\/em><\/strong><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">&#x1f3c6;<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>PAYS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1fa;&#x1f1f8; \u00c9TATS-UNIS<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>2m55.70s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1f3;&#x1f1f1; PAYS-BAS<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>2m57.18s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1e7;&#x1f1fc; BOTSWANA<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>2m57.27s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1e7;&#x1f1ea; BELGIQUE<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>2m57.88s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1f5;&#x1f1f1; POLOGNE<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>2m58.46s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6<\/span><span style=\"font-size: 0.9em\">.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1ef;&#x1f1f2; JAMA\u00cfQUE<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>2m58.76s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">7.<\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1ee;&#x1f1f9; ITALIE<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>2m58.81s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\">8.<\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1f9;&#x1f1f9; TRINIT\u00c9-ET-TOBAGO<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>3m00.85s<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>JO DE TOKYO 2020 &#8211; ATHL\u00c9TISME &#8211; D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s&rsquo;est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.<\/p>\n","protected":false},"author":1,"featured_media":156751,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2308,8433],"tags":[143],"class_list":["post-156832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-jo-tokyo-2020","tag-athletisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes<\/title>\n<meta name=\"description\" content=\"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s&#039;est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes\" \/>\n<meta property=\"og:description\" content=\"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s&#039;est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-07T12:30:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-07T13:01:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-Tokyo-2020-4x400m-hommes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 4&#215;400 m\u00e8tres hommes\",\"datePublished\":\"2021-08-07T12:30:35+00:00\",\"dateModified\":\"2021-08-07T13:01:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/\"},\"wordCount\":126,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Classement-Tokyo-2020-4x400m-hommes.png\",\"keywords\":[\"Athl\u00e9tisme\"],\"articleSection\":[\"Athl\u00e9tisme\",\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/\",\"name\":\"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Classement-Tokyo-2020-4x400m-hommes.png\",\"datePublished\":\"2021-08-07T12:30:35+00:00\",\"dateModified\":\"2021-08-07T13:01:09+00:00\",\"description\":\"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Classement-Tokyo-2020-4x400m-hommes.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Classement-Tokyo-2020-4x400m-hommes.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 4&#215;400 m\u00e8tres hommes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes","description":"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/","og_locale":"fr_FR","og_type":"article","og_title":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes","og_description":"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.","og_url":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-08-07T12:30:35+00:00","article_modified_time":"2021-08-07T13:01:09+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-Tokyo-2020-4x400m-hommes.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 4&#215;400 m\u00e8tres hommes","datePublished":"2021-08-07T12:30:35+00:00","dateModified":"2021-08-07T13:01:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/"},"wordCount":126,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-Tokyo-2020-4x400m-hommes.png","keywords":["Athl\u00e9tisme"],"articleSection":["Athl\u00e9tisme","JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/","url":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/","name":"JO de Tokyo 2020 - Athl\u00e9tisme : le classement du 4x400 m\u00e8tres hommes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-Tokyo-2020-4x400m-hommes.png","datePublished":"2021-08-07T12:30:35+00:00","dateModified":"2021-08-07T13:01:09+00:00","description":"JO DE TOKYO 2020 - ATHL\u00c9TISME - D\u00e9couvrez le classement (top 8) du 4x400m hommes des Jeux Olympiques de Tokyo, qui s'est d\u00e9roul\u00e9 ce samedi 7 ao\u00fbt.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-Tokyo-2020-4x400m-hommes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Classement-Tokyo-2020-4x400m-hommes.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jo-de-tokyo-2020-athletisme-le-classement-du-4x400-metres-hommes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"JO de Tokyo 2020 &#8211; Athl\u00e9tisme : le classement du 4&#215;400 m\u00e8tres hommes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/156832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=156832"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/156832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/156751"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=156832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=156832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=156832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}