{"id":157028,"date":"2021-08-07T21:22:46","date_gmt":"2021-08-07T19:22:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=157028&#038;preview=true&#038;preview_id=157028"},"modified":"2021-08-07T21:22:46","modified_gmt":"2021-08-07T19:22:46","slug":"michael-guigou-je-suis-tres-tres-fier-de-cette-longevite","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/","title":{"rendered":"Micha\u00ebl Guigou : \u00ab\u00a0Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>JO TOKYO 2020 &#8211; HANDBALL &#8211; Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Capitaine de cette \u00e9quipe de France, <strong>Micha\u00ebl Guigou<\/strong> a particip\u00e9 aux quatre aventures olympiques pour trois m\u00e9dailles d&rsquo;or et une d&rsquo;argent. Juste apr\u00e8s le match, il savourait ce nouveau succ\u00e8s des Bleus au micro de <em>France T\u00e9l\u00e9visions<\/em> :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">J&rsquo;ai du mal \u00e0 r\u00e9aliser. C&rsquo;est une comp\u00e9tition particuli\u00e8re, sans public, o\u00f9 il faut encore aller chercher plus loin tous ensemble. C&rsquo;est une victoire incroyable. Personnellement, je finis comme \u00e7a. \u00catre capitaine, c&rsquo;est se poser beaucoup de questions pour le groupe. Sur le terrain, j&rsquo;ai essay\u00e9 d&rsquo;accompagner au maximum l&rsquo;\u00e9quipe.<\/p>\n<p style=\"text-align: justify;\">Sortir sur une m\u00e9daille d&rsquo;or olympique, c&rsquo;est une belle sortie aussi. Je suis tr\u00e8s fier de ce groupe qui s&rsquo;est servi de tout ce qu&rsquo;il avait pour aller chercher la m\u00e9daille d&rsquo;or. Je ne suis pas trop mat\u00e9rialiste mais je vais rassembler les m\u00e9dailles. Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9, d&rsquo;avoir su aider l&rsquo;\u00e9quipe dans des r\u00f4les diff\u00e9rents.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Seulement quatri\u00e8me du championnat du monde en janvier 2021, l&rsquo;\u00e9quipe de France a su rebondir pour aller chercher un nouveau sacre olympique.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f93e;&#x1f1eb;&#x1f1f7; Pour son dernier match en \u00e9quipe de France, Micha\u00ebl Guigou repart avec la m\u00e9daille d&rsquo;or et s&rsquo;en va par la grande porte.<\/p>\n<p>&#x1f5e3;&#xfe0f; \u00ab\u00a0Une victoire incroyable\u00a0\u00bb. Retrouvez la r\u00e9action du capitaine des Bleus &#x2b07; <a href=\"https:\/\/twitter.com\/hashtag\/JeuxOlympiques?src=hash&amp;ref_src=twsrc%5Etfw\">#JeuxOlympiques<\/a><\/p>\n<p>Suivez les J.O. en direct &#x25b6; <a href=\"https:\/\/t.co\/7m2qNzjpBb\">https:\/\/t.co\/7m2qNzjpBb<\/a> <a href=\"https:\/\/t.co\/GD8R2YKOu4\">pic.twitter.com\/GD8R2YKOu4<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1424004325026803716?ref_src=twsrc%5Etfw\">August 7, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-des-jeux-olympiques-de-tokyo-2020\/\"><strong>Toute l&rsquo;actualit\u00e9 des Jeux Olympiques de Tokyo<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/jeux-olympiques-tokyo-2020-le-tableau-des-medailles\/\"><strong>Le tableau des m\u00e9dailles<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>JO TOKYO 2020 &#8211; HANDBALL &#8211; Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.<\/p>\n","protected":false},"author":1,"featured_media":157030,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2304,8433],"tags":[405,9915],"class_list":["post-157028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handball","category-jo-tokyo-2020","tag-handball","tag-jeux-olympiques-de-tokyo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Micha\u00ebl Guigou : &quot;Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9&quot;<\/title>\n<meta name=\"description\" content=\"JO TOKYO 2020 - HANDBALL - Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Micha\u00ebl Guigou : &quot;Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9&quot;\" \/>\n<meta property=\"og:description\" content=\"JO TOKYO 2020 - HANDBALL - Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-07T19:22:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Micha\u00ebl Guigou : &quot;Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9&quot;\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Micha\u00ebl Guigou : \u00ab\u00a0Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\u00a0\u00bb\",\"datePublished\":\"2021-08-07T19:22:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png\",\"keywords\":[\"Handball\",\"Jeux Olympiques de Tokyo\"],\"articleSection\":[\"Handball\",\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/\",\"name\":\"Micha\u00ebl Guigou : \\\"Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png\",\"datePublished\":\"2021-08-07T19:22:46+00:00\",\"description\":\"JO TOKYO 2020 - HANDBALL - Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Micha\u00ebl Guigou : \u00ab\u00a0Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Micha\u00ebl Guigou : \"Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\"","description":"JO TOKYO 2020 - HANDBALL - Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/","og_locale":"fr_FR","og_type":"article","og_title":"Micha\u00ebl Guigou : \"Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\"","og_description":"JO TOKYO 2020 - HANDBALL - Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.","og_url":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-08-07T19:22:46+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Micha\u00ebl Guigou : \"Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\"","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Micha\u00ebl Guigou : \u00ab\u00a0Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\u00a0\u00bb","datePublished":"2021-08-07T19:22:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png","keywords":["Handball","Jeux Olympiques de Tokyo"],"articleSection":["Handball","JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/","url":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/","name":"Micha\u00ebl Guigou : \"Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png","datePublished":"2021-08-07T19:22:46+00:00","description":"JO TOKYO 2020 - HANDBALL - Champion olympique pour la troisi\u00e8me fois, Micha\u00ebl Guigou tire sa r\u00e9v\u00e9rence internationale au sommet.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Michae\u0308l-Guigou-Je-suis-tre\u0300s-tre\u0300s-fier-de-cette-longe\u0301vite\u0301.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/michael-guigou-je-suis-tres-tres-fier-de-cette-longevite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Micha\u00ebl Guigou : \u00ab\u00a0Je suis tr\u00e8s tr\u00e8s fier de cette long\u00e9vit\u00e9\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/157028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=157028"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/157028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/157030"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=157028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=157028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=157028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}