{"id":157136,"date":"2021-08-08T05:08:08","date_gmt":"2021-08-08T03:08:08","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=157136"},"modified":"2021-08-08T07:38:15","modified_gmt":"2021-08-08T05:38:15","slug":"jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/","title":{"rendered":"JO Tokyo 2020 &#8211; Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif;\"><strong><em>JO TOKYO 2020 &#8211; CYCLISME SUR PISTE &#8211; Cinqui\u00e8me du keirin, Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova. Lee Wai-sze a pris la m\u00e9daille de bronze dans la petite finale.<br \/>\n<\/em><\/strong><\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif;\">Les jambes surpassent la t\u00eate en finale<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif;\">La maligne <strong>Olena Starikova<\/strong> et la puissante <strong>Kelsey Mitchell<\/strong> \u00e9taient les deux finalistes. <strong>Mitchell<\/strong> a emmen\u00e9 tout le sprint et a r\u00e9ussi \u00e0 prendre de la s\u00e9curit\u00e9 sur l&rsquo;Ukrainienne pour la derni\u00e8re ligne droite. Sur la deuxi\u00e8me manche, la Canadienne a parfaitement g\u00e9r\u00e9 les d\u00e9bats.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif;\">Pour la m\u00e9daille de bronze, <strong>Lee Wai-sze<\/strong> a surpris <strong>Hinze<\/strong> dans la ligne droite oppos\u00e9e et a domin\u00e9 l&rsquo;Allemande. M\u00eame si elle a attaqu\u00e9 plus tard, Hinze a \u00e9t\u00e9 domin\u00e9e par Lee Wai-Sze.<br \/>\n<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f6b4;&#x1f947; Cinqui\u00e8me du keirin il y a quelques jours, la &#x1f1e8;&#x1f1e6; Kelsey Mitchell devient championne olympique de la vitesse individuelle !<\/p>\n<p>Elle s&rsquo;impose en deux manches face \u00e0 l\u2019&#x1f1fa;&#x1f1e6; Olena Starikova <a href=\"https:\/\/twitter.com\/hashtag\/JeuxOlympiques?src=hash&amp;ref_src=twsrc%5Etfw\">#JeuxOlympiques<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Tokyo2020?src=hash&amp;ref_src=twsrc%5Etfw\">#Tokyo2020<\/a><\/p>\n<p>Suivez les J.O. en direct &#x25b6; <a href=\"https:\/\/t.co\/pCKRdHbCMe\">https:\/\/t.co\/pCKRdHbCMe<\/a> <a href=\"https:\/\/t.co\/c6Nx3MRJFj\">pic.twitter.com\/c6Nx3MRJFj<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1424203345279991811?ref_src=twsrc%5Etfw\">August 8, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif;\">Deux demi-finales atypiques<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif;\">Sur la premi\u00e8re demi-finale, <strong>Olena Starikova<\/strong> et <strong>Lee Wai-sze<\/strong> \u00e9taient deux femmes pass\u00e9es par les rep\u00eachages. L&rsquo;Ukrainienne a r\u00e9alis\u00e9 la m\u00eame tactique en se calant dans la roue de son adversaire pour la sauter dans la derni\u00e8re ligne droite sur la premi\u00e8re manche en 11 secondes 86 centi\u00e8mes. Apr\u00e8s un long moment d&rsquo;observation, <strong>Starikova<\/strong> a pris les devants \u00e0 1 tour et demi pour s&rsquo;imposer largement en 10 secondes 890.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif;\">Dans la seconde demi-finale, <strong>Kelsey Mitchell<\/strong> a domin\u00e9 la premi\u00e8re manche en 10 secondes 926 alors que <strong>Emma Hinze<\/strong> a tent\u00e9 de lancer de loin. Hinze a profit\u00e9 du manque d&rsquo;attention de la Canadienne pour gagner largement la deuxi\u00e8me manche en 10 secondes 998. Pour la belle, Mitchell a corrig\u00e9 son erreur et a emmen\u00e9 un sprint tr\u00e8s intense et tout en puissance en 10 secondes 728. <\/span><\/p>\n<h2><span style=\"font-family: georgia, palatino, serif;\">\u00c0 lire aussi<\/span><\/h2>\n<ul>\n<li><span style=\"font-family: georgia, palatino, serif;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-des-jeux-olympiques-de-tokyo-2020\/\"><strong>Toute l&rsquo;actualit\u00e9 des Jeux Olympiques de Tokyo<\/strong><\/a><\/span><\/li>\n<li><span style=\"font-family: georgia, palatino, serif;\"><a href=\"https:\/\/dicodusport.fr\/blog\/jeux-olympiques-tokyo-2020-le-tableau-des-medailles\/\"><strong>Le tableau des m\u00e9dailles<\/strong><\/a><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>JO TOKYO 2020 &#8211; CYCLISME SUR PISTE &#8211; Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova. Lee Wai-sze a pros la m\u00e9daille de bronze dans la petite finale.<\/p>\n","protected":false},"author":48,"featured_media":157142,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[14089,8433],"tags":[9915],"class_list":["post-157136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-piste","category-jo-tokyo-2020","tag-jeux-olympiques-de-tokyo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle<\/title>\n<meta name=\"description\" content=\"JO TOKYO 2020 - CYCLISME SUR PISTE - Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle\" \/>\n<meta property=\"og:description\" content=\"JO TOKYO 2020 - CYCLISME SUR PISTE - Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-08T03:08:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-08T05:38:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"JO Tokyo 2020 &#8211; Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle\",\"datePublished\":\"2021-08-08T03:08:08+00:00\",\"dateModified\":\"2021-08-08T05:38:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/\"},\"wordCount\":381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png\",\"keywords\":[\"Jeux Olympiques de Tokyo\"],\"articleSection\":[\"Cyclisme sur piste\",\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/\",\"name\":\"JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png\",\"datePublished\":\"2021-08-08T03:08:08+00:00\",\"dateModified\":\"2021-08-08T05:38:15+00:00\",\"description\":\"JO TOKYO 2020 - CYCLISME SUR PISTE - Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png\",\"width\":800,\"height\":445,\"caption\":\"JO Tokyo 2020 - Cyclisme sur piste Kelsey Mitchell championne olympique de la vitesse individuelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JO Tokyo 2020 &#8211; Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle","description":"JO TOKYO 2020 - CYCLISME SUR PISTE - Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/","og_locale":"fr_FR","og_type":"article","og_title":"JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle","og_description":"JO TOKYO 2020 - CYCLISME SUR PISTE - Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova.","og_url":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2021-08-08T03:08:08+00:00","article_modified_time":"2021-08-08T05:38:15+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"JO Tokyo 2020 &#8211; Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle","datePublished":"2021-08-08T03:08:08+00:00","dateModified":"2021-08-08T05:38:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/"},"wordCount":381,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png","keywords":["Jeux Olympiques de Tokyo"],"articleSection":["Cyclisme sur piste","JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/","url":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/","name":"JO Tokyo 2020 - Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png","datePublished":"2021-08-08T03:08:08+00:00","dateModified":"2021-08-08T05:38:15+00:00","description":"JO TOKYO 2020 - CYCLISME SUR PISTE - Kelsey Mitchell est devenue championne olympique de la vitesse chez les femmes en battant en finale Olena Starikova.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/JO-Tokyo-2020-Cyclisme-sur-piste-Kelsey-Mitchell-championne-olympique-de-la-vitesse-individuelle.png","width":800,"height":445,"caption":"JO Tokyo 2020 - Cyclisme sur piste Kelsey Mitchell championne olympique de la vitesse individuelle"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jo-tokyo-2020-cyclisme-sur-piste-kelsey-mitchell-championne-olympique-de-la-vitesse-individuelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"JO Tokyo 2020 &#8211; Cyclisme sur piste : Kelsey Mitchell championne olympique de la vitesse individuelle"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/157136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=157136"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/157136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/157142"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=157136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=157136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=157136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}