{"id":158059,"date":"2021-08-13T08:26:37","date_gmt":"2021-08-13T06:26:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=158059&#038;preview=true&#038;preview_id=158059"},"modified":"2021-08-13T11:30:08","modified_gmt":"2021-08-13T09:30:08","slug":"13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/","title":{"rendered":"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/athletisme\/\">ATHLETISME<\/a> &#8211; Qui l\u2019e\u00fbt cru ? Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. Ils \u2013 peuvent \u2013 croire &#8211; au podium, on est loin d\u2019une certitude de m\u00e9daille d\u2019or, la troisi\u00e8me place, on prend. Et pourtant !<\/strong> <\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 13 ao\u00fbt 2005<\/h2>\n<p style=\"text-align: justify;\">Incroyable, les Am\u00e9ricains ne sont pas en finale du relais 4 x 100 m masculin. Une erreur lors du passage de t\u00e9moin lors des demies et <strong>Maurice Green<\/strong> et ses co\u00e9quipiers sont d\u00e9finitivement out. Le podium est alors accessible pour les Fran\u00e7ais. Mais la plus haute marche du podium semble promise \u00e0 d\u2019autres. Jama\u00efque, Angleterre, Trinit\u00e9 et Tobago sont les principales nations favorites. Top d\u00e9part, c\u2019est <strong>Ladji Doucour\u00e9<\/strong> qui lance le relais tricolore, lui qui a appris sa participation \u00e0 cette course le matin m\u00eame. La transmission avec <strong>Ronald Pognon<\/strong> est parfaite, le sprint d\u2019<strong>Eddy De L\u00e9pine<\/strong> exceptionnel. Lorsque <strong>Lueyi Dovy<\/strong> prend le d\u00e9part pour les 100 derniers m\u00e8tres, il m\u00e8ne la course. Et malgr\u00e9 le retour de ses adversaires, il conserve cette avance pour franchir la ligne d\u2019arriv\u00e9e en t\u00eate. Mais oui Messieurs, vous \u00eates les premiers champions du monde fran\u00e7ais sur cette distance, savourez !<\/p>\n<p><span class=\"8F4Za3oq6zQcAUe0kpTCRVl9GgBmuHMsD5dvNwx\"><iframe loading=\"lazy\" title=\"Relais 4x100m Championnat du Monde Helsinki 2005 FR\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/H5j5pg2d21A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Info <\/strong>: Pour marquer un peu plus de leur empreinte ces Championnats du monde, les sprinteurs fran\u00e7ais ont r\u00e9alis\u00e9 la meilleure marque mondiale de la saison en 38.08.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ATHLETISME &#8211; Qui l\u2019e\u00fbt cru ? Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. Ils \u2013 peuvent \u2013 croire &#8211; au podium, on est loin d\u2019une certitude de m\u00e9daille d\u2019or, la troisi\u00e8me place, on prend. Et pourtant !<\/p>\n","protected":false},"author":18,"featured_media":158063,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2308,8],"tags":[143,8481],"class_list":["post-158059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-histoire","tag-athletisme","tag-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais<\/title>\n<meta name=\"description\" content=\"ATHLETISME - Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. On est loin d\u2019une certitude de m\u00e9daille d\u2019or.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais\" \/>\n<meta property=\"og:description\" content=\"ATHLETISME - Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. On est loin d\u2019une certitude de m\u00e9daille d\u2019or.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-13T06:26:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-13T09:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais\",\"datePublished\":\"2021-08-13T06:26:37+00:00\",\"dateModified\":\"2021-08-13T09:30:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/\"},\"wordCount\":267,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png\",\"keywords\":[\"Athl\u00e9tisme\",\"histoire\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/\",\"name\":\"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png\",\"datePublished\":\"2021-08-13T06:26:37+00:00\",\"dateModified\":\"2021-08-13T09:30:08+00:00\",\"description\":\"ATHLETISME - Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. On est loin d\u2019une certitude de m\u00e9daille d\u2019or.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png\",\"width\":800,\"height\":445,\"caption\":\"13 ao\u00fbt 2005 L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais","description":"ATHLETISME - Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. On est loin d\u2019une certitude de m\u00e9daille d\u2019or.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/","og_locale":"fr_FR","og_type":"article","og_title":"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais","og_description":"ATHLETISME - Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. On est loin d\u2019une certitude de m\u00e9daille d\u2019or.","og_url":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-08-13T06:26:37+00:00","article_modified_time":"2021-08-13T09:30:08+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais","datePublished":"2021-08-13T06:26:37+00:00","dateModified":"2021-08-13T09:30:08+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/"},"wordCount":267,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png","keywords":["Athl\u00e9tisme","histoire"],"articleSection":["Athl\u00e9tisme","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/","url":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/","name":"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png","datePublished":"2021-08-13T06:26:37+00:00","dateModified":"2021-08-13T09:30:08+00:00","description":"ATHLETISME - Apr\u00e8s les s\u00e9ries des Mondiaux d\u2019athl\u00e9tisme 2005, les Bleus peuvent croire au podium. On est loin d\u2019une certitude de m\u00e9daille d\u2019or.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/13-aout-2005-Lor-mondial-pour-le-relais-4-x-100-m-masculin-francais.png","width":800,"height":445,"caption":"13 ao\u00fbt 2005 L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/13-aout-2005-or-mondial-relais-4-x-100-m-masculin-francais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"13 ao\u00fbt 2005 : L\u2019or mondial pour le relais 4 x 100 m masculin fran\u00e7ais"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/158059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=158059"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/158059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/158063"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=158059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=158059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=158059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}