{"id":160456,"date":"2021-08-27T22:42:35","date_gmt":"2021-08-27T20:42:35","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=160456"},"modified":"2021-08-27T22:53:04","modified_gmt":"2021-08-27T20:53:04","slug":"tour-espagne-2021-14eme-etape-le-parcours-en-detail","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/","title":{"rendered":"Tour d&rsquo;Espagne 2021 &#8211; 14\u00e8me \u00e9tape : le parcours en d\u00e9tail"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\"><strong>CYCLISME &#8211; TOUR D&rsquo;ESPAGNE 2021 &#8211; La 14\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2021 partira de Don Benito et s&rsquo;ach\u00e8vera au Pico Villuercas avec une arriv\u00e9e au sommet apr\u00e8s 165,7 kilom\u00e8tres. 3500 m\u00e8tres de d\u00e9nivel\u00e9 seront au programme <span class=\"goog-text-highlight\">en <\/span><span class=\"goog-text-highlight\">Estr\u00e9madure<\/span>.\u00a0<\/strong> <\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">D&rsquo;abord, le d\u00e9part sera donn\u00e9 depuis <strong>Don Bonito<\/strong>, ville qui a accueilli le sprint bonification de la veille. Ensuite, les coureurs seront sur des routes plates via de grandes lignes droites sur les 50 premiers kilom\u00e8tres. Pour atteindre <strong>Ca\u00f1amero<\/strong>, les coureurs tourneront \u00e0 gauche pour aller sur des routes plus techniques sur 30 kilom\u00e8tres avec un long faux-plat montant pour arriver \u00e0 600 m\u00e8tres d&rsquo;altitude. <\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">Les coureurs rejoindront la premi\u00e8re mont\u00e9e apr\u00e8s 79 kilom\u00e8tres de course. Le <strong>Puerto Berzocana<\/strong> est une mont\u00e9e r\u00e9guli\u00e8re de 7,7 kilom\u00e8tres \u00e0 5,2% et suivi de peu, sans r\u00e9elle descente, par l&rsquo;<strong>Alto Collado de Ballesteros<\/strong>, une ascension courte et abrupte sur une route \u00e9troite en b\u00e9ton. La mont\u00e9e de 2,8 kilom\u00e8tres aura un pourcentage moyen de 14%. Quasiment au milieu de cette mont\u00e9e, les coureurs feront face \u00e0 des rampes \u00e0 20 %.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><strong>Les leaders \u00e0 la bagarre dans le final<\/strong><\/h2>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">Puis, la descente de 13 kilom\u00e8tres m\u00e8nera les coureurs \u00e0 <strong>Guadalupe<\/strong> pour une longue boucle assez vallonn\u00e9e sur pr\u00e8s de 40 kilom\u00e8tres pour revenir \u00e0 <strong>Guadalupe<\/strong> avant de s&rsquo;engager dans un circuit local bossel\u00e9. Ces trois bosses seront longues de 2,9 km \u00e0 6,3 % apr\u00e8s la travers\u00e9e d&rsquo;<strong>Alia<\/strong>, de 2,4 km \u00e0 5,4 % et de 1,8 km \u00e0 5,6 % avant de revenir sur la ville connue pour le monast\u00e8re royal de Santa Mar\u00eda de Guadalupe.<br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">Par la suite, les coureurs r\u00e9utiliseront la descente du <strong>Collado de Ballesteros<\/strong> mais dans le sens de la mont\u00e9e. Les 6 premiers kilom\u00e8tres seront assez irr\u00e9guliers entre 4 et 8 % Au milieu du col, il y aura un kilom\u00e8tre \u00e0 pr\u00e8s de 10 % avant de voir la pente s&rsquo;adoucir jusqu&rsquo;\u00e0 une portion plate apr\u00e8s 10 kilom\u00e8tres d&rsquo;ascension. La pente redeviendra difficile avec des pourcentages autour des 8 % sur deux kilom\u00e8tres pour rejoindre le sommet du <strong>Collado de Ballesteros<\/strong>. <\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">Mais, les coureurs tourneront \u00e0 gauche pour atteindre le <strong>Pico Villuercas<\/strong> sur une route \u00e9troite menant aux installations militaires abandonn\u00e9es au sommet. La pente atteindra 15% juste avant la ligne d&rsquo;arriv\u00e9e \u00e0 1580 m\u00e8tres d&rsquo;altitude. Le <strong>Pico Villuerca<\/strong> est le plus haut sommet de la Sierra de Guadalupe et aussi le point culminant du grand syst\u00e8me <span class=\"\">des <\/span><span class=\"\">Montes de Tol\u00e8de<\/span>. Ce syst\u00e8me est une cha\u00eene de montagne dans le sous-plateau sud de la p\u00e9ninsule ib\u00e9rique.<br \/>\n<\/span><\/p>\n<h2 style=\"text-align: justify;\"><strong>Le profil du Pico Villuercas<\/strong><\/h2>\n<div id=\"attachment_161905\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Le-profil-du-Pico-Villuercas.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-161905\" class=\"wp-image-161905 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Le-profil-du-Pico-Villuercas.jpg\" alt=\"Le profil du Pico Villuercas\" width=\"500\" height=\"497\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Le-profil-du-Pico-Villuercas.jpg 500w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Le-profil-du-Pico-Villuercas-300x298.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Le-profil-du-Pico-Villuercas-150x150.jpg 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Le-profil-du-Pico-Villuercas-80x80.jpg 80w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-161905\" class=\"wp-caption-text\">Le profil du Pico Villuercas &#8211; ASO<\/p><\/div>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi\u00a0<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-profil-14eme-etape\/\"><strong>Le profil de la 14\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2021-nos-favoris-pour-la-14eme-etape\/\">Nos favoris pour la 14\u00e8me \u00e9tape<\/a>\u00a0<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; TOUR D&rsquo;ESPAGNE 2021 &#8211; La 14\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2021 partira de Don Benito et s&rsquo;ach\u00e8vera au Pico Villuercas avec une arriv\u00e9e au sommet apr\u00e8s 165,7 kilom\u00e8tres. 3500 m\u00e8tres de d\u00e9nivel\u00e9 seront au programme en Estr\u00e9madure.\u00a0<\/p>\n","protected":false},"author":48,"featured_media":161909,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47042],"tags":[3119],"class_list":["post-160456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-actualite-cyclisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail<\/title>\n<meta name=\"description\" content=\"CYCLISME - TOUR D&#039;ESPAGNE 2021 - La 14\u00e8me \u00e9tape du Tour d&#039;Espagne 2021 partira de Don Benito et s&#039;ach\u00e8vera au Pico Villuercas. Le parcours.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - TOUR D&#039;ESPAGNE 2021 - La 14\u00e8me \u00e9tape du Tour d&#039;Espagne 2021 partira de Don Benito et s&#039;ach\u00e8vera au Pico Villuercas. Le parcours.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-27T20:42:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-27T20:53:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Tour d&rsquo;Espagne 2021 &#8211; 14\u00e8me \u00e9tape : le parcours en d\u00e9tail\",\"datePublished\":\"2021-08-27T20:42:35+00:00\",\"dateModified\":\"2021-08-27T20:53:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png\",\"keywords\":[\"Actualit\u00e9 Cyclisme\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/\",\"name\":\"Tour d'Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png\",\"datePublished\":\"2021-08-27T20:42:35+00:00\",\"dateModified\":\"2021-08-27T20:53:04+00:00\",\"description\":\"CYCLISME - TOUR D'ESPAGNE 2021 - La 14\u00e8me \u00e9tape du Tour d'Espagne 2021 partira de Don Benito et s'ach\u00e8vera au Pico Villuercas. Le parcours.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png\",\"width\":1200,\"height\":670,\"caption\":\"Tour d'Espagne 2021 le parcours de la 14\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&rsquo;Espagne 2021 &#8211; 14\u00e8me \u00e9tape : le parcours en d\u00e9tail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail","description":"CYCLISME - TOUR D'ESPAGNE 2021 - La 14\u00e8me \u00e9tape du Tour d'Espagne 2021 partira de Don Benito et s'ach\u00e8vera au Pico Villuercas. Le parcours.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail","og_description":"CYCLISME - TOUR D'ESPAGNE 2021 - La 14\u00e8me \u00e9tape du Tour d'Espagne 2021 partira de Don Benito et s'ach\u00e8vera au Pico Villuercas. Le parcours.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2021-08-27T20:42:35+00:00","article_modified_time":"2021-08-27T20:53:04+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Tour d&rsquo;Espagne 2021 &#8211; 14\u00e8me \u00e9tape : le parcours en d\u00e9tail","datePublished":"2021-08-27T20:42:35+00:00","dateModified":"2021-08-27T20:53:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png","keywords":["Actualit\u00e9 Cyclisme"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/","url":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/","name":"Tour d'Espagne 2021 - 14\u00e8me \u00e9tape : le parcours en d\u00e9tail","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png","datePublished":"2021-08-27T20:42:35+00:00","dateModified":"2021-08-27T20:53:04+00:00","description":"CYCLISME - TOUR D'ESPAGNE 2021 - La 14\u00e8me \u00e9tape du Tour d'Espagne 2021 partira de Don Benito et s'ach\u00e8vera au Pico Villuercas. Le parcours.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Tour-dEspagne-2021-le-parcours-de-la-14eme-etape.png","width":1200,"height":670,"caption":"Tour d'Espagne 2021 le parcours de la 14\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-espagne-2021-14eme-etape-le-parcours-en-detail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&rsquo;Espagne 2021 &#8211; 14\u00e8me \u00e9tape : le parcours en d\u00e9tail"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/160456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=160456"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/160456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/161909"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=160456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=160456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=160456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}