{"id":160618,"date":"2021-08-24T18:20:38","date_gmt":"2021-08-24T16:20:38","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=160618&#038;preview=true&#038;preview_id=160618"},"modified":"2021-08-25T10:41:51","modified_gmt":"2021-08-25T08:41:51","slug":"jeux-paralympiques-tokyo-2020-programme-francais-25-aout","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/","title":{"rendered":"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-des-jeux-paralympiques-de-tokyo-2020\/\">JEUX PARALYMPIQUES DE TOKYO 2020<\/a> &#8211; Chaque jour, retrouvez tous les athl\u00e8tes tricolores en lice aux Jeux Paralympiques. Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les Fran\u00e7ais en lice le 25 ao\u00fbt<\/h2>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 2h : Escrime fauteuil &#8211; Sabre individuel hommes cat\u00e9gorie A :<\/strong> avec Romain Noble.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 2h : Escrime fauteuil &#8211; Sabre individuel hommes cat\u00e9gorie B :<\/strong> avec Maxime Valet.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 2h : Para tennis de table &#8211; Individuel hommes classe 3 :<\/strong> avec Florian Merrien.<\/p>\n<p style=\"text-align: justify;\"><strong>2h06 : Para natation &#8211; S\u00e9ries 400m nage libre hommes S9 :<\/strong> avec Ugo Didier.<\/p>\n<div id=\"attachment_160687\" style=\"width: 809px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-160687\" class=\"wp-image-160687 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Ugo-Didier.jpg\" alt=\"Ugo Didier\" width=\"799\" height=\"533\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Ugo-Didier.jpg 799w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Ugo-Didier-300x200.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Ugo-Didier-768x512.jpg 768w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><p id=\"caption-attachment-160687\" class=\"wp-caption-text\">Ugo Didier &#8211; Photo F\u00e9d\u00e9ration Fran\u00e7aise Handisport<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>2h21 : Para natation &#8211; S\u00e9ries 400m nage libre femmes S9 :<\/strong> avec Claire Supiot.<\/p>\n<p style=\"text-align: justify;\"><strong>3h33 : Para natation &#8211; S\u00e9ries 50m nage libre femmes S10 :<\/strong> avec Emeline Pierre.<\/p>\n<p style=\"text-align: justify;\"><strong>3h39 : Para natation &#8211; S\u00e9ries 100m papillon hommes S13 :<\/strong> avec Alex Portal.<\/p>\n<p style=\"text-align: justify;\"><strong>4h17 : Para cyclisme &#8211; Qualifications Poursuite individuelle femmes 3000m C5 :<\/strong> avec Marie Patouillet.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 4h40 : Para tennis de table &#8211; Individuel hommes classe 2 :<\/strong> avec Fabien Lamirault.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 4h40 : Para tennis de table &#8211; Individuel hommes classe 2 :<\/strong> avec St\u00e9phane Molliens.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 4h40 : Para tennis de table &#8211; Individuel hommes classe 8 :<\/strong> avec Cl\u00e9ment Berthier.<\/p>\n<p style=\"text-align: justify;\"><strong>4h52 : Para cyclisme &#8211; Qualifications Poursuite individuelle hommes 4000m B :<\/strong> avec Alexandre Lloveras (guide : Corentin Ermenault).<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 5h20 : Para tennis de table &#8211; Individuel femmes classe 8 :<\/strong> avec Thu Kamkasomphou.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 6h40 : Para tennis de table &#8211; Individuel femmes classe 11 :<\/strong> avec L\u00e9a Ferney.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 9h00 : Para tennis de table &#8211; Individuel hommes classe 10 :<\/strong> avec Mat\u00e9o Boh\u00e9as.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 9h40 : Para tennis de table &#8211; Individuel hommes classe 4 :<\/strong> avec Maxime Thomas.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 11h00 : Para tennis de table &#8211; Individuel hommes classe 11 :<\/strong> avec Lucas Cr\u00e9ange.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 12h20 : Para tennis de table &#8211; Individuel hommes classe 3 :<\/strong> avec Florian Merrien.<\/p>\n<p><strong>12h32 : Para natation &#8211; FINALE 100m papillon hommes S13 :<\/strong> avec Alex Portal.<\/p>\n<p style=\"text-align: justify;\"><strong>13h00 : Rugby fauteuil &#8211; Phase de poules &#8211; Groupe A :<\/strong> Japon &#8211; France<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 partir de 13h40 : Para tennis de table &#8211; Individuel femmes classe 8 :<\/strong> avec Thu Kamkasomphou.<\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-l-actualite-des-jeux-paralympiques-de-tokyo-2020\/\"><b>Toute l&rsquo;actualit\u00e9 des Jeux Paralympiques de Tokyo<\/b><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>JEUX PARALYMPIQUES DE TOKYO 2020 &#8211; Chaque jour, retrouvez tous les athl\u00e8tes tricolores en lice aux Jeux Paralympiques. Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt.<\/p>\n","protected":false},"author":4,"featured_media":160686,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[14180],"tags":[],"class_list":["post-160618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeux-paralympiques-tokyo-2020"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt<\/title>\n<meta name=\"description\" content=\"JEUX PARALYMPIQUES DE TOKYO 2020 - Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt aux Jeux Paralympiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt\" \/>\n<meta property=\"og:description\" content=\"JEUX PARALYMPIQUES DE TOKYO 2020 - Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt aux Jeux Paralympiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-24T16:20:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-25T08:41:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt\",\"datePublished\":\"2021-08-24T16:20:38+00:00\",\"dateModified\":\"2021-08-25T08:41:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/\"},\"wordCount\":376,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png\",\"articleSection\":[\"Jeux Paralympiques de Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/\",\"name\":\"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png\",\"datePublished\":\"2021-08-24T16:20:38+00:00\",\"dateModified\":\"2021-08-25T08:41:51+00:00\",\"description\":\"JEUX PARALYMPIQUES DE TOKYO 2020 - Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt aux Jeux Paralympiques.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png\",\"width\":800,\"height\":445,\"caption\":\"Jeux Paralympiques de Tokyo 2020 le programme des Fran\u00e7ais pour le 25 ao\u00fbt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt","description":"JEUX PARALYMPIQUES DE TOKYO 2020 - Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt aux Jeux Paralympiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/","og_locale":"fr_FR","og_type":"article","og_title":"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt","og_description":"JEUX PARALYMPIQUES DE TOKYO 2020 - Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt aux Jeux Paralympiques.","og_url":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-08-24T16:20:38+00:00","article_modified_time":"2021-08-25T08:41:51+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt","datePublished":"2021-08-24T16:20:38+00:00","dateModified":"2021-08-25T08:41:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/"},"wordCount":376,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png","articleSection":["Jeux Paralympiques de Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/","url":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/","name":"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png","datePublished":"2021-08-24T16:20:38+00:00","dateModified":"2021-08-25T08:41:51+00:00","description":"JEUX PARALYMPIQUES DE TOKYO 2020 - Voici le programme des Fran\u00e7ais pour le mercredi 25 ao\u00fbt aux Jeux Paralympiques.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Jeux-Paralympiques-de-Tokyo-2020-le-programme-des-Francais-pour-le-25-aout.png","width":800,"height":445,"caption":"Jeux Paralympiques de Tokyo 2020 le programme des Fran\u00e7ais pour le 25 ao\u00fbt"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-tokyo-2020-programme-francais-25-aout\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Jeux Paralympiques de Tokyo 2020 : le programme des Fran\u00e7ais pour le 25 ao\u00fbt"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/160618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=160618"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/160618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/160686"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=160618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=160618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=160618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}