{"id":16079,"date":"2018-04-10T11:03:17","date_gmt":"2018-04-10T09:03:17","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=16079"},"modified":"2020-06-15T13:58:54","modified_gmt":"2020-06-15T11:58:54","slug":"mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/","title":{"rendered":"Mathilde Becerra : \u00ab\u00a0Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C&rsquo;est mon objectif\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d&rsquo;escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques.\u00a0<\/strong><\/em><\/p>\n<h5 style=\"text-align: justify;\">Mathilde, peux-tu te pr\u00e9senter en quelques mots ?<\/h5>\n<p style=\"text-align: justify;\">Je m\u2019appelle Mathilde, j\u2019ai 26 ans et je suis originaire de Toulouse. J\u2019ai un dipl\u00f4me d\u2019ing\u00e9nieure mais je me consacre actuellement exclusivement \u00e0 ma carri\u00e8re dans l\u2019escalade.<\/p>\n<h5 style=\"text-align: justify;\">A quel \u00e2ge et comment as-tu commenc\u00e9 l\u2019escalade ?<\/h5>\n<p style=\"text-align: justify;\">J\u2019ai commenc\u00e9 \u00e0 grimper \u00e0 l\u2019\u00e2ge de 13 ans. Une amie m\u2019a initi\u00e9e \u00e0 ce sport un peu par hasard et \u00e7a a \u00e9t\u00e9 le coup de foudre. Mes parents n\u2019arrivaient plus \u00e0 me faire descendre du mur. Je ne pensais qu\u2019\u00e0 \u00e7a et j\u2019attendais chaque entra\u00eenement avec impatience. M\u00eame pas un an apr\u00e8s avoir commenc\u00e9 l\u2019escalade, je me suis tourn\u00e9e vers la comp\u00e9tition. \u00c7a a \u00e9t\u00e9 un peu chaotique au d\u00e9part mais je n\u2019ai pas baiss\u00e9 les bras. J\u2019ai r\u00e9ussi \u00e0 int\u00e9grer l\u2019\u00e9quipe de France \u00e0 l\u2019\u00e2ge de 16 ans, ce qui a lanc\u00e9 ma carri\u00e8re dans le haut niveau.<\/p>\n<h5 style=\"text-align: justify;\">Quelle est la plus grande \u00e9motion sportive que tu as eue jusqu&rsquo;\u00e0 aujourd\u2019hui ?<\/h5>\n<p style=\"text-align: justify;\">J\u2019ai eu deux grandes \u00e9motions \u00e0 ce jour :<\/p>\n<p style=\"text-align: justify;\">La premi\u00e8re en 2016, lorsque j\u2019ai remport\u00e9 mon titre de championne de France dans mon sud-ouest natal. C\u2019\u00e9tait une r\u00e9elle surprise car j\u2019allais sur cette comp\u00e9tition dans l\u2019optique de r\u00e9gler les derniers d\u00e9tails avant les \u00e9ch\u00e9ances internationales, sans accorder d\u2019importance au classement. Cette victoire \u00e9tait d\u2019autant plus belle que j\u2019ai \u00e9t\u00e9 la seule \u00e0 atteindre le sommet de la voie (le parcours trac\u00e9 sur le mur), devant ma famille et mes proches.<\/p>\n<p style=\"text-align: justify;\">La deuxi\u00e8me grande \u00e9motion fut en 2015 lorsque j\u2019ai r\u00e9ussi \u00e0 acc\u00e9der aux phases finales d\u2019une Coupe du monde (top 8). La concurrence \u00e0 l\u2019international est redoutable et il faut se battre bec et ongles pour avoir sa place. J\u2019en r\u00eavais depuis si longtemps. J\u2019ai donc pu grimper en finale aux c\u00f4t\u00e9s des meilleures mondiales devant le public fran\u00e7ais qui m\u2019a pouss\u00e9 jusqu\u2019au bout dans une ambiance \u00e9lectrique. J\u2019ai m\u00eame d\u00e9croch\u00e9 une 4\u00e8me place, ma meilleure place internationale \u00e0 ce jour !<\/p>\n<h5 style=\"text-align: justify;\">Quelles sont les\u00a0trois qualit\u00e9s indispensables pour \u00eatre performant en escalade ?<\/h5>\n<p style=\"text-align: justify;\">L\u2019escalade, c\u2019est beaucoup de qualit\u00e9s physiques mais aussi mentales. Je dirais qu\u2019il faut avoir un excellent rapport poids\/puissance, une gestuelle aiguis\u00e9e (pr\u00e9cision, technique et fluidit\u00e9 des mouvements) ainsi qu\u2019un mental d\u2019acier.<\/p>\n<div id=\"attachment_16081\" style=\"width: 670px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-16081\" class=\"wp-image-16081 size-large\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becera-2-1024x683.jpg\" alt=\"Mathilde Becera 2\" width=\"660\" height=\"440\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becera-2-1024x683.jpg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becera-2-300x200.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becera-2-768x512.jpg 768w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><p id=\"caption-attachment-16081\" class=\"wp-caption-text\">\u00a9 Samuel Chall\u00e9at<\/p><\/div>\n<h5 style=\"text-align: justify;\">Comment se d\u00e9compose une semaine d\u2019entra\u00eenement type pour toi ?<\/h5>\n<p style=\"text-align: justify;\">Les semaines ne sont jamais les m\u00eames mais en g\u00e9n\u00e9ral, je m\u2019entra\u00eene 5 \u00e0 6 jours par semaine avec 3 \u00e0 4 s\u00e9ances par jour (muscu, escalade, cardio\u2026). J\u2019ai environ 60% d\u2019escalade pour 40% de pr\u00e9paration physique. Il faut compter entre 15 et 20h par semaine.<\/p>\n<h5 style=\"text-align: justify;\">Quels sont tes prochains objectifs \u00e0 court terme ?<\/h5>\n<p style=\"text-align: justify;\">Pour cette saison, j\u2019esp\u00e8re de nouveau remporter les Championnats de France, ainsi qu\u2019\u00eatre dans le top 5 du classement mondial.<\/p>\n<h5 style=\"text-align: justify;\">L\u2019escalade sera au JO de 2020. On peut imaginer qu\u2019\u00e0 moyen terme c\u2019est ton v\u00e9ritable objectif ?<\/h5>\n<p style=\"text-align: justify;\">Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C\u2019est clairement un objectif pour moi, cela dit le format choisi par le comit\u00e9 olympique rend la t\u00e2che difficile. Il s\u2019agit d\u2019un combin\u00e9 des trois disciplines de l\u2019escalade (la difficult\u00e9, le bloc et la vitesse). A l\u2019heure actuelle, quasiment tous les grimpeurs sont sp\u00e9cialis\u00e9s dans une discipline. Pour esp\u00e9rer aller aux JO, il faut donc compl\u00e8tement changer sa fa\u00e7on de s\u2019entra\u00eener et inclure les autre disciplines, ce qui en soi est tr\u00e8s int\u00e9ressant. Mais c\u2019est un peu comme demander \u00e0 un sprinteur de faire du marathon ! Du coup personnellement, je continue \u00e0 me consacrer pleinement \u00e0 ma discipline (la difficult\u00e9), tout en commen\u00e7ant \u00e0 faire des comp\u00e9titions dans les deux autres.<\/p>\n<h5 style=\"text-align: justify;\">Paris 2024, les JO en France, est-ce d\u00e9j\u00e0 dans un coin de ta t\u00eate ?<\/h5>\n<p style=\"text-align: justify;\">Oui \u00e7a l\u2019est ! M\u00eame si d\u2019ici l\u00e0 j\u2019aurais peut \u00eatre arr\u00eat\u00e9 la comp\u00e9tition. Si le format change et que chaque discipline individuelle\u00a0a sa place, j\u2019y songerai s\u00e9rieusement. Sinon, j\u2019aimerais \u00eatre impliqu\u00e9e dans les Jeux \u00e0 un autre niveau, pourquoi pas en tant qu\u2019entra\u00eeneur national.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Nicolas Jacquemard<br \/>\n<\/strong><\/em><a style=\"color: #000000;\" href=\"https:\/\/twitter.com\/Nico_Jacquemard\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"color: #000000;\" href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d&rsquo;escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques. <\/p>\n","protected":false},"author":1,"featured_media":16082,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[10930,4,2316],"tags":[477,1506,1004,2665],"class_list":["post-16079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escalade","category-portraits","category-tous-les-sports","tag-escalade","tag-jeux-olympiques-2024","tag-paris-2024","tag-portrait"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mathilde Becerra : &quot;Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C&#039;est mon objectif&quot;<\/title>\n<meta name=\"description\" content=\"Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d&#039;escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mathilde Becerra : &quot;Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C&#039;est mon objectif&quot;\" \/>\n<meta property=\"og:description\" content=\"Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d&#039;escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-10T09:03:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-15T11:58:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becerra.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Mathilde Becerra : \u00ab\u00a0Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C&rsquo;est mon objectif\u00a0\u00bb\",\"datePublished\":\"2018-04-10T09:03:17+00:00\",\"dateModified\":\"2020-06-15T11:58:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/\"},\"wordCount\":778,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mathilde-Becerra.png\",\"keywords\":[\"Escalade\",\"Jeux olympiques 2024\",\"Paris 2024\",\"portrait\"],\"articleSection\":[\"Escalade\",\"Portraits\",\"Sports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/\",\"name\":\"Mathilde Becerra : \\\"Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C'est mon objectif\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mathilde-Becerra.png\",\"datePublished\":\"2018-04-10T09:03:17+00:00\",\"dateModified\":\"2020-06-15T11:58:54+00:00\",\"description\":\"Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d'escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mathilde-Becerra.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mathilde-Becerra.png\",\"width\":1200,\"height\":670,\"caption\":\"Mathilde Becerra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mathilde Becerra : \u00ab\u00a0Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C&rsquo;est mon objectif\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mathilde Becerra : \"Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C'est mon objectif\"","description":"Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d'escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/","og_locale":"fr_FR","og_type":"article","og_title":"Mathilde Becerra : \"Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C'est mon objectif\"","og_description":"Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d'escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques.","og_url":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2018-04-10T09:03:17+00:00","article_modified_time":"2020-06-15T11:58:54+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becerra.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Mathilde Becerra : \u00ab\u00a0Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C&rsquo;est mon objectif\u00a0\u00bb","datePublished":"2018-04-10T09:03:17+00:00","dateModified":"2020-06-15T11:58:54+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/"},"wordCount":778,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becerra.png","keywords":["Escalade","Jeux olympiques 2024","Paris 2024","portrait"],"articleSection":["Escalade","Portraits","Sports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/","url":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/","name":"Mathilde Becerra : \"Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C'est mon objectif\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becerra.png","datePublished":"2018-04-10T09:03:17+00:00","dateModified":"2020-06-15T11:58:54+00:00","description":"Nous avons rencontr\u00e9 Mathilde Becerra, championne de France d'escalade, qui nous parle du d\u00e9but de sa saison ou encore des Jeux Olympiques.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becerra.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/04\/Mathilde-Becerra.png","width":1200,"height":670,"caption":"Mathilde Becerra"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mathilde-becerra-quel-athlete-ne-reve-pas-aller-aux-jo-est-mon-objectif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mathilde Becerra : \u00ab\u00a0Quel athl\u00e8te ne r\u00eave pas d\u2019aller aux JO ? C&rsquo;est mon objectif\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/16079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=16079"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/16079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/16082"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=16079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=16079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=16079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}