{"id":161989,"date":"2021-08-28T08:00:28","date_gmt":"2021-08-28T06:00:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=161989"},"modified":"2021-09-06T12:33:13","modified_gmt":"2021-09-06T10:33:13","slug":"28-aout-2004-premier-titre-olympique-pour-julien-absalon","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/","title":{"rendered":"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/vtt\/\">VTT<\/a> &#8211; Malgr\u00e9 le gain du classement g\u00e9n\u00e9ral de la Coupe du monde, Julien Absalon est loin d\u2019\u00eatre favori pour une m\u00e9daille d\u2019or sur le circuit d\u2019Ath\u00e8nes. Mais les Jeux nous r\u00e9servent parfois de bonnes surprises. Lui vise au moins le podium, il termine sur la plus haute marche.<\/strong><\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 28 ao\u00fbt 2004<\/h2>\n<p style=\"text-align: justify;\">Tout s\u2019est pass\u00e9 assez vite dans cette course olympique de cross-country. Assez t\u00f4t, <strong>Julien Absalon<\/strong> d\u00e9cide d\u2019acc\u00e9l\u00e9rer laissant le champion d\u2019Europe en titre, <strong>Jos\u00e9 Antonio Hermida<\/strong>, quelques kilom\u00e8tres derri\u00e8re. Le tout est de tenir les trois tours restants, mais le cycliste tricolore est sur son nuage, motiv\u00e9 par un suppl\u00e9ment d\u2019\u00e2me, son p\u00e8re \u00e9tant d\u00e9c\u00e9d\u00e9 deux ans auparavant. Alors <strong>Julien Absalon<\/strong> roule, et d\u00e9roule m\u00eame jusqu\u2019\u00e0 la ligne d\u2019arriv\u00e9e. Juste le temps de r\u00e9cup\u00e9rer un drapeau bleu, blanc, rouge dans la derni\u00e8re ligne droite, et le voil\u00e0 champion olympique. A tout juste 24 ans, il s\u2019impose en solitaire avec une minute d\u2019avance sur l\u2019Espagnol et annonce son entr\u00e9e dans la cour des grands.<\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: Deux titres olympiques, cinq de champion du monde mais \u00e9galement cinq sacres continentaux, voil\u00e0 une partie du palmar\u00e8s de <strong>Julien Absalon<\/strong>. Une partie seulement \u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 28 ao\u00fbt 2004, Julien Absalon remportait son premier titre olympique sur le circuit des Jeux d&rsquo;Ath\u00e8nes. Retour sur ce sacre.<\/p>\n","protected":false},"author":18,"featured_media":161994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8,10279],"tags":[8481,161,692],"class_list":["post-161989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-vtt","tag-histoire","tag-jeux-olympiques","tag-vtt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon<\/title>\n<meta name=\"description\" content=\"Le 28 ao\u00fbt 2004, Julien Absalon remportait son premier titre olympique sur le circuit des Jeux d&#039;Ath\u00e8nes. Retour sur ce sacre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon\" \/>\n<meta property=\"og:description\" content=\"Le 28 ao\u00fbt 2004, Julien Absalon remportait son premier titre olympique sur le circuit des Jeux d&#039;Ath\u00e8nes. Retour sur ce sacre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-28T06:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-06T10:33:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon\",\"datePublished\":\"2021-08-28T06:00:28+00:00\",\"dateModified\":\"2021-09-06T10:33:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png\",\"keywords\":[\"histoire\",\"Jeux Olympiques\",\"VTT\"],\"articleSection\":[\"Histoire\",\"VTT\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/\",\"name\":\"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png\",\"datePublished\":\"2021-08-28T06:00:28+00:00\",\"dateModified\":\"2021-09-06T10:33:13+00:00\",\"description\":\"Le 28 ao\u00fbt 2004, Julien Absalon remportait son premier titre olympique sur le circuit des Jeux d'Ath\u00e8nes. Retour sur ce sacre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png\",\"width\":800,\"height\":445,\"caption\":\"28 ao\u00fbt 2004 Premier titre olympique pour Julien Absalon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon","description":"Le 28 ao\u00fbt 2004, Julien Absalon remportait son premier titre olympique sur le circuit des Jeux d'Ath\u00e8nes. Retour sur ce sacre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/","og_locale":"fr_FR","og_type":"article","og_title":"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon","og_description":"Le 28 ao\u00fbt 2004, Julien Absalon remportait son premier titre olympique sur le circuit des Jeux d'Ath\u00e8nes. Retour sur ce sacre.","og_url":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-08-28T06:00:28+00:00","article_modified_time":"2021-09-06T10:33:13+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon","datePublished":"2021-08-28T06:00:28+00:00","dateModified":"2021-09-06T10:33:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png","keywords":["histoire","Jeux Olympiques","VTT"],"articleSection":["Histoire","VTT"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/","url":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/","name":"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png","datePublished":"2021-08-28T06:00:28+00:00","dateModified":"2021-09-06T10:33:13+00:00","description":"Le 28 ao\u00fbt 2004, Julien Absalon remportait son premier titre olympique sur le circuit des Jeux d'Ath\u00e8nes. Retour sur ce sacre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/28-aout-2004-Premier-titre-olympique-pour-Julien-Absalon.png","width":800,"height":445,"caption":"28 ao\u00fbt 2004 Premier titre olympique pour Julien Absalon"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/28-aout-2004-premier-titre-olympique-pour-julien-absalon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"28 ao\u00fbt 2004 : Premier titre olympique pour Julien Absalon"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/161989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=161989"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/161989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/161994"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=161989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=161989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=161989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}