{"id":163087,"date":"2021-09-03T08:00:09","date_gmt":"2021-09-03T06:00:09","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=163087"},"modified":"2021-09-06T12:33:12","modified_gmt":"2021-09-06T10:33:12","slug":"3-septembre-1838-la-grande-ascension-d-henriette-dangeville","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/","title":{"rendered":"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/alpinisme\/\">ALPINISME<\/a> &#8211; Environ 30 ans avant ce 3 septembre 1838, il y a bien une femme qui est parvenue au sommet du Mont-Blanc. Mais Marie Paradis le dit elle-m\u00eame, ses guides ont d\u00fb la \u00ab tirer, tra\u00eener, porter \u00bb pour y arriver. Henriette d\u2019Angeville, elle, a parfaitement pr\u00e9par\u00e9 son ascension.<\/strong> <\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 3 septembre 1838<\/h2>\n<p style=\"text-align: justify;\">Il est 4h du matin, lorsque <strong>Henriette d\u2019Angeville<\/strong> prend le d\u00e9part pour grimper au sommet du Mont-Blanc. La temp\u00e9rature est fra\u00eeche, 6\u00b0, mais l\u2019alpiniste est bien \u00e9quip\u00e9e. Avec notamment un pantalon flanelle, trois chemises, quatre paires de bas, elle a de quoi avancer chaudement. Pour se sustenter ainsi que les multiples guides, porteurs et le muletier qui l\u2019accompagnent, elle a \u00e9galement tout pr\u00e9vu. Comptez une vingtaine de poulets r\u00f4tis, presque autant de bouteilles de vin, deux gigots de mouton et on en passe. Pas question d\u2019oublier quelque chose. Une pause au refuge des Grands Mulets et c\u2019est reparti. Mais plus le sommet est proche, plus il faut puiser dans les ressources, combattre la fatigue. A bout de souffle, <strong>Henriette d\u2019Angeville<\/strong> pose finalement\u00a0 le pied au sommet du Mont-Blanc, devenant \u00e0 jamais sa \u00ab fianc\u00e9e \u00bb.<\/p>\n<div id=\"attachment_163088\" style=\"width: 880px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-163088\" class=\"wp-image-163088 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Henriette-dAngeville.jpg\" alt=\"\" width=\"870\" height=\"489\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Henriette-dAngeville.jpg 870w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Henriette-dAngeville-300x169.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/08\/Henriette-dAngeville-768x432.jpg 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><p id=\"caption-attachment-163088\" class=\"wp-caption-text\">Photo DR<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: Lors de la r\u00e9ception donn\u00e9e par <strong>Henriette d\u2019Angeville<\/strong> pour marquer l\u2019exploit, <strong>Marie Paradis<\/strong> la reconna\u00eet comme \u00e9tant vraiment la premi\u00e8re femme \u00e0 avoir grimper au sommet du Mont-Blanc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retour sur la grande ascension vers le sommet du Mont-Blanc de l&rsquo;alpiniste franco-suisse Henriette d&rsquo;Angeville le 3 septembre 1838.<\/p>\n","protected":false},"author":18,"featured_media":163701,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[8481],"class_list":["post-163087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","tag-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville<\/title>\n<meta name=\"description\" content=\"Retour sur la grande ascension vers le sommet du Mont-Blanc de l&#039;alpiniste franco-suisse Henriette d&#039;Angeville le 3 septembre 1838.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville\" \/>\n<meta property=\"og:description\" content=\"Retour sur la grande ascension vers le sommet du Mont-Blanc de l&#039;alpiniste franco-suisse Henriette d&#039;Angeville le 3 septembre 1838.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-03T06:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-06T10:33:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville\",\"datePublished\":\"2021-09-03T06:00:09+00:00\",\"dateModified\":\"2021-09-06T10:33:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/\"},\"wordCount\":250,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png\",\"keywords\":[\"histoire\"],\"articleSection\":[\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/\",\"name\":\"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png\",\"datePublished\":\"2021-09-03T06:00:09+00:00\",\"dateModified\":\"2021-09-06T10:33:12+00:00\",\"description\":\"Retour sur la grande ascension vers le sommet du Mont-Blanc de l'alpiniste franco-suisse Henriette d'Angeville le 3 septembre 1838.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png\",\"width\":800,\"height\":445,\"caption\":\"3 septembre 1838 La grande ascension d\u2019Henriette d\u2019Angeville\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville","description":"Retour sur la grande ascension vers le sommet du Mont-Blanc de l'alpiniste franco-suisse Henriette d'Angeville le 3 septembre 1838.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/","og_locale":"fr_FR","og_type":"article","og_title":"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville","og_description":"Retour sur la grande ascension vers le sommet du Mont-Blanc de l'alpiniste franco-suisse Henriette d'Angeville le 3 septembre 1838.","og_url":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-09-03T06:00:09+00:00","article_modified_time":"2021-09-06T10:33:12+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville","datePublished":"2021-09-03T06:00:09+00:00","dateModified":"2021-09-06T10:33:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/"},"wordCount":250,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png","keywords":["histoire"],"articleSection":["Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/","url":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/","name":"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png","datePublished":"2021-09-03T06:00:09+00:00","dateModified":"2021-09-06T10:33:12+00:00","description":"Retour sur la grande ascension vers le sommet du Mont-Blanc de l'alpiniste franco-suisse Henriette d'Angeville le 3 septembre 1838.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/3-septembre-1838-La-grande-ascension-dHenriette-dAngeville.png","width":800,"height":445,"caption":"3 septembre 1838 La grande ascension d\u2019Henriette d\u2019Angeville"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/3-septembre-1838-la-grande-ascension-d-henriette-dangeville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"3 septembre 1838 : La grande ascension d\u2019Henriette d\u2019Angeville"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/163087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=163087"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/163087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/163701"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=163087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=163087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=163087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}