{"id":165558,"date":"2021-09-10T21:52:20","date_gmt":"2021-09-10T19:52:20","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=165558&#038;preview=true&#038;preview_id=165558"},"modified":"2021-09-10T21:52:08","modified_gmt":"2021-09-10T19:52:08","slug":"pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/","title":{"rendered":"Pronostic RB Leipzig &#8211; Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>BUNDESLIGA &#8211; Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.<\/b><br \/>\n<\/em><\/p>\n<h2 style=\"text-align: justify;\">Pronostic RB Leipzig &#8211; Bayern Munich : Samedi 11 septembre, 18h30<\/h2>\n<p style=\"text-align: justify;\">D\u00e9but de saison moyen de <strong>Leipzig<\/strong> qui a largement domin\u00e9 Stuttgart \u00e0 la maison mais qui a perdu ses deux premiers d\u00e9placements. Le <strong>Bayern<\/strong> a \u00e9t\u00e9 accroch\u00e9 par Gladbach lors de la premi\u00e8re journ\u00e9e avant de gagner deux fois, non sans mal face \u00e0 Cologne. Les Bavarois sont invaincus face \u00e0 Leipzig depuis sept rencontres donc on part sur <strong>une victoire du Bayern ou un nul avec plus de 1,5 buts dans le match<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 600px;\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 11 septembre, 18h30<\/span><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; text-align: center; width: 200px;\"><span style=\"font-size: 12px; color: #ffffff;\">N2 et + de 1,5 buts<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; width: 600px;\"><strong>RB Leipzig &#8211; Bayern Munich<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 200px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/27883142?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#ffffff;background-color:#C80A00;border-color:#a00800;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#ffffff;padding:0px 16px;font-size:13px;line-height:26px;border-color:#d9544d;border-radius:5px;text-shadow:none\"> 1.50<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BUNDESLIGA &#8211; Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.<\/p>\n","protected":false},"author":1,"featured_media":165563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[4484,7173,75,9327,4949],"class_list":["post-165558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-bayern-munich","tag-bundesliga","tag-football","tag-leipzig","tag-pronostics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga - Dicodusport<\/title>\n<meta name=\"description\" content=\"BUNDESLIGA - Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga\" \/>\n<meta property=\"og:description\" content=\"BUNDESLIGA - Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-10T19:52:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Pronostic RB Leipzig &#8211; Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga\",\"datePublished\":\"2021-09-10T19:52:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/\"},\"wordCount\":164,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png\",\"keywords\":[\"Bayern Munich\",\"Bundesliga\",\"Football\",\"Leipzig\",\"Pronostics\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/\",\"name\":\"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png\",\"datePublished\":\"2021-09-10T19:52:20+00:00\",\"description\":\"BUNDESLIGA - Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png\",\"width\":1200,\"height\":670,\"caption\":\"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronostic RB Leipzig &#8211; Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga - Dicodusport","description":"BUNDESLIGA - Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/","og_locale":"fr_FR","og_type":"article","og_title":"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga","og_description":"BUNDESLIGA - Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.","og_url":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-09-10T19:52:20+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Pronostic RB Leipzig &#8211; Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga","datePublished":"2021-09-10T19:52:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/"},"wordCount":164,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png","keywords":["Bayern Munich","Bundesliga","Football","Leipzig","Pronostics"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/","url":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/","name":"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png","datePublished":"2021-09-10T19:52:20+00:00","description":"BUNDESLIGA - Le RB Leipzig re\u00e7oit Bayern Munich dans le cadre de la 4\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Pronostic-RB-Leipzig-Bayern-Munich-4eme-journee-de-Bundesliga.png","width":1200,"height":670,"caption":"Pronostic RB Leipzig - Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-bayern-munich-4eme-journee-de-bundesliga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pronostic RB Leipzig &#8211; Bayern Munich, 4\u00e8me journ\u00e9e de Bundesliga"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/165558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=165558"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/165558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/165563"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=165558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=165558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=165558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}