{"id":166270,"date":"2021-09-13T18:02:13","date_gmt":"2021-09-13T16:02:13","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=166270&#038;preview=true&#038;preview_id=166270"},"modified":"2021-09-13T20:56:58","modified_gmt":"2021-09-13T18:56:58","slug":"tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/","title":{"rendered":"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s"},"content":{"rendered":"<p align=\"JUSTIFY\"><em><strong>Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As est l&rsquo;un des \u00e9v\u00e9nements les plus importants du tennis dans la cat\u00e9gorie d&rsquo;\u00e2ge des 12-14 ans. Cette comp\u00e9tition a r\u00e9v\u00e9l\u00e9 de grands noms par le pass\u00e9, et cette ann\u00e9e, c&rsquo;est une Fran\u00e7aise qui s&rsquo;est impos\u00e9e. Focus sur Mathilde Ngijol Carr\u00e9, laur\u00e9ate chez les filles, et sur l&rsquo;espoir que suscite une telle performance dans ce tournoi.<\/strong><\/em><\/p>\n<p align=\"JUSTIFY\"><strong>Les Petits As<\/strong>. Tous les ans, ce tournoi r\u00e9unit la cr\u00e8me de la (tr\u00e8s) jeune g\u00e9n\u00e9ration, les futur(e)s joueurs et joueuses qui arpenteront le circuit professionnel par la suite. Cet \u00e9v\u00e9nement est scrut\u00e9 de pr\u00e8s par de nombreux observateurs, soucieux de d\u00e9nicher la prochaine star du tennis. Il est vrai que figurent au palmar\u00e8s des noms ronflants comme Rafael Nadal, Juan Carlos Ferrero, Michael Chang, Richard Krajicek, Martina Hingis, Jelena Ostapenko o\u00f9 Bianca Andreescu, tous laur\u00e9ats de Grand Chelem.<\/p>\n<h2 style=\"text-align: justify;\" align=\"JUSTIFY\">Un Fran\u00e7ais ou une Fran\u00e7aise qui gagne, pas si souvent que cela<\/h2>\n<p align=\"JUSTIFY\">Bien entendu, certains vainqueurs de ce tournoi n&rsquo;ont pas eu par la suite la carri\u00e8re qu&rsquo;on leur promettait, quelques-uns devenant des flops monumentaux. N\u00e9anmoins, la victoire dans le tournoi f\u00e9minin de <strong>Mathilde Ngijol Carr\u00e9<\/strong> est une performance retentissante, \u00e0 la fois une bonne et une mauvaise nouvelle pour la formation fran\u00e7aise.<\/p>\n<p align=\"JUSTIFY\">Cela faisait 37 ans que la France n&rsquo;avait pas triomph\u00e9 dans le tournoi f\u00e9minin. La Parisienne<strong> Mathilde Ngijol Carr\u00e9<\/strong> a r\u00e9ussi cet exploit ce week-end en battant l&rsquo;Isra\u00e9lienne <strong>Mika Buchnik<\/strong> 4-6, 6-2, 6-1, devant un public tout acquis \u00e0 sa cause. La Fran\u00e7aise aura 14 ans en octobre, et cette victoire suscite d\u00e9j\u00e0 une forte attente dans un tennis f\u00e9minin fran\u00e7ais plut\u00f4t sinistr\u00e9 depuis les retraites d&rsquo;Am\u00e9lie Mauresmo, Mary Pierce et Marion Bartoli, les derni\u00e8res tricolores laur\u00e9ates de Grand Chelem.<\/p>\n<h2 style=\"text-align: justify;\" align=\"JUSTIFY\">Une joueuse prometteuse, mais un exil n\u00e9cessaire<\/h2>\n<p align=\"JUSTIFY\">Sportivement, les attentes sont justifiables. La joueuse mesure 1.85 m, frappe fort, est dot\u00e9e d&rsquo;un grand service et d&rsquo;un jeu spectaculaire. Son style de jeu conviendrait parfaitement au tennis actuel, on pourrait ainsi la comparer \u00e0 une Karolina Pliskova ou \u00e0 une Petra Kvitova. Pendant tout son tournoi, elle a fait preuve de sang-froid, m\u00eame quand elle \u00e9tait men\u00e9e au score, et sa finale n&rsquo;a pas d\u00e9rog\u00e9 \u00e0 la r\u00e8gle, puisqu&rsquo;apr\u00e8s un gros coup de mou dans le deuxi\u00e8me set, la Fran\u00e7aise a repris sa marche en avant pour surclasser son adversaire dans la derni\u00e8re manche.<\/p>\n<blockquote class=\"twitter-tweet\"><p>The Frenchie claimed a historical win yesterday at <a href=\"https:\/\/twitter.com\/hashtag\/LesPetitsAs?src=hash&amp;ref_src=twsrc%5Etfw\">#LesPetitsAs<\/a><br \/>\n\u2070Would you like to relive the story in video? <a href=\"https:\/\/t.co\/Ozfo2zFc5V\">pic.twitter.com\/Ozfo2zFc5V<\/a><\/p>\n<p>\u2014 Les Petits As &#8211; Le Mondial Lacoste (@LesPetitsAs) <a href=\"https:\/\/twitter.com\/LesPetitsAs\/status\/1437343379113775105?ref_src=twsrc%5Etfw\">September 13, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p align=\"JUSTIFY\">N\u00e9anmoins, la jeune espoir, d\u00e9j\u00e0 championne de France de la cat\u00e9gorie des 11\/12 ans, a choisi de s&rsquo;exiler en Espagne pour parfaire sa formation. Elle fr\u00e9quente assidument les courts de l&rsquo;acad\u00e9mie de tennis de Barcelone, dirig\u00e9e par un membre du staff de <strong>Rafael Nadal<\/strong>. Sans doute un moyen d&rsquo;\u00e9chapper \u00e0 la pression pr\u00e9sente dans l&rsquo;Hexagone d\u00e8s qu&rsquo;un espoir r\u00e9ussit une performance marquante. Le meilleur exemple \u00e9tant bien entendu <strong>Richard Gasquet<\/strong>, en couverture de Tennis Magazine \u00e0 l&rsquo;\u00e2ge de 9 ans, laur\u00e9at des <strong>Petits As<\/strong> \u00e0 13 ans, qui m\u00eame s&rsquo;il a r\u00e9ussi \u00e0 faire une longue et belle carri\u00e8re, n&rsquo;a jamais atteint le niveau qu&rsquo;on lui promettait. Lui-m\u00eame a admis que cette pression avait \u00e9t\u00e9 n\u00e9gative pour sa carri\u00e8re.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">La r\u00e9cente victoire d&rsquo;<strong>Emma Raducanu<\/strong> lors de l&rsquo;US Open prouve que le talent se d\u00e9tecte tr\u00e8s t\u00f4t. <strong>Mathilde Ngijol Carr\u00e9<\/strong> est encore jeune, elle a d\u00e9j\u00e0 particip\u00e9 \u00e0 Roland-Garros juniors cette ann\u00e9e, mais elle devra franchir beaucoup d&rsquo;obstacles sur et en dehors du court pour esp\u00e9rer pr\u00e9tendre \u00e0 un destin de championne, dans un tennis f\u00e9minin en perp\u00e9tuel renouvellement.<\/p>\n<p align=\"JUSTIFY\">\n","protected":false},"excerpt":{"rendered":"<p>Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As est l&rsquo;un des \u00e9v\u00e9nements les plus importants du tennis dans la cat\u00e9gorie d&rsquo;\u00e2ge des 12-14 ans. Cette comp\u00e9tition a r\u00e9v\u00e9l\u00e9 de grands noms par le pass\u00e9, et cette ann\u00e9e, c&rsquo;est une Fran\u00e7aise qui s&rsquo;est impos\u00e9e. Focus sur Mathilde Ngijol Carr\u00e9, laur\u00e9ate chez les filles, et sur l&rsquo;espoir que suscite une telle performance dans ce tournoi.<\/p>\n","protected":false},"author":59,"featured_media":166280,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2302],"tags":[136,4792],"class_list":["post-166270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-tennis","tag-tennis-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s<\/title>\n<meta name=\"description\" content=\"Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As a sacr\u00e9 la Fran\u00e7aise Mathilde Ngijol Carr\u00e9, une premi\u00e8re pour le tennis tricolore depuis 37 ans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As a sacr\u00e9 la Fran\u00e7aise Mathilde Ngijol Carr\u00e9, une premi\u00e8re pour le tennis tricolore depuis 37 ans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-13T16:02:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-13T18:56:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s\",\"datePublished\":\"2021-09-13T16:02:13+00:00\",\"dateModified\":\"2021-09-13T18:56:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/\"},\"wordCount\":689,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png\",\"keywords\":[\"Tennis\",\"Tennis fran\u00e7ais\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/\",\"name\":\"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png\",\"datePublished\":\"2021-09-13T16:02:13+00:00\",\"dateModified\":\"2021-09-13T18:56:58+00:00\",\"description\":\"Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As a sacr\u00e9 la Fran\u00e7aise Mathilde Ngijol Carr\u00e9, une premi\u00e8re pour le tennis tricolore depuis 37 ans.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png\",\"width\":800,\"height\":445,\"caption\":\"Petits As 2021 Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s","description":"Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As a sacr\u00e9 la Fran\u00e7aise Mathilde Ngijol Carr\u00e9, une premi\u00e8re pour le tennis tricolore depuis 37 ans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/","og_locale":"fr_FR","og_type":"article","og_title":"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s","og_description":"Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As a sacr\u00e9 la Fran\u00e7aise Mathilde Ngijol Carr\u00e9, une premi\u00e8re pour le tennis tricolore depuis 37 ans.","og_url":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2021-09-13T16:02:13+00:00","article_modified_time":"2021-09-13T18:56:58+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s","datePublished":"2021-09-13T16:02:13+00:00","dateModified":"2021-09-13T18:56:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/"},"wordCount":689,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png","keywords":["Tennis","Tennis fran\u00e7ais"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/","url":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/","name":"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png","datePublished":"2021-09-13T16:02:13+00:00","dateModified":"2021-09-13T18:56:58+00:00","description":"Disput\u00e9 \u00e0 Tarbes, le tournoi des Petits As a sacr\u00e9 la Fran\u00e7aise Mathilde Ngijol Carr\u00e9, une premi\u00e8re pour le tennis tricolore depuis 37 ans.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Petits-As-2021-Mathilde-Ngijol-Carre-37-ans-apres.png","width":800,"height":445,"caption":"Petits As 2021 Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tennis-petits-as-2021-mathilde-ngijol-carre-37-ans-apres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Petits As 2021 : Mathilde Ngijol Carr\u00e9, 37 ans apr\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/166270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=166270"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/166270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/166280"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=166270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=166270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=166270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}