{"id":167298,"date":"2021-09-18T08:05:22","date_gmt":"2021-09-18T06:05:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=167298"},"modified":"2021-09-18T13:45:33","modified_gmt":"2021-09-18T11:45:33","slug":"18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/","title":{"rendered":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques"},"content":{"rendered":"<p><em><strong>Il y a cinq ans, les athl\u00e8tes paralympiques d\u00e9filaient dans le stade Maracana de Rio de Janeiro pour la c\u00e9r\u00e9monie de cl\u00f4ture des Jeux. Retour sur celle-ci et les r\u00e9sultats, tricolores notamment, de la comp\u00e9tition.<\/strong><\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 18 septembre 2016<\/h2>\n<p>La veille de ce 18 septembre, <strong>Bahman Golbarnezhad<\/strong> perdait la vie suite \u00e0 une chute lors de la comp\u00e9tition. La c\u00e9r\u00e9monie de cl\u00f4ture devient alors un moment de recueillement et d\u2019hommage rendu au cycliste iranien. Avant cet instant d\u2019\u00e9motion, les feux d\u2019artifice ont illumin\u00e9 le ciel br\u00e9silien puis les musiciens et chanteurs ont fait danser les spectateurs. Pour ouvrir le bal des artistes, <strong>Johnatha Bastos<\/strong> offrait un solo de guitare au stade de Maracana.<\/p>\n<p>Du c\u00f4t\u00e9 des r\u00e9sultats sportifs, la Chine a domin\u00e9 les Jeux avec plus de 230 m\u00e9dailles dont quasiment la moiti\u00e9 en or. Devanc\u00e9e par la Grande-Bretagne en seconde place, c\u2019est l\u2019Ukraine qui monte sur la troisi\u00e8me marche du podium d\u2019un titre suppl\u00e9mentaire seulement face aux Etats-Unis. Pour les Fran\u00e7ais, le bilan est plus mitig\u00e9. Les Bleus ram\u00e8nent 28 breloques du Br\u00e9sil dont 9 en or. Le pongiste <strong>Fabien Lamirault<\/strong> r\u00e9alise le doubl\u00e9 en individuel et par \u00e9quipe, tout comme l\u2019athl\u00e8te <strong>Marie-Am\u00e9lie Le Fur<\/strong>, en longueur et sur 400 m.<br \/>\nNouvelle \u00e9motion lors de la c\u00e9r\u00e9monie entre le passage de t\u00e9moin avec Tokyo et l\u2019extinction de la flamme olympique. Cependant \u00e0 cet instant, nous ne savions pas encore qu\u2019il faudrait attendre cinq ans pour voir cette derni\u00e8re s\u2019embraser de nouveau.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: A Tokyo, <a href=\"https:\/\/dicodusport.fr\/blog\/jeux-paralympiques-de-tokyo-le-bilan-de-la-delegation-francaise-en-chiffres\/\">l\u2019\u00e9quipe de France a pulv\u00e9ris\u00e9 son objectif de m\u00e9dailles<\/a> (35) en allant en chercher 54 dont 11 du plus beau des m\u00e9taux. De bon augure pour les Jeux de Paris dans trois ans\u2026<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.0pt; line-height: 107%;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 18 septembre 2016, les Jeux Paralympiques de Rio s&rsquo;achevaient avec une c\u00e9r\u00e9monie de cl\u00f4ture riche en \u00e9motions. Retour sur celle-ci.<\/p>\n","protected":false},"author":18,"featured_media":167308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[5753,8],"tags":[8481,1964],"class_list":["post-167298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handisport","category-histoire","tag-histoire","tag-jeux-paralympiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques<\/title>\n<meta name=\"description\" content=\"Le 18 septembre 2016, les Jeux Paralympiques de Rio s&#039;achevaient avec une c\u00e9r\u00e9monie de cl\u00f4ture riche en \u00e9motions. Retour sur celle-ci.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques\" \/>\n<meta property=\"og:description\" content=\"Le 18 septembre 2016, les Jeux Paralympiques de Rio s&#039;achevaient avec une c\u00e9r\u00e9monie de cl\u00f4ture riche en \u00e9motions. Retour sur celle-ci.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-18T06:05:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-18T11:45:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques\",\"datePublished\":\"2021-09-18T06:05:22+00:00\",\"dateModified\":\"2021-09-18T11:45:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png\",\"keywords\":[\"histoire\",\"jeux paralympiques\"],\"articleSection\":[\"Handisport\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/\",\"name\":\"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png\",\"datePublished\":\"2021-09-18T06:05:22+00:00\",\"dateModified\":\"2021-09-18T11:45:33+00:00\",\"description\":\"Le 18 septembre 2016, les Jeux Paralympiques de Rio s'achevaient avec une c\u00e9r\u00e9monie de cl\u00f4ture riche en \u00e9motions. Retour sur celle-ci.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png\",\"width\":800,\"height\":445,\"caption\":\"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques","description":"Le 18 septembre 2016, les Jeux Paralympiques de Rio s'achevaient avec une c\u00e9r\u00e9monie de cl\u00f4ture riche en \u00e9motions. Retour sur celle-ci.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/","og_locale":"fr_FR","og_type":"article","og_title":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques","og_description":"Le 18 septembre 2016, les Jeux Paralympiques de Rio s'achevaient avec une c\u00e9r\u00e9monie de cl\u00f4ture riche en \u00e9motions. Retour sur celle-ci.","og_url":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-09-18T06:05:22+00:00","article_modified_time":"2021-09-18T11:45:33+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques","datePublished":"2021-09-18T06:05:22+00:00","dateModified":"2021-09-18T11:45:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png","keywords":["histoire","jeux paralympiques"],"articleSection":["Handisport","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/","url":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/","name":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png","datePublished":"2021-09-18T06:05:22+00:00","dateModified":"2021-09-18T11:45:33+00:00","description":"Le 18 septembre 2016, les Jeux Paralympiques de Rio s'achevaient avec une c\u00e9r\u00e9monie de cl\u00f4ture riche en \u00e9motions. Retour sur celle-ci.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/18-septembre-2016-Ceremonie-de-cloture-des-Jeux-Paralympiques.png","width":800,"height":445,"caption":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/18-septembre-2016-ceremonie-de-cloture-des-jeux-paralympiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"18 septembre 2016 : C\u00e9r\u00e9monie de cl\u00f4ture des Jeux Paralympiques"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/167298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=167298"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/167298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/167308"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=167298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=167298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=167298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}