{"id":168154,"date":"2021-09-21T08:00:00","date_gmt":"2021-09-21T06:00:00","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=168154"},"modified":"2021-09-21T08:11:28","modified_gmt":"2021-09-21T06:11:28","slug":"21-septembre-1948-marcel-cerdan-devient-champion-du-monde","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/","title":{"rendered":"21 septembre 1948 : Marcel Cerdan devient champion du monde"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/boxe\/\">BOXE<\/a> &#8211; En ce soir de septembre 1948, c\u2019est le combat tant attendu entre Marcel Cerdan et Tony Zale, alias le Bombardier marocain et le Roi du K.O. Et ce duel se d\u00e9roule \u00e0 la perfection pour le Fran\u00e7ais.<\/strong> <\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 21 septembre 1948<\/h2>\n<p style=\"text-align: justify;\">Enfin, le jour J est arriv\u00e9. En France, les adeptes attendaient tellement la rencontre entre <strong>Marcel Cerdan<\/strong> et <strong>Tony Zale<\/strong> que les ventes de radios ont explos\u00e9. Pire encore, la consommation d\u2019\u00e9lectricit\u00e9 d\u00e9passe tout entendement. En un soir, les Fran\u00e7ais en mangent l\u2019\u00e9quivalent de trois semaines, insolent ! Mais cela n\u2019a pas \u00e9t\u00e9 en vain.<\/p>\n<p style=\"text-align: justify;\">Dans un Roosevelt Stadium acquis \u00e0 la cause de l\u2019Am\u00e9ricain, c\u2019est bien <strong>Marcel Cerdan<\/strong> qui encha\u00eene les bons coups. Et \u00e0 trop subir, <strong>Tony Zale<\/strong> vacille. Le Roi du K.O perd ainsi sa ceinture des poids moyens \u2026 par K.O technique \u00e0 la 11<sup>\u00e8me<\/sup> reprise. Sur la totalit\u00e9 de celles-ci, une seule est \u00e0 mettre au cr\u00e9dit du champion en titre qui le c\u00e8de ainsi \u00e0 l\u2019homme d\u2019<strong>Edith Piaf<\/strong>. Ce dernier arrive alors en France en h\u00e9ros. Malheureusement, <strong>Marcel Cerdan<\/strong> ne conserve pas ce sacre tr\u00e8s longtemps, il s\u2019incline en juin 1949 avant d\u2019\u00eatre victime d\u2019un accident d\u2019avion en octobre la m\u00eame ann\u00e9e, \u00e0 33 ans.<\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: Ambassadeur de la boxe \u00e9galement, <a href=\"https:\/\/dicodusport.fr\/blog\/jean-paul-belmondo-une-vie-sur-le-ring\/\">le regrett\u00e9 <strong>Jean-Paul Belmondo<\/strong><\/a> a d\u00e9couvert la discipline en 1943 mais c\u2019est en 1948, au lendemain du titre de <strong>Marcel Cerdan<\/strong>, qu\u2019il s\u2019en fait une v\u00e9ritable passion.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 21 septembre 1948, Marcel Cerdan devenait champion du monde des poids moyens contre Tony Zale au Roosevelt Stadium. Retour sur ce jour.<\/p>\n","protected":false},"author":18,"featured_media":168157,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8672,8],"tags":[622,8481],"class_list":["post-168154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","category-histoire","tag-boxe","tag-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>21 septembre 1948 : Marcel Cerdan devient champion du monde<\/title>\n<meta name=\"description\" content=\"Le 21 septembre 1948, Marcel Cerdan devenait champion du monde des poids moyens contre Tony Zale au Roosevelt Stadium. Retour sur ce jour.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"21 septembre 1948 : Marcel Cerdan devient champion du monde\" \/>\n<meta property=\"og:description\" content=\"Le 21 septembre 1948, Marcel Cerdan devenait champion du monde des poids moyens contre Tony Zale au Roosevelt Stadium. Retour sur ce jour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-21T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-21T06:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"21 septembre 1948 : Marcel Cerdan devient champion du monde\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"21 septembre 1948 : Marcel Cerdan devient champion du monde\",\"datePublished\":\"2021-09-21T06:00:00+00:00\",\"dateModified\":\"2021-09-21T06:11:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/\"},\"wordCount\":264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png\",\"keywords\":[\"boxe\",\"histoire\"],\"articleSection\":[\"Boxe\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/\",\"name\":\"21 septembre 1948 : Marcel Cerdan devient champion du monde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png\",\"datePublished\":\"2021-09-21T06:00:00+00:00\",\"dateModified\":\"2021-09-21T06:11:28+00:00\",\"description\":\"Le 21 septembre 1948, Marcel Cerdan devenait champion du monde des poids moyens contre Tony Zale au Roosevelt Stadium. Retour sur ce jour.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png\",\"width\":800,\"height\":445,\"caption\":\"21 septembre 1948 Marcel Cerdan devient champion du monde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"21 septembre 1948 : Marcel Cerdan devient champion du monde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"21 septembre 1948 : Marcel Cerdan devient champion du monde","description":"Le 21 septembre 1948, Marcel Cerdan devenait champion du monde des poids moyens contre Tony Zale au Roosevelt Stadium. Retour sur ce jour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"21 septembre 1948 : Marcel Cerdan devient champion du monde","og_description":"Le 21 septembre 1948, Marcel Cerdan devenait champion du monde des poids moyens contre Tony Zale au Roosevelt Stadium. Retour sur ce jour.","og_url":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-09-21T06:00:00+00:00","article_modified_time":"2021-09-21T06:11:28+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"21 septembre 1948 : Marcel Cerdan devient champion du monde","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"21 septembre 1948 : Marcel Cerdan devient champion du monde","datePublished":"2021-09-21T06:00:00+00:00","dateModified":"2021-09-21T06:11:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/"},"wordCount":264,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png","keywords":["boxe","histoire"],"articleSection":["Boxe","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/","url":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/","name":"21 septembre 1948 : Marcel Cerdan devient champion du monde","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png","datePublished":"2021-09-21T06:00:00+00:00","dateModified":"2021-09-21T06:11:28+00:00","description":"Le 21 septembre 1948, Marcel Cerdan devenait champion du monde des poids moyens contre Tony Zale au Roosevelt Stadium. Retour sur ce jour.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/21-septembre-1948-Marcel-Cerdan-devient-champion-du-monde.png","width":800,"height":445,"caption":"21 septembre 1948 Marcel Cerdan devient champion du monde"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/21-septembre-1948-marcel-cerdan-devient-champion-du-monde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"21 septembre 1948 : Marcel Cerdan devient champion du monde"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/168154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=168154"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/168154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/168157"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=168154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=168154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=168154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}