{"id":168450,"date":"2021-09-22T15:32:40","date_gmt":"2021-09-22T13:32:40","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=168450&#038;preview=true&#038;preview_id=168450"},"modified":"2021-09-22T16:03:41","modified_gmt":"2021-09-22T14:03:41","slug":"lincroyable-conference-de-presse-de-ronald-koeman","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/","title":{"rendered":"L&rsquo;incroyable conf\u00e9rence de presse de Ronald Koeman"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>LIGA &#8211; En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s&rsquo;est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">L&rsquo;entra\u00eeneur n\u00e9erlandais a lu un texte qu&rsquo;il avait donc pr\u00e9par\u00e9 puis s&rsquo;est retir\u00e9 sans attendre les questions des journalistes. Le club a \u00e9t\u00e9 pr\u00e9venu seulement quelques minutes avant le d\u00e9but, des intentions de son coach. Dans son communiqu\u00e9, <strong>Ronald Koeman<\/strong> a notamment expliqu\u00e9 :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Le club est \u00e0 mes c\u00f4t\u00e9s dans une situation de reconstruction. La situation \u00e9conomique est li\u00e9e \u00e0 la situation sportive. Nous, en tant qu&rsquo;\u00e9quipe, nous devons la reconstruire sans faire de grands investissements, et cela demande du temps. Les talents peuvent devenir des stars mondiales en une ou deux ann\u00e9es. Les jeunes auront des opportunit\u00e9s, comme en avaient eu Xavi ou Iniesta, mais on demande de la patience. Rester \u00e0 un classement \u00e9lev\u00e9 en Liga serait un succ\u00e8s. En Ligue des champions, on ne peut pas attendre de miracles. La d\u00e9faite face au Bayern Munich (0-3 en C1) doit \u00eatre vue sous cet angle.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">En plus d&rsquo;avoir un effectif affaibli, le Bar\u00e7a a de nombreux bless\u00e9s comme Sergio Aguero ou Ansu Fati. Les noms de <strong>Roberto Martinez<\/strong> ou <strong>Xavi<\/strong> sont \u00e9voqu\u00e9s en cas de licenciement de Ronald Koeman.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">&#x1f5e3; <a href=\"https:\/\/twitter.com\/RonaldKoeman?ref_src=twsrc%5Etfw\">@RonaldKoeman<\/a>: \u00ab\u00a0Contamos con vuestro apoyo en estos tiempos dif\u00edciles\u00a0\u00bb <a href=\"https:\/\/t.co\/l6lP9C9eCp\">pic.twitter.com\/l6lP9C9eCp<\/a><\/p>\n<p>\u2014 FC Barcelona (@FCBarcelona_es) <a href=\"https:\/\/twitter.com\/FCBarcelona_es\/status\/1440634729263288323?ref_src=twsrc%5Etfw\">September 22, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGA &#8211; En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s&rsquo;est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.<\/p>\n","protected":false},"author":1,"featured_media":168454,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[912,2101,75],"class_list":["post-168450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-barca","tag-barcelone","tag-football"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;incroyable conf\u00e9rence de presse de Ronald Koeman<\/title>\n<meta name=\"description\" content=\"En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s&#039;est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;incroyable conf\u00e9rence de presse de Ronald Koeman\" \/>\n<meta property=\"og:description\" content=\"En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s&#039;est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T13:32:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-22T14:03:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L&#039;incroyable conf\u00e9rence de presse de Ronald Koeman\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"L&rsquo;incroyable conf\u00e9rence de presse de Ronald Koeman\",\"datePublished\":\"2021-09-22T13:32:40+00:00\",\"dateModified\":\"2021-09-22T14:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/\"},\"wordCount\":267,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png\",\"keywords\":[\"bar\u00e7a\",\"barcelone\",\"Football\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/\",\"name\":\"L'incroyable conf\u00e9rence de presse de Ronald Koeman\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png\",\"datePublished\":\"2021-09-22T13:32:40+00:00\",\"dateModified\":\"2021-09-22T14:03:41+00:00\",\"description\":\"En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s'est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;incroyable conf\u00e9rence de presse de Ronald Koeman\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'incroyable conf\u00e9rence de presse de Ronald Koeman","description":"En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s'est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/","og_locale":"fr_FR","og_type":"article","og_title":"L'incroyable conf\u00e9rence de presse de Ronald Koeman","og_description":"En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s'est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-09-22T13:32:40+00:00","article_modified_time":"2021-09-22T14:03:41+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"L'incroyable conf\u00e9rence de presse de Ronald Koeman","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"L&rsquo;incroyable conf\u00e9rence de presse de Ronald Koeman","datePublished":"2021-09-22T13:32:40+00:00","dateModified":"2021-09-22T14:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/"},"wordCount":267,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png","keywords":["bar\u00e7a","barcelone","Football"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/","url":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/","name":"L'incroyable conf\u00e9rence de presse de Ronald Koeman","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png","datePublished":"2021-09-22T13:32:40+00:00","dateModified":"2021-09-22T14:03:41+00:00","description":"En difficult\u00e9 depuis le d\u00e9but de la saison avec le Bar\u00e7a, Ronald Koeman s'est pr\u00e9sent\u00e9 seulement deux minutes en conf\u00e9rence de presse \u00e0 la veille du match face \u00e0 Cadiz.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Lincroyable-confe\u0301rence-de-presse-de-Ronald-Koeman.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/lincroyable-conference-de-presse-de-ronald-koeman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;incroyable conf\u00e9rence de presse de Ronald Koeman"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/168450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=168450"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/168450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/168454"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=168450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=168450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=168450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}