{"id":169433,"date":"2021-09-27T08:00:19","date_gmt":"2021-09-27T06:00:19","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=169433"},"modified":"2021-09-27T11:30:58","modified_gmt":"2021-09-27T09:30:58","slug":"27-septembre-1988-ben-johnson-champion-olympique-dechu","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/","title":{"rendered":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/athletisme\/\">ATHLETISME<\/a> &#8211; Avec le <a href=\"https:\/\/dicodusport.fr\/blog\/flandres-2021-julian-alaphilippe-conserve-son-titre-de-champion-du-monde\/\">nouveau sacre mondial de Julian Alaphilippe<\/a> hier, nul doute que vous avez d\u00e9j\u00e0 pas mal entendu parler du cycliste tricolore. Inutile de revenir alors sur <a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-championnats-du-monde-2020-course-en-ligne-hommes-julian-alaphilippe-sacre\/\">son titre de l\u2019ann\u00e9e derni\u00e8re<\/a>, parlons d\u2019autre chose. Malheureusement, l\u2019affaire du jour est moins glorieuse, retour sur le scandale Ben Johnson \u00e0 S\u00e9oul.<\/strong><\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 27 septembre 1988<\/h2>\n<p style=\"text-align: justify;\">Le 24 septembre 1988, <strong>Ben Johnson<\/strong> entre dans l\u2019histoire en d\u00e9crochant le titre olympique sur 100 m. Loin devant <strong>Carl Lewis<\/strong>, vainqueur quatre ans auparavant et grand favori, l\u2019athl\u00e8te canadien l\u00e8ve le doigt vers le ciel avant de franchir la ligne d\u2019arriv\u00e9e. En 9 secondes 79, <strong>Ben Johnson<\/strong> am\u00e9liore \u00e9galement le record du monde. L\u2019histoire est sur le moment assez belle. Un fils d\u2019une famille pauvre d\u00e9couvert \u00e0 16 ans et qui gravit petit \u00e0 petit les \u00e9chelons. Puis un jour, c\u2019est le titre olympique, il est le h\u00e9ros de tout un peuple. Mais voil\u00e0, depuis quelques ann\u00e9es d\u00e9j\u00e0, certains sont perplexes quant aux performances et l\u2019\u00e9volution physique du champion du monde 1987, son grand rival am\u00e9ricain en t\u00eate.<\/p>\n<p style=\"text-align: justify;\">Le 27 septembre, la nouvelle tombe. Trois jours apr\u00e8s avoir go\u00fbt\u00e9 \u00e0 la plus haute marche du podium, <strong>Ben Johnson<\/strong> est d\u00e9muni de tout. Au revoir le record du monde, <strong>Carl Lewis<\/strong> r\u00e9cup\u00e8re la m\u00e9daille d\u2019or. Contr\u00f4l\u00e9 positif aux st\u00e9ro\u00efdes anabolisants, il ne cessera de crier au complot, en vain. Le fait est, il l\u2019avouera plus tard, qu\u2019il se dopait, pas avec le produit d\u00e9cel\u00e9 mais un autre plus difficile \u00e0 d\u00e9tecter. Pour \u00eatre clair, la lutte contre le dopage d\u00e9butait \u00e0 peine et si les athl\u00e8tes \u00e9taient -presque- tous sous st\u00e9ro\u00efdes, ils ne se faisaient pas prendre, ou ils avaient un meilleur entourage\u2026 Le champion d\u00e9chu est suspendu deux ans, c\u2019est la premi\u00e8re grande histoire de dopage des Jeux Olympiques. En 1993, <strong>Ben Johnson<\/strong> est de nouveau contr\u00f4l\u00e9 positif et est exclu \u00e0 vie des pistes pour r\u00e9cidive.<\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: <strong>Ben Johnson<\/strong> s\u2019est lanc\u00e9 des ann\u00e9es plus tard dans la lutte antidopage notamment avec le programme Pure Sport. Le roi d\u00e9chu est alors retourn\u00e9 dans le stade olympique de S\u00e9oul pour partager son message.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 27 septembre 1988, trois jours apr\u00e8s conquis les Jeux, Ben Johnson se voit retirer son titre olympique et le record du monde du 100 m.<\/p>\n","protected":false},"author":18,"featured_media":169464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2308,8],"tags":[143,8481],"class_list":["post-169433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-histoire","tag-athletisme","tag-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu<\/title>\n<meta name=\"description\" content=\"Le 27 septembre 1988, trois jours apr\u00e8s conquis les Jeux, Ben Johnson se voit retirer son titre olympique et le record du monde du 100 m.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu\" \/>\n<meta property=\"og:description\" content=\"Le 27 septembre 1988, trois jours apr\u00e8s conquis les Jeux, Ben Johnson se voit retirer son titre olympique et le record du monde du 100 m.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-27T06:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-27T09:30:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu\",\"datePublished\":\"2021-09-27T06:00:19+00:00\",\"dateModified\":\"2021-09-27T09:30:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/\"},\"wordCount\":394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png\",\"keywords\":[\"Athl\u00e9tisme\",\"histoire\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/\",\"name\":\"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png\",\"datePublished\":\"2021-09-27T06:00:19+00:00\",\"dateModified\":\"2021-09-27T09:30:58+00:00\",\"description\":\"Le 27 septembre 1988, trois jours apr\u00e8s conquis les Jeux, Ben Johnson se voit retirer son titre olympique et le record du monde du 100 m.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png\",\"width\":800,\"height\":445,\"caption\":\"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/27-septembre-1988-ben-johnson-champion-olympique-dechu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu","description":"Le 27 septembre 1988, trois jours apr\u00e8s conquis les Jeux, Ben Johnson se voit retirer son titre olympique et le record du monde du 100 m.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/","og_locale":"fr_FR","og_type":"article","og_title":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu","og_description":"Le 27 septembre 1988, trois jours apr\u00e8s conquis les Jeux, Ben Johnson se voit retirer son titre olympique et le record du monde du 100 m.","og_url":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-09-27T06:00:19+00:00","article_modified_time":"2021-09-27T09:30:58+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu","datePublished":"2021-09-27T06:00:19+00:00","dateModified":"2021-09-27T09:30:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/"},"wordCount":394,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png","keywords":["Athl\u00e9tisme","histoire"],"articleSection":["Athl\u00e9tisme","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/","url":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/","name":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png","datePublished":"2021-09-27T06:00:19+00:00","dateModified":"2021-09-27T09:30:58+00:00","description":"Le 27 septembre 1988, trois jours apr\u00e8s conquis les Jeux, Ben Johnson se voit retirer son titre olympique et le record du monde du 100 m.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/27-septembre-1988-Ben-Johnson-champion-olympique-dechu.png","width":800,"height":445,"caption":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/27-septembre-1988-ben-johnson-champion-olympique-dechu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"27 septembre 1988 : Ben Johnson, champion olympique d\u00e9chu"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/169433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=169433"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/169433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/169464"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=169433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=169433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=169433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}