{"id":169611,"date":"2021-09-27T21:01:18","date_gmt":"2021-09-27T19:01:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=169611&#038;preview=true&#038;preview_id=169611"},"modified":"2021-09-27T21:15:11","modified_gmt":"2021-09-27T19:15:11","slug":"palmares-nuit-du-rugby-2021","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/","title":{"rendered":"Le palmar\u00e8s de la Nuit du Rugby 2021"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>RUGBY &#8211; Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l&rsquo;Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet en temps r\u00e9el de la c\u00e9r\u00e9monie.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Meilleur joueur du TOP 14 2020-2021<\/h2>\n<p style=\"text-align: justify;\">Antoine Dupont (Stade Toulousain).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-169643\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-du-TOP-14-2020-2021-1024x1024.png\" alt=\"Antoine Dupont - Meilleur joueur du TOP 14 2020-2021\" width=\"740\" height=\"740\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-du-TOP-14-2020-2021-1024x1024.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-du-TOP-14-2020-2021-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-du-TOP-14-2020-2021-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-du-TOP-14-2020-2021-768x768.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-du-TOP-14-2020-2021-80x80.png 80w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-du-TOP-14-2020-2021.png 1200w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<hr \/>\n<h2>Meilleur joueur de PRO D2 2020-2021<\/h2>\n<p style=\"text-align: justify;\">Melvyn Jaminet (USAP).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-169639\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Meilleur-joueur-de-PRO-D2-2020-2021-1024x1024.png\" alt=\"Melvyn Jaminet - Meilleur joueur de PRO D2 2020-2021\" width=\"740\" height=\"740\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Meilleur-joueur-de-PRO-D2-2020-2021-1024x1024.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Meilleur-joueur-de-PRO-D2-2020-2021-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Meilleur-joueur-de-PRO-D2-2020-2021-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Meilleur-joueur-de-PRO-D2-2020-2021-768x768.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Meilleur-joueur-de-PRO-D2-2020-2021-80x80.png 80w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Meilleur-joueur-de-PRO-D2-2020-2021.png 1200w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<hr \/>\n<h2>R\u00e9v\u00e9lation de la saison 2020-2021<\/h2>\n<p style=\"text-align: justify;\">Melvyn Jaminet (USAP).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-169619 size-large\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Revelation-de-la-saison-2020-2021-1024x1024.png\" alt=\"Melvyn Jaminet - R\u00e9v\u00e9lation de la saison 2020-2021\" width=\"740\" height=\"740\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Revelation-de-la-saison-2020-2021-1024x1024.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Revelation-de-la-saison-2020-2021-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Revelation-de-la-saison-2020-2021-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Revelation-de-la-saison-2020-2021-768x768.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Revelation-de-la-saison-2020-2021-80x80.png 80w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Melvyn-Jaminet-Revelation-de-la-saison-2020-2021.png 1200w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<hr \/>\n<h2 style=\"text-align: justify;\">Meilleur joueur international fran\u00e7ais 2020-2021<\/h2>\n<p style=\"text-align: justify;\">Antoine Dupont (Stade Toulousain).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-169635\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-international-francais-2020-2021-1024x1024.png\" alt=\"Antoine Dupont - Meilleur joueur international fran\u00e7ais 2020-2021\" width=\"740\" height=\"740\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-international-francais-2020-2021-1024x1024.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-international-francais-2020-2021-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-international-francais-2020-2021-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-international-francais-2020-2021-768x768.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-international-francais-2020-2021-80x80.png 80w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Antoine-Dupont-Meilleur-joueur-international-francais-2020-2021.png 1200w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<hr \/>\n<h2>Meilleure joueuse \u00c9quipe de France \u00e0 XV 2020-2021<\/h2>\n<p>Marjorie Mayans (Blagnac Rugby F\u00e9minin).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-169621 size-large\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Marjorie-Mayans-Meilleure-joueuse-de-lequipe-de-France-a-XV-2020-2021-1024x1024.png\" alt=\"Marjorie Mayans - Meilleure joueuse de l'\u00e9quipe de France \u00e0 XV 2020-2021\" width=\"740\" height=\"740\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Marjorie-Mayans-Meilleure-joueuse-de-lequipe-de-France-a-XV-2020-2021-1024x1024.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Marjorie-Mayans-Meilleure-joueuse-de-lequipe-de-France-a-XV-2020-2021-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Marjorie-Mayans-Meilleure-joueuse-de-lequipe-de-France-a-XV-2020-2021-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Marjorie-Mayans-Meilleure-joueuse-de-lequipe-de-France-a-XV-2020-2021-768x768.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Marjorie-Mayans-Meilleure-joueuse-de-lequipe-de-France-a-XV-2020-2021-80x80.png 80w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Marjorie-Mayans-Meilleure-joueuse-de-lequipe-de-France-a-XV-2020-2021.png 1200w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<hr \/>\n<h2 style=\"text-align: justify;\">Meilleur arbitre 2020-2021<\/h2>\n<p style=\"text-align: justify;\">Romain Poite (Comit\u00e9 Midi-Pyr\u00e9n\u00e9es).<\/p>\n<hr \/>\n<h2 style=\"text-align: justify;\">Meilleur staff d&rsquo;entra\u00eeneurs TOP 14 2020-2021<\/h2>\n<p><strong>Stade Toulousain :<\/strong> Ugo Mola, Jean Bouilhou, Virgile Lacombe, Cl\u00e9ment Poitrenaud et Laurent Thu\u00e9ry.<\/p>\n<hr \/>\n<h2 style=\"text-align: justify;\">Meilleur staff d&rsquo;entra\u00eeneurs PRO D2 2020-2021<\/h2>\n<p style=\"text-align: justify;\"><strong>USAP :<\/strong> Patrick Arlettaz, Perry Freshwater et G\u00e9rald Bastide.<\/p>\n<hr \/>\n<h2 style=\"text-align: justify;\">Plus bel essai 2020-2021<\/h2>\n<p style=\"text-align: justify;\">Matthis Lebel lors de la 21<sup>\u00e8me<\/sup> journ\u00e9e de TOP 14 (Stade Toulousain).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/NuitDuRugby?src=hash&amp;ref_src=twsrc%5Etfw\">#NuitDuRugby<\/a><br \/>\n&#x1f3c5; PLUS BEL ESSAI&#x1f3c5;<\/p>\n<p>Vous avez \u00e9t\u00e9 tr\u00e8s nombreux \u00e0 voter pour d\u00e9signer le plus bel essai de la saison !<br \/>\nOn vous laisse d\u00e9couvrir cette merveille sign\u00e9e Matthis Lebel avec le <a href=\"https:\/\/twitter.com\/StadeToulousain?ref_src=twsrc%5Etfw\">@StadeToulousain<\/a> &#x1f525;<\/p>\n<p>En association avec <a href=\"https:\/\/twitter.com\/LandRover?ref_src=twsrc%5Etfw\">@LandRover<\/a> <a href=\"https:\/\/t.co\/VhWym3kXhR\">pic.twitter.com\/VhWym3kXhR<\/a><\/p>\n<p>\u2014 TOP 14 Rugby (@top14rugby) <a href=\"https:\/\/twitter.com\/top14rugby\/status\/1442558854999547905?ref_src=twsrc%5Etfw\">September 27, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<hr \/>\n<h2>Meilleure joueuse \u00e9quipe de France \u00e0 VII<\/h2>\n<p style=\"text-align: justify;\">S\u00e9raphine Okemba.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-169648\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Seraphine-Okemba-Meilleure-joueuse-de-lequipe-de-France-a-7-1024x1024.png\" alt=\"S\u00e9raphine Okemba - Meilleure joueuse de l'\u00e9quipe de France \u00e0 7\" width=\"740\" height=\"740\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Seraphine-Okemba-Meilleure-joueuse-de-lequipe-de-France-a-7-1024x1024.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Seraphine-Okemba-Meilleure-joueuse-de-lequipe-de-France-a-7-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Seraphine-Okemba-Meilleure-joueuse-de-lequipe-de-France-a-7-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Seraphine-Okemba-Meilleure-joueuse-de-lequipe-de-France-a-7-768x768.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Seraphine-Okemba-Meilleure-joueuse-de-lequipe-de-France-a-7-80x80.png 80w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/Seraphine-Okemba-Meilleure-joueuse-de-lequipe-de-France-a-7.png 1200w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY &#8211; Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l&rsquo;Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet de la c\u00e9r\u00e9monie.<\/p>\n","protected":false},"author":4,"featured_media":144580,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2303],"tags":[13,111],"class_list":["post-169611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby","tag-rugby","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le palmar\u00e8s de la Nuit du Rugby 2021<\/title>\n<meta name=\"description\" content=\"RUGBY - Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l&#039;Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet de la c\u00e9r\u00e9monie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le palmar\u00e8s de la Nuit du Rugby 2021\" \/>\n<meta property=\"og:description\" content=\"RUGBY - Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l&#039;Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet de la c\u00e9r\u00e9monie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-27T19:01:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-27T19:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le palmar\u00e8s de la Nuit du Rugby 2021\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Le palmar\u00e8s de la Nuit du Rugby 2021\",\"datePublished\":\"2021-09-27T19:01:18+00:00\",\"dateModified\":\"2021-09-27T19:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png\",\"keywords\":[\"Rugby\",\"Top 14\"],\"articleSection\":[\"Rugby\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/\",\"name\":\"Le palmar\u00e8s de la Nuit du Rugby 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png\",\"datePublished\":\"2021-09-27T19:01:18+00:00\",\"dateModified\":\"2021-09-27T19:15:11+00:00\",\"description\":\"RUGBY - Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l'Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet de la c\u00e9r\u00e9monie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png\",\"width\":800,\"height\":445,\"caption\":\"Melvyn Jaminet - Photo Icon Sport\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/palmares-nuit-du-rugby-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le palmar\u00e8s de la Nuit du Rugby 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le palmar\u00e8s de la Nuit du Rugby 2021","description":"RUGBY - Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l'Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet de la c\u00e9r\u00e9monie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Le palmar\u00e8s de la Nuit du Rugby 2021","og_description":"RUGBY - Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l'Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet de la c\u00e9r\u00e9monie.","og_url":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-09-27T19:01:18+00:00","article_modified_time":"2021-09-27T19:15:11+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Le palmar\u00e8s de la Nuit du Rugby 2021","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Le palmar\u00e8s de la Nuit du Rugby 2021","datePublished":"2021-09-27T19:01:18+00:00","dateModified":"2021-09-27T19:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png","keywords":["Rugby","Top 14"],"articleSection":["Rugby"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/","url":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/","name":"Le palmar\u00e8s de la Nuit du Rugby 2021","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png","datePublished":"2021-09-27T19:01:18+00:00","dateModified":"2021-09-27T19:15:11+00:00","description":"RUGBY - Ce lundi, la Nuit du Rugby 2021 a eu lieu \u00e0 l'Olympia, \u00e0 Paris. Retrouvez le palmar\u00e8s complet de la c\u00e9r\u00e9monie.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/XV-de-France-5-joueurs-a-suivre-pour-la-tournee-en-Australie.png","width":800,"height":445,"caption":"Melvyn Jaminet - Photo Icon Sport"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/palmares-nuit-du-rugby-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le palmar\u00e8s de la Nuit du Rugby 2021"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/169611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=169611"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/169611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/144580"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=169611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=169611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=169611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}