{"id":170805,"date":"2021-10-04T08:40:23","date_gmt":"2021-10-04T06:40:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=170805&#038;preview=true&#038;preview_id=170805"},"modified":"2021-10-04T08:40:23","modified_gmt":"2021-10-04T06:40:23","slug":"top-14-immanquable-5eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/","title":{"rendered":"Top 14 : L&rsquo;immanquable de la 5\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOP 14 2021-2022 &#8211; Bouscul\u00e9 \u00e0 Biarritz, le Stade Toulousain reste n\u00e9anmoins invaincu et tr\u00f4ne en haut du classement du Top 14. Bordeaux-B\u00e8gles, Brive et Pau r\u00e9alisent de bonnes op\u00e9rations, alors que La Rochelle et le Stade Fran\u00e7ais restent englu\u00e9s en bas de classement.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Le match de la journ\u00e9e : Lyon OU 15 &#8211; 20 Union Bordeaux-B\u00e8gles<\/h2>\n<p style=\"text-align: justify;\">Entre des Lyonnais proches de l&rsquo;exploit la semaine derni\u00e8re au Racing 92, et des Bordelo-B\u00e9glais invaincus depuis trois matchs, cette affiche entre deux pr\u00e9tendants aux phases finales avait fi\u00e8re allure. Si les Rhodaniens marquent la premi\u00e8re p\u00e9nalit\u00e9, le carton jaune re\u00e7u d\u00e8s la 9\u00e8me minute par <strong>Fainga&rsquo;s<\/strong> va leur co\u00fbter cher, puisqu&rsquo;ils vont encaisser un 10-0 pendant leur inf\u00e9riorit\u00e9 num\u00e9rique, 10 points inscrits par <strong>Matthieu Jalibert<\/strong>, avec notamment un essai de roublard valid\u00e9 apr\u00e8s un interminable arbitrage vid\u00e9o. Devant leur public, les Lyonnais r\u00e9agissent, mettent beaucoup d&rsquo;intensit\u00e9 et provoquent de multiples fautes de leur adversaire, qui r\u00e9colteront 2 cartons jaunes.<\/p>\n<p style=\"text-align: justify;\">Le demi d&rsquo;ouverture<strong> L\u00e9o Berdeu<\/strong> passera de son c\u00f4t\u00e9 cinq p\u00e9nalit\u00e9s au total et permet \u00e0 son \u00e9quipe de reprendre l&rsquo;avantage 15-13. Mais les Girondins ne l\u00e2chent pas, et \u00e0 la 67\u00e8me minute, ils plantent un coup de poignard dans le dos des Lyonnais gr\u00e2ce \u00e0 un essai de l&rsquo;arri\u00e8re <strong>Romain Buros<\/strong>, sur une belle perc\u00e9e de <strong>Dubi\u00e9<\/strong>. Les Lyonnais feront alors le si\u00e8ge de la ligne bordelaise mais resteront muets jusqu&rsquo;\u00e0 la fin du match. Cette victoire est un gros coup pour l&rsquo;UBB, d\u00e9sormais deuxi\u00e8me du Top 14.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">: \u00a0\u00bb \u00a0\u00bb<br \/>\nLe coach Rouge et Noir revient, en conf\u00e9rence de presse, sur la d\u00e9faite \u00e0 domicile face \u00e0 l&rsquo;Union Bordeaux-B\u00e8gles (15-20).<br \/>\nPlus de d\u00e9clarations &#x27a1;&#xfe0f; <a href=\"https:\/\/t.co\/LcWLQezs42\">https:\/\/t.co\/LcWLQezs42<\/a><a href=\"https:\/\/twitter.com\/hashtag\/TeamLOU?src=hash&amp;ref_src=twsrc%5Etfw\">#TeamLOU<\/a> &#x26ab; <a href=\"https:\/\/t.co\/NSpzK0jxFD\">pic.twitter.com\/NSpzK0jxFD<\/a><\/p>\n<p>\u2014 LOU Rugby (@LeLOURugby) <a href=\"https:\/\/twitter.com\/LeLOURugby\/status\/1444336549135626242?ref_src=twsrc%5Etfw\">October 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le club en forme : la Section Paloise<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;objectif de Pau reste le maintien, et cette victoire sur le terrain d&rsquo;un adversaire direct est donc cruciale. R\u00e9duits \u00e0 14 d\u00e8s la 27\u00e8me minute \u00e0 cause d&rsquo;un carton rouge re\u00e7u par leur ailier <strong>Tuimaba<\/strong>, les Palois ont alors survol\u00e9 la rencontre face \u00e0 des Perpignanais compl\u00e9tement inhib\u00e9s par leur sup\u00e9riorit\u00e9 num\u00e9rique. La charni\u00e8re <strong>Clovis Le Bail &#8211; Antoine Hastoy<\/strong> a r\u00e9gn\u00e9 en ma\u00eetre sur le match, avec un essai chacun et une animation offensive impeccable. M\u00eame s&rsquo;ils ont laiss\u00e9 filer le bonus offensif \u00e0 la derni\u00e8re seconde, les Palois d\u00e9crochent un succ\u00e8s bien m\u00e9rit\u00e9, le deuxi\u00e8me d&rsquo;affil\u00e9e en inf\u00e9riorit\u00e9 num\u00e9rique, et se replacent en haut de classement.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Clovis Le Bail : \u00ab M\u00eame \u00e0 14, on garde notre plan. Cette victoire est positive mais on est frustr\u00e9s de perdre le bonus sur cette derni\u00e8re action. On reste tr\u00e8s humbles car on sait qu\u2019il est difficile d\u2019encha\u00eener. \u00bb<a href=\"https:\/\/twitter.com\/hashtag\/USAPSP?src=hash&amp;ref_src=twsrc%5Etfw\">#USAPSP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TOP14?src=hash&amp;ref_src=twsrc%5Etfw\">#TOP14<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/HonhaSection?src=hash&amp;ref_src=twsrc%5Etfw\">#HonhaSection<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/EnVertEtContreTous?src=hash&amp;ref_src=twsrc%5Etfw\">#EnVertEtContreTous<\/a> <a href=\"https:\/\/t.co\/m5U5X3mWMZ\">pic.twitter.com\/m5U5X3mWMZ<\/a><\/p>\n<p>\u2014 SectionPaloise (@SectionPaloise) <a href=\"https:\/\/twitter.com\/SectionPaloise\/status\/1444320855123800066?ref_src=twsrc%5Etfw\">October 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le club qui d\u00e9\u00e7oit : Le Stade Rochelais<\/h2>\n<p style=\"text-align: justify;\">La saison de La Rochelle ne d\u00e9colle toujours pas. \u00c0 Montpellier, les Maritimes se sont inclin\u00e9s pour la quatri\u00e8me fois en cinq rencontres, un d\u00e9but de saison indigne d&rsquo;un finaliste en titre. Les Rochelais \u00e9taient pourtant plein d&rsquo;envie mais ont commis un trop grand nombre de fautes. Le buteur Montpelli\u00e9rain <strong>Paolo Garbisi<\/strong> s&rsquo;en est donn\u00e9 \u00e0 c\u0153ur joie, r\u00e9ussissant un 7\/7 au pied pour inscrire les 21 points de la victoire de son \u00e9quipe. L&rsquo;essai de <strong>Jules Favre<\/strong> arrivera trop tardivement pour permettre \u00e0 La Rochelle de ramener au moins un point de bonus d\u00e9fensif (21-11). Le Stade Rochelais est avant-dernier, mais le calendrier \u00e0 venir est assez favorable, et leur laissera une chance de se relancer.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Dans un match hach\u00e9, le <a href=\"https:\/\/twitter.com\/MHR_officiel?ref_src=twsrc%5Etfw\">@MHR_officiel<\/a> a profit\u00e9 des erreurs adverses pour s&rsquo;imposer face au <a href=\"https:\/\/twitter.com\/staderochelais?ref_src=twsrc%5Etfw\">@staderochelais<\/a> (21-11), pour la 5e journ\u00e9e de <a href=\"https:\/\/twitter.com\/hashtag\/TOP14?src=hash&amp;ref_src=twsrc%5Etfw\">#TOP14<\/a> &#x1f3c9;<\/p>\n<p>L&rsquo;ouvreur Paolo Garbisi a marqu\u00e9 tous les points de son \u00e9quipe &#x1f1ee;&#x1f1f9;<\/p>\n<p>Le r\u00e9sum\u00e9 de la rencontre &#x1f449; <a href=\"https:\/\/t.co\/fwhOpJtaxm\">https:\/\/t.co\/fwhOpJtaxm<\/a><a href=\"https:\/\/twitter.com\/hashtag\/MHRSR?src=hash&amp;ref_src=twsrc%5Etfw\">#MHRSR<\/a> <a href=\"https:\/\/t.co\/UGeIeIlRrq\">pic.twitter.com\/UGeIeIlRrq<\/a><\/p>\n<p>\u2014 We Rugby (@We_Rugby) <a href=\"https:\/\/twitter.com\/We_Rugby\/status\/1444323233768030215?ref_src=twsrc%5Etfw\">October 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le joueur : Wilfrid Hounkpatin (Castres Olympique)<\/h2>\n<p style=\"text-align: justify;\">Le pilier Castrais a effectu\u00e9 ses d\u00e9buts en bleu cet \u00e9t\u00e9 en Australie, apr\u00e8s avoir du d\u00e9clarer forfait lors du Tournoi des 6 Nations 2020. Force est de constater qu&rsquo;il est d\u00e9j\u00e0 dans une forme internationale au regard de son match de samedi contre Toulon. En plus d&rsquo;une assise imp\u00e9riale en m\u00eal\u00e9e, le pilier gauche a inscrit pas moins de deux essais ! Le premier en suivant bien une perc\u00e9e de <strong>Julian Dumora<\/strong>, puis le second en jouant rapidement une p\u00e9nalit\u00e9 proche de la ligne. Ayant parcouru 30 m\u00e8tres ballon en mains, ce qui est \u00e9norme pour un joueur de premi\u00e8re ligne, le Tarnais contribue ainsi \u00e0 l&rsquo;excellent d\u00e9but de saison de son \u00e9quipe, 4\u00e8me du Top 14.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le barom\u00e8tre de Castres &#8211; Toulon : Hounkpatin fait le doubl\u00e9, Nakarawa en rodage <a href=\"https:\/\/t.co\/0W3I7GI0XR\">https:\/\/t.co\/0W3I7GI0XR<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Rugby?src=hash&amp;ref_src=twsrc%5Etfw\">#Rugby<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Top14?src=hash&amp;ref_src=twsrc%5Etfw\">#Top14<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/CastresOlympique?src=hash&amp;ref_src=twsrc%5Etfw\">#CastresOlympique<\/a> <a href=\"https:\/\/twitter.com\/RugbyramaFR?ref_src=twsrc%5Etfw\">@RugbyramaFR<\/a> <a href=\"https:\/\/t.co\/3lkzOXPuqS\">pic.twitter.com\/3lkzOXPuqS<\/a><\/p>\n<p>\u2014 Rugby&rsquo;O&rsquo;Top (@rugbyotop) <a href=\"https:\/\/twitter.com\/rugbyotop\/status\/1444411380216389633?ref_src=twsrc%5Etfw\">October 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">L&rsquo;essai : Aymeric Luc (RC Toulon)<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;ailier toulonnais est l&rsquo;un des seuls joueurs de son \u00e9quipe \u00e0 \u00eatre au niveau cette saison, et il l&rsquo;a prouv\u00e9 lors du d\u00e9placement \u00e0 Castres. Apr\u00e8s avoir r\u00e9cup\u00e9r\u00e9 acrobatiquement un ballon tomb\u00e9 par les Tarnais \u00e0 l&rsquo;approche de ses propres 22 m\u00e8tres, il a crochet\u00e9 l&rsquo;arri\u00e8re <strong>Dumora<\/strong>, acc\u00e9l\u00e9r\u00e9 sur 80 m\u00e8tres, puis magnifiquement d\u00e9pos\u00e9 son vis-\u00e0-vis <strong>Geoffrey Palis<\/strong> pour aller pointer dans l&rsquo;en-but. Un exploit personnel malheureusement <a href=\"https:\/\/dicodusport.fr\/blog\/top-14-castres-enfonce-un-peu-plus-toulon-dans-le-doute\/\">insuffisant pour permettre \u00e0 son \u00e9quipe de repartir avec un r\u00e9sultat de Castres (d\u00e9faite 27-16)<\/a>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Revivez dans les conditions du direct l&rsquo;unique essai mais n\u00e9anmoins magnifique du <a href=\"https:\/\/twitter.com\/RCTofficiel?ref_src=twsrc%5Etfw\">@RCTofficiel<\/a> avec cet exploit personnel d&rsquo;Aymeric Luc <a href=\"https:\/\/twitter.com\/hashtag\/CORCT?src=hash&amp;ref_src=twsrc%5Etfw\">#CORCT<\/a> <a href=\"https:\/\/t.co\/ns1OE3haxi\">pic.twitter.com\/ns1OE3haxi<\/a><\/p>\n<p>\u2014 Canal Rugby Club (@CanalRugbyClub) <a href=\"https:\/\/twitter.com\/CanalRugbyClub\/status\/1444411647842521089?ref_src=twsrc%5Etfw\">October 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">La d\u00e9claration<\/h2>\n<blockquote>\n<p style=\"text-align: justify;\">Mon apport sur les deux essais ? Les connaisseurs verront que c&rsquo;est gr\u00e2ce aux avants.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>Antoine Dupont<\/strong>, toujours empreint d&rsquo;humilit\u00e9 apr\u00e8s son entr\u00e9e d\u00e9cisive contre Biarritz (victoire 17-11).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Antoine Dupont : \u00ab On savait o\u00f9 on mettait les pieds donc le bilan comptable apr\u00e8s cinq journ\u00e9es est positif. Dans l\u2019\u00e9tat d\u2019esprit on \u00e9tait l\u00e0 d\u00e8s le d\u00e9but. Mon apport sur les deux essais ? Les connaisseurs verront que c\u2019est gr\u00e2ce aux avants. \u00bb <a href=\"https:\/\/twitter.com\/hashtag\/BOST?src=hash&amp;ref_src=twsrc%5Etfw\">#BOST<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FBSport?src=hash&amp;ref_src=twsrc%5Etfw\">#FBSport<\/a> <a href=\"https:\/\/t.co\/G3p31DjIWj\">pic.twitter.com\/G3p31DjIWj<\/a><\/p>\n<p>\u2014 France Bleu Occitanie (@bleuoccitanie) <a href=\"https:\/\/twitter.com\/bleuoccitanie\/status\/1444350001707167744?ref_src=twsrc%5Etfw\">October 2, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">La stat<\/h2>\n<p style=\"text-align: justify;\">La Rochelle ne s&rsquo;est jamais impos\u00e9e \u00e0 Montpellier depuis son accession en Top 14 (2010).<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-top-14-2021-2022-5eme-journee-programme-tv-et-resultats\/\"><strong>Les r\u00e9sultats de la 5\u00e8me journ\u00e9e de Top 14<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/top-14-2021-2022-le-classement-complet\/\"><strong>Le classement du Top 14<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2021-2022 &#8211; Retrouvez tout ce qu&rsquo;il faut retenir de la 5\u00e8me journ\u00e9e de Top 14, avec un Toulouse toujours sur le toit du classement.<\/p>\n","protected":false},"author":59,"featured_media":171138,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47050],"tags":[],"class_list":["post-170805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Top 14 : L&#039;immanquable de la 5\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"TOP 14 2021-2022 - Retrouvez tout ce qu&#039;il faut retenir de la 5\u00e8me journ\u00e9e de Top 14, avec un Toulouse toujours sur le toit du classement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 : L&#039;immanquable de la 5\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2021-2022 - Retrouvez tout ce qu&#039;il faut retenir de la 5\u00e8me journ\u00e9e de Top 14, avec un Toulouse toujours sur le toit du classement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-04T06:40:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Top-14-Limmanquable-de-la-5eme-journee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 : L&#039;immanquable de la 5\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Top 14 : L&rsquo;immanquable de la 5\u00e8me journ\u00e9e\",\"datePublished\":\"2021-10-04T06:40:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/\"},\"wordCount\":1152,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Top-14-Limmanquable-de-la-5eme-journee.png\",\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/\",\"name\":\"Top 14 : L'immanquable de la 5\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Top-14-Limmanquable-de-la-5eme-journee.png\",\"datePublished\":\"2021-10-04T06:40:23+00:00\",\"description\":\"TOP 14 2021-2022 - Retrouvez tout ce qu'il faut retenir de la 5\u00e8me journ\u00e9e de Top 14, avec un Toulouse toujours sur le toit du classement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Top-14-Limmanquable-de-la-5eme-journee.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Top-14-Limmanquable-de-la-5eme-journee.png\",\"width\":800,\"height\":445,\"caption\":\"Top 14 L'immanquable de la 5\u00e8me journ\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-5eme-journee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 : L&rsquo;immanquable de la 5\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 : L'immanquable de la 5\u00e8me journ\u00e9e","description":"TOP 14 2021-2022 - Retrouvez tout ce qu'il faut retenir de la 5\u00e8me journ\u00e9e de Top 14, avec un Toulouse toujours sur le toit du classement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 : L'immanquable de la 5\u00e8me journ\u00e9e","og_description":"TOP 14 2021-2022 - Retrouvez tout ce qu'il faut retenir de la 5\u00e8me journ\u00e9e de Top 14, avec un Toulouse toujours sur le toit du classement.","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2021-10-04T06:40:23+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Top-14-Limmanquable-de-la-5eme-journee.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Top 14 : L'immanquable de la 5\u00e8me journ\u00e9e","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Top 14 : L&rsquo;immanquable de la 5\u00e8me journ\u00e9e","datePublished":"2021-10-04T06:40:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/"},"wordCount":1152,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Top-14-Limmanquable-de-la-5eme-journee.png","articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/","name":"Top 14 : L'immanquable de la 5\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Top-14-Limmanquable-de-la-5eme-journee.png","datePublished":"2021-10-04T06:40:23+00:00","description":"TOP 14 2021-2022 - Retrouvez tout ce qu'il faut retenir de la 5\u00e8me journ\u00e9e de Top 14, avec un Toulouse toujours sur le toit du classement.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Top-14-Limmanquable-de-la-5eme-journee.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Top-14-Limmanquable-de-la-5eme-journee.png","width":800,"height":445,"caption":"Top 14 L'immanquable de la 5\u00e8me journ\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-5eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 : L&rsquo;immanquable de la 5\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/170805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=170805"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/170805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/171138"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=170805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=170805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=170805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}